{"id":15835,"date":"2020-01-21T23:14:52","date_gmt":"2020-01-21T23:14:52","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=15835"},"modified":"2023-07-21T15:18:51","modified_gmt":"2023-07-21T20:18:51","slug":"peru-brecha-salarial-la-principal-barrera-para-las-ejecutivas","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/peru-brecha-salarial-la-principal-barrera-para-las-ejecutivas\/","title":{"rendered":"Per\u00fa: Brecha salarial, la principal barrera para las ejecutivas"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li> <strong>Seis de cada diez ejecutivas encuestadas afirman que la maternidad detuvo en alg\u00fan momento su carrera profesional <\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Por Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/AmecoPress. Lima, 21 ene. 20. &#8211; La desigualdad salarial es la principal barrera que identifican las ejecutivas peruanas en sus empresas, revel\u00f3 el estudio Esade Gender Monitor Latinoam\u00e9rica 2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De un total de 226 entrevistadas, el 23,48% consider\u00f3 que hay diferencia de sueldos entre varones y mujeres en sus compa\u00f1\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cComo empresaria y madre de 4 hijos percibo que en Per\u00fa existe a\u00fan machismo y brecha tanto en instituciones del Estado como en empresas privadas\u201d, manifest\u00f3 al respecto Mar\u00eda Dongo, gerenta de Fitosana e integrante de la junta directiva de la C\u00e1mara Peruana de Franquicias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Empresas y maternidad<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otra barrera que encuentran las directivas peruanas en su desarrollo profesional es el cuidado de la familia. Tal es as\u00ed que 6 de cada 10 ejecutivas peruanas encuestadas reconocen que la maternidad afect\u00f3 de alguna forma en su carrera profesional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abDe ellas, un 32,2% afirma que se ha planteado no tener m\u00e1s hijos para favorecer su trayectoria en la empresa\u00bb, detalla el estudio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, el 19,1% de las ejecutivas que no son madres asegura que ha pensado en no formar una familia por este motivo. Las consultadas tampoco creen que sean suficientes las medidas de sus empresas para que la maternidad no afecte a su desempe\u00f1o laboral y oportunidades de promoci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Dongo coincidi\u00f3 en que la maternidad s\u00ed afecta, pero que las instituciones y el Estado deber\u00edan impulsar m\u00e1s pol\u00edticas de g\u00e9nero que faciliten el desarrollo profesional de la mujer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl apoyo deber\u00eda ser no solo desde el Ministerio de la Mujer sino tambi\u00e9n con instituciones y leyes que favorezcan no solo a mujeres embarazadas sino a la crianza de los hijos con horarios flexibles, porque finalmente las mujeres cumplimos un rol importante dentro de la estructura empresarial como en el hogar\u201d, acot\u00f3 Dongo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Obst\u00e1culos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El informe de Esade, en colaboraci\u00f3n con Am\u00e9rica Econom\u00eda Intelligence, concluye en que los principales obst\u00e1culos que encuentran las ejecutivas peruanas en su camino hacia la alta direcci\u00f3n son las pocas pol\u00edticas eficientes de igualdad de g\u00e9nero en las empresas, la dificultad para alternar el cuidado de los hijos con las exigencias de un puesto de responsabilidad y la cultura empresarial que da por hecho que las mujeres no est\u00e1n comprometidas con su carrera profesional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se\u00f1ala que en el proceso de ascenso el 70,8% percibe un favoritismo por sus compa\u00f1eros varones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La clave<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Sueldos. En \u00e1mbitos generales, el ingreso promedio mensual de las mujeres asciende a S\/ 1.450 y de los varones a S\/ 2.027; es decir, estos \u00faltimos ganan S\/ 577 m\u00e1s, seg\u00fan el \u00faltimo informe de empleo del Instituto Nacional de Estad\u00edstica e Inform\u00e1tica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Seis de cada diez ejecutivas encuestadas afirman que la maternidad detuvo en alg\u00fan momento su carrera profesional <\/p>\n","protected":false},"author":3,"featured_media":15836,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[691,53],"tags":[],"class_list":["post-15835","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-internacional"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/15835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=15835"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/15835\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/15836"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=15835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=15835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=15835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}