{"id":15818,"date":"2020-01-21T22:35:50","date_gmt":"2020-01-21T22:35:50","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=15818"},"modified":"2023-07-21T15:18:51","modified_gmt":"2023-07-21T20:18:51","slug":"fondo-guadalupe-musalem-25-anos-de-cambiar-vidas","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/fondo-guadalupe-musalem-25-anos-de-cambiar-vidas\/","title":{"rendered":"Fondo Guadalupe Musalem: 25 a\u00f1os de cambiar vidas"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Inici\u00f3 su campa\u00f1a de procuraci\u00f3n de recursos 2020, esperan recaudar\nm\u00e1s de 2 mdp<\/strong><\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Durante\nel 2020 ser\u00e1n beneficiadas 25 j\u00f3venes mujeres de bachillerato y al menos 14\nuniversitarias. <\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Oaxaca, 21 de enero 2020.- El Fondo\nGuadalupe Musalem inici\u00f3 la campa\u00f1a de Procuraci\u00f3n de Fondos 2020 \u201cTu donativo\ncambia su vida\u201d, con el objetivo de reunir 2 millones 300 mil pesos para seguir fortaleciendo la educaci\u00f3n de j\u00f3venes oaxaque\u00f1as, misma que en 25\na\u00f1os ha otorgado becas a j\u00f3venes provenientes de comunidades ind\u00edgenas y\nrurales de esta entidad: 153\nhan realizado estudios de bachillerato y 46 m\u00e1s de nivel universitario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante\nla artista oaxaque\u00f1a, Lila Downs, quien ha acompa\u00f1ado el esfuerzo de esta\norganizaci\u00f3n, la presidenta del Fondo Guadalupe Musalem, Beatriz \u00c1vila Curiel,&nbsp; invit\u00f3 a las personas generosas a\nsolidarizarse para continuar otorgando las becas \u201cque van m\u00e1s all\u00e1 de un apoco\necon\u00f3mico, lo que el FGM les aporta son valores que las fortalece para tomar\nsus propias decisiones\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con\nel apoyo de personas generosas, durante el 2020 el Fondo Guadalupe Musalem\nbeneficiar\u00e1 en cada ciclo escolar a 25 j\u00f3venes mujeres de nivel medio superior\ny 14 m\u00e1s de nivel superior. Dentro de los beneficios que reciben las becarias\nse encuentran capacitaciones de formaci\u00f3n integral, servicios m\u00e9dicos,\nacompa\u00f1amiento de una tutora, beca econ\u00f3mica, entro otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zitlaly\nGuti\u00e9rrez, coordinadora de la cooperativa de mujeres \u201cVida Nueva\u201d de Teotitlan\nde Flores Mag\u00f3n, y quien logr\u00f3 sus estudios a trav\u00e9s de la Beca Guadalupe\nMusalem, manifest\u00f3: \u201cel Fondo nos da alas, nos hace crecer, nos ayuda a\nencontrarnos a nosotras mismas, a cambiar nuestras vidas, nuestras almas, con\nlos aprendizajes que nos transmiten somos capaces de fortalecer las buenas\npr\u00e1cticas de nuestra comunidad y cambiar las que por muchos a\u00f1os nos han\nlastimado por el hecho de ser mujeres. <\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2020\/01\/BECARIA-3-1024x683.jpg\" alt=\"\" data-id=\"15821\" data-link=\"https:\/\/redsemlac.com\/semmexico\/?attachment_id=15821\" class=\"wp-image-15821\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2020\/01\/BECARIA-5-1024x683.jpg\" alt=\"\" data-id=\"15823\" data-link=\"https:\/\/redsemlac.com\/semmexico\/?attachment_id=15823\" class=\"wp-image-15823\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2020\/01\/BECARIA-4-1024x611.jpg\" alt=\"\" data-id=\"15822\" data-link=\"https:\/\/redsemlac.com\/semmexico\/?attachment_id=15822\" class=\"wp-image-15822\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2020\/01\/BECARIA-2-1024x683.jpg\" alt=\"\" data-id=\"15820\" data-link=\"https:\/\/redsemlac.com\/semmexico\/?attachment_id=15820\" class=\"wp-image-15820\"\/><\/figure><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La\nempresaria oaxaque\u00f1a Herminda Fern\u00e1ndez (OMNI MUSIC) se refiri\u00f3 a lo honrada\nque se siente por haberse comprometido con el Fondo que ha encontrado\nsoluciones estructurales apost\u00e1ndole a la educaci\u00f3n, a\u00f1o tras a\u00f1o las becarias\nnos demuestran que este proyecto es un acierto, donantes, becarias, Fondo,\nsomos sin duda una red virtuosa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En\nsu oportunidad Lila Downs destac\u00f3 la forma en que las becas del Fondo Guadalupe\nMusalem ha contribuido a cambiar la vida de las j\u00f3venes oaxaque\u00f1as y que\nnuevamente anuncia el inicio de la nueva campa\u00f1a de recaudaci\u00f3n de recursos que\nse destinar\u00e1n a las becarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCon\nregocijo o\u00edmos hablar de las becarias que sobresalen gracias a su educaci\u00f3n,\nsus logros, sus sue\u00f1os, las mujeres que se han educado han regresado a su\ncomunidad de origen y han aportado al desarrollo de su comunidad, son semillas\nque dan frutos, cantar por ellas ha sido un venero de inspiraci\u00f3n y lo ser\u00e1\nsiempre\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante\nel 2020, el Fondo Guadalupe Musalem busca cumplir la meta de reunir 2 millones\n300 mil pesos, con la colaboraci\u00f3n de la sociedad en general, empresas,\nartistas, hombres y mujeres que conf\u00edan en el talento de las j\u00f3venes oaxaque\u00f1as\ny en la transparencia y rendici\u00f3n de cuentas de la organizaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los donativos entregados al Fondo\nGuadalupe Musalem A.C., por personas generosas, han permitido beneficiar a <strong>153 <\/strong>mujeres j\u00f3venes para realizar<strong> estudios de bachillerato<\/strong> y apoyar a <strong>46 de ellas en alg\u00fan tramo de sus estudios\nuniversitarios.&nbsp; <\/strong>El <strong>53<\/strong> por ciento de las beneficiarias son\nmujeres hablantes de una lengua ind\u00edgena, provenientes de <strong>100 localidades <\/strong>de<strong> 73\nmunicipios<\/strong> de Oaxaca.&nbsp; Actualmente se\napoya a <strong>25<\/strong> j\u00f3venes para cursar\nestudios de bachillerato y a <strong>15<\/strong> m\u00e1s\na realizar estudios universitarios. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los\nprincipales logros <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Dos\nbecarias universitarias del FGM se encuentran realizando estudios<\/li><li>superiores\nal obtener la beca <em>HeForShe<\/em> otorgada\npor la Universidad del Claustro de Sor Juana y ONU Mujeres.<\/li><li>Ocho\ngraduadas han sido elegidas por sus comunidades para desempe\u00f1ar cargos de\nelecci\u00f3n popular mediante el sistema normativo, o invitadas a incorporarse a la\nadministraci\u00f3n municipal, cuatro de ellas en el \u00faltimo proceso realizado en\n2019.&nbsp; <\/li><li>Tres\ngraduadas ocuparon puestos directivos y operativos en 2017 y 2018, en\ninstancias gubernamentales responsables de las pol\u00edticas p\u00fablicas en materia de\ng\u00e9nero.&nbsp; Una de ellas se desempe\u00f1a\nactualmente como Directora de fortalecimiento a las pol\u00edticas p\u00fablicas de la\nSecretar\u00eda de la Mujer Oaxaque\u00f1a. <\/li><li>Cuatro\ngraduadas del FGM han recibido el Premio Nacional de la Juventud y una m\u00e1s el\nPremio Estatal de la Juventud en 2015.<\/li><li>Dos\nj\u00f3venes han obtenido becas para realizar estudios en Estados Unidos. Y varias\nm\u00e1s han participado en reuniones internacionales de: Cine, Liderazgo,\nFeminismo, Turismo, Juventud Ind\u00edgena, etc. <\/li><li>Varias\nde las j\u00f3venes que fueron becarias de bachillerato participan activamente en\ncolectivos u organizaciones de la sociedad civil. <\/li><li>El\nFondo Guadalupe Musalem A.C. ha recibido el apoyo de asociaciones de otros\npa\u00edses como <em>Canadian Friends of Oaxaca<\/em>;\n<em>Foundation Mexxa<\/em>, Fundaci\u00f3n Malala,\nLatina Chicana, Fundaci\u00f3n Kellogg.&nbsp;\nActualmente forma parte de Global Giving para recibir donativos en l\u00ednea\ndeducibles en USA y UKA.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">95% de las j\u00f3venes beneficiarias del\nbachillerato concluyeron o est\u00e1n estudiando el bachillerato. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">68% de las j\u00f3venes que concluyeron el\nbachillerato realizaron o est\u00e1n realizando estudios universitarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14% de las j\u00f3venes que cursaron\nestudios universitarios, han realizado o est\u00e1n realizando estudios de posgrado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">58% de las j\u00f3venes que han realizado\nestudios universitarios, han sido apoyadas por el Fondo Guadalupe Musalem con\nuna beca universitaria, en alg\u00fan tramo de sus estudios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si\ndesea contribuir en la educaci\u00f3n de las j\u00f3venes becarias, existen varias\nopciones para hacer llegar sus aportaciones&nbsp;\ny obtener la deducibilidad de su donativo.&nbsp; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dep\u00f3sitos\no transferencias a la cuenta Fondo Guadalupe Musalem A.C., BANAMEX Sucursal:\n7005, Cuenta No. 4686887. CLABE 002610700546868876.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\nreciben donativos tambi\u00e9n a trav\u00e9s de PayPal. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si\nrequiere m\u00e1s informaci\u00f3n o desea realizar una consulta espec\u00edfica, puede llamar\nal (951) 514 6927 o bien escribir al correo\ncoordinacion@fondoguadalupemusalem.org<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inici\u00f3 su campa\u00f1a de procuraci\u00f3n de recursos 2020, esperan recaudar m\u00e1s de 2 mdp<\/p>\n","protected":false},"author":3,"featured_media":15819,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[691,54],"tags":[],"class_list":["post-15818","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-mujeres"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/15818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=15818"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/15818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/15819"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=15818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=15818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=15818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}