{"id":14809,"date":"2019-12-08T23:51:25","date_gmt":"2019-12-08T23:51:25","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=14809"},"modified":"2023-07-21T15:15:28","modified_gmt":"2023-07-21T20:15:28","slug":"opinion-248","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/opinion-248\/","title":{"rendered":"El Registro P\u00fablico de Agresores Sexuales y otros sue\u00f1os de CSI"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Por: Claudia Almaguer<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. 08 de diciembre 2019.- El pasado jueves 21 de\nnoviembre la jefa de gobierno de la Ciudad de M\u00e9xico Claudia Sheinbaum decret\u00f3\nuna \u201cAlerta de Violencia contra las Mujeres\u201d prometiendo entre otras cosas\npropuestas de ley relacionadas al tema como la que reci\u00e9n esta semana entreg\u00f3 al\nCongreso de esa entidad en la que propone la creaci\u00f3n de un \u201cRegistro P\u00fablico\nde Agresores Sexuales\u201d que pretende constituirse como una herramienta\ninnovadora de consulta p\u00fablica para la prevenci\u00f3n de la violencia sexual contra\nlas mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Preocupa profundamente entre la sociedad civil organizada\nque este gesto pol\u00edtico busque sustituir una alerta formal, porque ning\u00fan\ngobernante en el pa\u00eds ha emitido por s\u00ed mismo una Alerta de Violencia de G\u00e9nero\ndado que es un instrumento emanado de la Ley General de Acceso de las Mujeres a\nuna Vida Libre de Violencia que se genera a partir de todo un proceso\nestablecido en el Reglamento de dicha norma y que decreta la Secretar\u00eda de\nGobernaci\u00f3n a trav\u00e9s de la Comisi\u00f3n Nacional para Prevenir y Erradicar la\nViolencia contra las Mujeres. Luego entonces lo que se decret\u00f3 en CDMX tiene\nlos alcances que Sheinbaum determine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto al revuelo causado por su propuesta legal la\np\u00e1gina del Congreso de Ciudad de M\u00e9xico indica que la iniciativa de Ley del\nRegistro P\u00fablico de Agresores Sexuales permitir\u00eda contar con informaci\u00f3n de las\npersonas con sentencia firme por la comisi\u00f3n de delitos de car\u00e1cter sexual lo\nque supuestamente generar\u00eda investigaciones eficaces contribuyendo as\u00ed a\ngarantizar derechos de las v\u00edctimas, pero tambi\u00e9n contendr\u00eda informaci\u00f3n de\nacceso p\u00fablico de estas personas como la fotograf\u00eda actual, el nombre, la edad,\nlos alias, la nacionalidad y el delito o delitos sexuales. Y no s\u00f3lo es\ninevitable pensar en sistemas de registros de agresores sexuales como el de\nEstados Unidos, sino que estos son expresamente mencionados como referente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bueno, pues pensemos en espacios como el National Sex\nOffender Public Website (NSOPW) que se define como un recurso de seguridad\np\u00fablica para los ciudadanos estadounidenses y es el resultado de toda una labor\nde colaboraci\u00f3n entre el Departamento de Justicia, los gobiernos estatales,\nterritoriales y tribales que permite el acceso no s\u00f3lo a datos personales como\nel nombre, los alias y fotograf\u00edas recientes, sino tambi\u00e9n la ubicaci\u00f3n y la\nproximidad de un delincuente sexual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde luego cada Estado norteamericano de acuerdo con su\npropia legislaci\u00f3n permite m\u00e1s o menos informaci\u00f3n del agresor sexual, por\nejemplo, Nueva York refiere que los jueces asignan a seg\u00fan cada caso 3 niveles\nde riesgo a los delincuentes sexuales que son supervisados de manera bien distinta:\nlos datos de un agresor en nivel 1 no se comparten, aunque deben junto con los\nde nivel 2 actualizar sus fotograf\u00edas cada tres a\u00f1os. En cambio, aquellos en\nnivel 3 est\u00e1n obligados a subir sus fotos anualmente y son vigilados cada 90\nd\u00edas por la polic\u00eda del lugar en el que vivan inclusive para verificar que no\nhayan cambiado su apariencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero all\u00ed existe otro sistema jur\u00eddico penal que no se\nparece al nuestro por m\u00e1s que compartamos ciertos elementos del procedimiento\ncomo la oralidad, el debate, etc\u00e9tera. Adem\u00e1s, all\u00ed hay tambi\u00e9n un acuerdo\nfundamental en t\u00e9rminos de la informaci\u00f3n, sistemas de datos sofisticados que\npueden compartirse sin agujeros porque todos all\u00ed entienden un marco conceptual\ncom\u00fan para los registros y cuentan con programas para lo que aqu\u00ed llamamos\nreinserci\u00f3n social y la vigilancia en este caso de cierto tipo de criminales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pretender comparar eso a la propuesta de Ciudad de M\u00e9xico\nmuy probablemente de con resultados indeseados, pero sirve para exponer otros\nvac\u00edos relacionados a las agresiones sexuales que se suscitan en el pa\u00eds:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En M\u00e9xico el agresor\nsexual no es ning\u00fan extra\u00f1o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para empezar, aqu\u00ed sabemos perfectamente cu\u00e1l es el perfil\nde los agresores sexuales de mujeres la Encuesta Nacional de la Din\u00e1mica de las\nRelaciones en los Hogares 2016 del Instituto Nacional de Estad\u00edstica y\nGeograf\u00eda indica que de las 4.4 millones de mujeres que se\u00f1alaron haber\npadecido abusos sexuales en la infancia m\u00e1s del 80 % fueron agredidas por un\npariente masculino o persona cercana a la familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En entrevista al Universal la Directora General de Pol\u00edticas\nP\u00fablicas de la Comisi\u00f3n Ejecutiva de Atenci\u00f3n a V\u00edctimas Ana Mar\u00eda Su\u00e1rez\nse\u00f1al\u00f3 que 9 de cada 10 agresiones fueron cometidas por hombres y el 70 % de\nlas mismas sucedi\u00f3 en el hogar de la v\u00edctima. Luego entonces, son urgentes\notras formas de intervenci\u00f3n antes que invertir en el uso de nuevas tecnolog\u00edas\ny buscadores que den con que el agresor est\u00e1 en la habitaci\u00f3n contigua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En M\u00e9xico los\nagresores sexuales con sentencia firme no son muchos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de que la ENDIREH indica que 10.8 millones de\nmujeres en el tiempo del levantamiento de la encuesta fueron sometidas a\ndistintos actos de violencia sexual desde el acoso hasta la violaci\u00f3n, el\nn\u00famero de denuncias por estos delitos fueron mucho menos, 36,933 en 2017,\n42,929 en 2018 y 43,187 hasta octubre de 2019, busque ahora el n\u00famero de\nsentenciados por delitos sexuales y si encuentra alguna informaci\u00f3n al respecto\nver\u00e1 que son todav\u00eda menos los que tienen sentencia firme. Precisamente la CEAV\nestima que anualmente se cometen 600 mil delitos sexuales, pero apenas 10\nagresores por cada mil denuncias son consignados ante la autoridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta impunidad est\u00e1 \u00edntimamente relacionada a lo que se\nmencion\u00f3 en la columna pasada, para que haya posibilidad de sanci\u00f3n debe haber\ninvestigaciones de calidad de los delitos sexuales en M\u00e9xico que no se reduce\ns\u00f3lo a una acusaci\u00f3n simplista en contra del Ministerio P\u00fablico sino a la\nverificaci\u00f3n de si se cuenta o no con los recursos materiales y humanos, adem\u00e1s\nde los conocimientos especializados para la integraci\u00f3n de la perspectiva de\ng\u00e9nero en el ejercicio de la acci\u00f3n penal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En M\u00e9xico la\nrecopilaci\u00f3n y la disponibilidad de la informaci\u00f3n es un caos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pensar en crear un registro de agresores sexuales en M\u00e9xico\nno tiene sentido si hablamos de una sola entidad federativa, para que\nfuncionase como herramienta en la investigaci\u00f3n y no como mero discurso tendr\u00eda\nque constituirse a nivel nacional y el obst\u00e1culo ser\u00eda homologar los criterios\npara los registros que se hacen en las instituciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta dificultad es notoria al momento en que las \u00e1reas del\ngobierno federal o la Comisi\u00f3n Nacional de Derechos Humanos se animan a la\nelaboraci\u00f3n de diagn\u00f3sticos sobre el manejo de algunos delitos, por ejemplo, en\nla publicaci\u00f3n del Diagn\u00f3stico Cuantitativo sobre la Atenci\u00f3n de la Violencia\nSexual en M\u00e9xico de marzo de 2016 el Comit\u00e9 de Violencia Sexual de la CEAV\nsolicit\u00f3 informaci\u00f3n de las v\u00edctimas, de los presuntos agresores, del delito\ncometido y los servicios proporcionados. As\u00ed 9 procuradur\u00edas no entregaron\ndatos, 5 enviaron formatos in\u00fatiles y las otras 18 ten\u00edan informaci\u00f3n\nincompleta. Lo mismo ocurri\u00f3 con la autoridad jurisdiccional, en donde 11\ntribunales no entregaron datos, 1 manifest\u00f3 no contar con la informaci\u00f3n, 5\nenviaron formatos in\u00fatiles y los otros 15 tambi\u00e9n tuvieron inconsistencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a ello respecto a la calidad de los datos entregados\nse indica: \u201cLa informaci\u00f3n recibida muestra una amplia heterogeneidad en los\nmecanismos, procedimientos y sistemas de registro. Incluso entre las\ninstituciones que brindan el mismo tipo de servicio en las diferentes entidades\nfederativas\u2026 resulta evidente que en t\u00e9rminos generales cada dependencia\nregistra las variables que considera relevantes y lo hace de manera distinta,\nconsiderando diferentes rangos, periodos, y tipo de informaci\u00f3n.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En M\u00e9xico el prop\u00f3sito de la privaci\u00f3n de la libertad y\notras sanciones es la reinserci\u00f3n social (aunque usted no lo crea)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hecho de contar con una sentencia firme respecto a un\ndelito no significa que una persona pierda todos sus derechos, el art\u00edculo 18\nconstitucional indica que el sistema penitenciario se organizar\u00e1 sobre la base\ndel respeto a los derechos humanos, del trabajo, la capacitaci\u00f3n para el mismo,\nla educaci\u00f3n, la salud y el deporte como medios para lograr la reinserci\u00f3n del\nsentenciado a la sociedad y procurar que no vuelva a delinquir, observando los\nbeneficios que para \u00e9l prev\u00e9 la ley.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto conduce a que instrumentos jur\u00eddicos como la Ley\nNacional de Ejecuci\u00f3n Penal defina la reinserci\u00f3n social como la restituci\u00f3n\ndel pleno ejercicio de las libertades tras el cumplimiento de una sanci\u00f3n o\nmedida ejecutada con respeto a los derechos humanos. As\u00ed la persona privada de\nsu libertad tiene derecho a recibir un trato digno, asistencia, alimentaci\u00f3n,\neducaci\u00f3n y formaci\u00f3n para el trabajo, porque no se trata de que el Estado se\nvengue, sino que coadyuve a que la persona pueda resolver las circunstancias\nque le llevaron a delinquir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a la reinserci\u00f3n para responsables de delitos que\nconstituyen violencia de g\u00e9nero apenas se han propuesto reformas al respecto,\npero no han sido tomadas en cuenta, en San Luis Potos\u00ed duerme el sue\u00f1o de los\njustos la iniciativa presentada en junio por el gobernador Carreras que integra\nadem\u00e1s de las sanciones para los delitos de feminicidio, violaci\u00f3n, abuso\nsexual, acoso sexual y violencia familiar, el acceso a servicios reeducativos\nintegrales que se establecen en el art\u00edculo 13 de la Ley de Acceso de las\nMujeres a una Vida Libre de Violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si algo evidencia esta idea de Claudia es que en M\u00e9xico no\nexiste la reinserci\u00f3n social con perspectiva de g\u00e9nero, esto es el delincuente\nagresor de mujeres sale y es devuelto a su entorno creyendo en su propia\nsuperioridad y en otros estereotipos de la masculinidad machista, verdadero\nproblema en esta trama.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, y con todo esto, la idea de vigilar a dos o tres\nagresores sexuales con sentencia sin antes resolver estos obst\u00e1culos es un\ndesprop\u00f3sito legal que suena a ofensa por querer prometer soluciones expr\u00e9s a\nproblem\u00e1ticas sist\u00e9micas. A m\u00e1s ver.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Preocupa profundamente entre la sociedad civil organizada que este gesto pol\u00edtico busque sustituir una alerta formal<\/p>\n","protected":false},"author":3,"featured_media":14810,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[690,82,110],"tags":[],"class_list":["post-14809","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-la-opinion","category-la-opinion-columnas"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/14809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=14809"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/14809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/14810"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=14809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=14809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=14809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}