{"id":13527,"date":"2019-11-04T18:02:55","date_gmt":"2019-11-04T18:02:55","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=13527"},"modified":"2023-07-21T15:13:51","modified_gmt":"2023-07-21T20:13:51","slug":"que-la-democracia-se-vuelva-cronica","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/que-la-democracia-se-vuelva-cronica\/","title":{"rendered":"Que la democracia se vuelva cr\u00f3nica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong> Norma Loto<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Buenos Aires, Argentina. 04 de noviembre 2019.- Para buscar a la t\u00eda en el geri\u00e1trico hab\u00eda que dejar todo ordenado en su casa y eso no es poca cosa: el desayuno, el hijo, el cachorrito, pensar el almuerzo, la ropa y todo. Todo y m\u00e1s, as\u00ed como viven (vivimos) las mujeres, Y por \u00faltimo, buscar el documento en ese bolso lleno de sorpresas, migas, monedas, agendas, libros. El documento. Sin eso<em>, \u00a1no vale la pena intentar votar!,<\/em>\u00a0le canchere\u00f3 (algo tan obvio)Juan, el hije ni\u00f1e creciente de Ene.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ese domingo 27 de octubre, Ene empez\u00f3 as\u00ed &nbsp;y sin saber que la vida le ense\u00f1ar\u00eda un par de cosas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hab\u00eda que llegar al geri\u00e1trico. Llegar hasta all\u00ed no es la gran cosa. Solo hay que conducir derecho por Cabildo hasta Lacroze y desde all\u00ed caminar unos pocos metros. Pero, llegar hasta ese lugar es predisponerse de fuerzas que tambalean a cada instante, de construir columnas internas que sirvan para sostener el alma que observa la muerte en vida o la vida en muerte de quienes all\u00ed duran y perduran.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, tambi\u00e9n el desaf\u00edo es sacar a la t\u00eda del geri\u00e1trico. La \u201ct\u00eda\u201d, se llama Monina y&nbsp; tiene 98 a\u00f1os. Se mueve poco, por eso &nbsp;hay que ayudar a pararse, a bajar las escalera, a sostenerse de parada. A veces usa un tr\u00edpode, pero es in\u00fatil, tampoco sirve. Pero su mente, es \u00fanica; porque simplemente es brillantemente l\u00facida, ubicada en tiempo y espacio, \u00a1es una masa!. Ella, cuenta con orgullo que fue una de las primeras mujeres divorciadas, cuando divorciarse era ley, pero casi no era un hecho, ni verbo pero s\u00ed era una herej\u00eda<em>, \u201cporque no importaba si eras infeliz. Hab\u00eda que bajar la cabeza y perdonar todo. Eso, era ser buena mujer\u201d<\/em>. Cuenta, tambi\u00e9n, que pas\u00f3 por la experiencia de vivir con \u201crareza\u201d el derecho del voto de las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero ahora es tan dif\u00edcil mover a Monina con esa fragilidad corrosiva. Estar con ella es como hacerse cargo de esos instantes que podr\u00edan ser los \u00faltimos de su vida. Sin embargo, hay que simular y sonre\u00edr y hablar pausado y repetir todo mil veces y sudar la espalda por la insoportable tensi\u00f3n. S\u00ed, sobre todo, eso, sonre\u00edr y hacer como que \u00abac\u00e1 no pasa nada\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de salir del geri\u00e1trico, Ene le record\u00f3: \u201c<em>no es obligaci\u00f3n que votes Monina. Pod\u00e9s no votar a tu edad\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Monina le clav\u00f3 su mirada y apret\u00f3 sus dientes como seguramente lo hizo cuando ech\u00f3 de la casa\u00a0 a su ex, al que a\u00fan lo llama \u201cel muy vivo\u201d, \u201cel infiel\u201d\u00a0<em>\u00a1No, nena, no. Es mi deber votar. Ll\u00e9vame, ya! \u00a1Yo quiero votar y no se habla m\u00e1s!<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El imperativo de Monina, fue como si un tel\u00f3n cayera sobre el escenario. No hab\u00eda nada m\u00e1s por hablar: hab\u00eda que llevarla a votar. (Y quiz\u00e1s aplaudir)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ene se abochorn\u00f3 y medit\u00f3 que nunca hab\u00eda dimensionado la vida de Monina. Es que &nbsp;hab\u00eda recorrido un largo camino esa \u201cmuchacha\u201d. Caminos sinuosos entre dictaduras y democracias y &nbsp;m\u00e1s dictaduras hasta llegar a esta bendita y prolongada democracia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cSi mi viejo me escuchara tratando de persuadir a alguien para que no vote, se enojar\u00eda mucho, much\u00edsimo. Quiz\u00e1s est\u00e1 sentado al lado del Tata Dios, diciendo: \u00b4mir\u00e1, esa mi hija. Nunca le ense\u00f1\u00e9 eso\u00a8\u201d,<\/em>&nbsp;imagin\u00f3 Ene.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incluso, alguna vez, Ene hab\u00eda coqueteando con una iniciativa llamada Kil\u00f3metro 501, que invitaba a la ciudadan\u00eda a trasladarse a m\u00e1s de 500 kil\u00f3metros del domicilio para que \u00abno votes y no te multen\u00bb. Es que en los a\u00f1os 90, eran muchas m\u00e1s las ganas de huir que de votar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El domingo 27,\u00a0 Ene que es periodista y profe, \u00a0tambi\u00e9n pens\u00f3 en la juventud que no conoce otra cosa que la democracia y que a veces se la observa con pocos compromisos c\u00edvicos sociales y pol\u00edticos. Ese domingo de votaci\u00f3n tampoco imagin\u00f3 lo que se ven\u00eda el mi\u00e9rcoles en la clase del aula 402. Es que sus alumnxs dir\u00edan en sus cr\u00f3nicas que el domingo hab\u00eda sido\u00a0<em>\u201cun d\u00eda especial para todos los argentinos, elegir representante lo damos como moneda corriente pero no todos los estados tienen ese derecho, tenemos que festejarlo<\/em>\u201d, \u00a0que\u00a0<em>\u201cel d\u00eda de la votaci\u00f3n es algo as\u00ed como d\u00eda festivo, donde todos salen a la calle y se juntan en puntos de encuentros\u201d,<\/em>\u00a0que\u00a0<em>\u201cdes-afortunadamente para el pa\u00eds , la democracia no fue siempre tan popular y justa\u201d<\/em>, que el domingo era \u201c<em>el d\u00eda de hacer honores a la modalidad de gobiernos caracter\u00edstica de\u00a0la Argentina\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de las pocas cosas espont\u00e1neas que el patriarcado no prohibi\u00f3 a las mujeres es: emocionarse. Y si es con l\u00e1grimas, MEJOR. Y Ene sabe de eso y se dio el permiso de emocionarse en el aula 402 al escuchar las cr\u00f3nicas. Ese mi\u00e9rcoles 30 de octubre, tras escuchar a sus alumnxs, revivi\u00f3 la odisea que fue hacer votar a su t\u00eda y record\u00f3 que su padre, un pol\u00edtico que &nbsp;se hab\u00eda pasado la &nbsp;vida persiguiendo revoluciones, le dec\u00eda:&nbsp;<em>\u201caunque te hayan decepcionado nunca pierdas las ganas de votar\u00bb.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ese mi\u00e9rcoles mientras Bel\u00e9n, Mateo y Agustina le\u00edan sus cr\u00f3nicas, se cumpl\u00eda 36 a\u00f1os\u00a0 de aquel 30 de octubre de 1983, cuando el pueblo argentino volv\u00eda a las urnas tras una sangrienta dictadura. Un 30 de octubre, el Dr Ra\u00fal Alfons\u00edn fue electo presidente. As\u00ed, las urnas ya no estaban \u201c<em>bien guardadas<\/em>\u201d, como presumi\u00f3 alguna vez el Genocida. Y esa profesora, se dio cuenta que no solo su t\u00eda hab\u00eda recorrido un largo camino sino que el camino se lo recorre todos los d\u00edas para estar del lado libre de la vida. Y pens\u00f3, tambi\u00e9n, que: \u00abojal\u00e1 que la pasi\u00f3n por votar nunca se pierda y que\u00a0 la democracia se vuelva cr\u00f3nica\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ese domingo 27 de octubre, Ene empez\u00f3 as\u00ed  y sin saber que la vida le ense\u00f1ar\u00eda un par de cosas.<\/p>\n","protected":false},"author":3,"featured_media":13528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[690,53],"tags":[],"class_list":["post-13527","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-internacional"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/13527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=13527"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/13527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/13528"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=13527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=13527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=13527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}