{"id":13495,"date":"2019-11-01T02:36:01","date_gmt":"2019-11-01T02:36:01","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=13495"},"modified":"2023-07-21T15:13:15","modified_gmt":"2023-07-21T20:13:15","slug":"opinion-198","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/opinion-198\/","title":{"rendered":"Ambig\u00fa"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Atrapado Amlo en su red de mentiras y equ\u00edvocos<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>+ Quiere prensa anodina y solapadora, como la que odiaba<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Martha Elba Torres Mart\u00ednez<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atrapado en su propia red de mentiras y equ\u00edvocos, el\npresidente L\u00f3pez Obrador termin\u00f3 ayer por agudizar a\u00fan m\u00e1s la severa crisis de\ncomunicaci\u00f3n que enfrenta desde el 17 de octubre, por el caso Culiac\u00e1n. Y\nsiempre, quien la lleva, es la prensa por su obligaci\u00f3n social de cuestionar.\nQuiere medios anodinos y solapadores, los mismos que tanto critic\u00f3 en su relaci\u00f3n\ncon otros gobiernos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pleito ya no es solo con Reforma, Proceso, Carlos Loret,\nahora es con Televisa y La Jornada. Las y los periodistas ya no solo son fif\u00eds,\nd\u00e9spotas, sabelotodo y hampones, sino tambi\u00e9n perros malagradecidos que muerden\na quien les quita el bozal. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay un desprecio encarnado ya en todo lo que represente\ncuestionamiento a sus decisiones y acciones. Lo vimos con sus desplantes\nvalemadristas sobre el accidente que sobrevino a de parte de su \u201cfuente\u201d, el\npasado fin de semana en Sonora. \u00bfPara qu\u00e9 van? Que cubran con corresponsales.\nPara que las rechiflas y reclamos que se multiplican en las plazas donde se\npara, desaparezcan del material audiovisual oficial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Odia L\u00f3pez Obrador, que la prensa no se fije en lo\nimportante del operativo fallido en Culiac\u00e1n ni crea las distintas siete\nversiones que se dieron sobre el arresto y liberaci\u00f3n de Ovidio Guzm\u00e1n. \u00bfPor\nqu\u00e9 jodidos no entienden que todo fue para salvar vidas? <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Ah! Chinga! Acaso le importa la cuenta de sangre en lo que\nva de su gobierno: 26 mil homicidios dolosos, mil de ellos feminicidios. Y a\nlos asesinos les ruega: \u00a1ya no hay guerra\u2026 queremos paz! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfMedito acaso que forzar al general Crescencio Sandoval, la\nrevelaci\u00f3n de la identidad del coronel que dirigi\u00f3 el operativo en la capital\nsinaloense, es tanto como firmar su sentenciada, e incluso la de su familia?\nTodo por un chivo expiatorio, para una estrategia de seguridad fallida, vituperada\ncon el piensen en sus mamacitas y el fuchi y wuacala, por el propio\npresidente\/predicador que se siente la reencarnaci\u00f3n de Jes\u00fas el Cristo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero siempre entre lo malo hay cosas buenas. Ojal\u00e1 L\u00f3pez\nObrador entienda que su sobreexposici\u00f3n todas las ma\u00f1anas con sus \u201cotros datos\u201d,\nque no son m\u00e1s que una sarta de mentiras, termina marcando la agenda medi\u00e1tica,\npero en su contra. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El razonamiento period\u00edstico tiene a la verificaci\u00f3n de\ndatos, al cruce de informaci\u00f3n y cotejos. A eso es a lo que le tiene tirria:\nque lo que dice, no se asuma como verdad absoluta y \u00fanica al margen de la\nrealidad. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro arista, y dir\u00eda el m\u00e1s in\u00e9dito en L\u00f3pez Obrador, es que\nhaya aceptado que se equivocaron. Eso s\u00ed es realmente novedoso, porque nunca\nacepta sus errores. Lo vimos con el nuevo aeropuerto de Texcoco, con las\nestancias infantiles, los medicamentos, Santa Luc\u00eda, el Tren Maya y una\nrefiner\u00eda cucha y la peor decisi\u00f3n: paralizar la inversi\u00f3n en obra p\u00fablica,\nporque los recursos en bancos dejan mejores dividendos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero hay que pensar en positivo y esperemos que m\u00e1s que\naceptaci\u00f3n de equivocaciones, corrija\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ***<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Porque \u00a1ah! Como se equivocaron con el operativo. Lo m\u00e1s\ngrotesco, el video presentado en el minuto a minuto de Culiac\u00e1n, en donde el\njoven Guzm\u00e1n L\u00f3pez queda como el h\u00e9roe de la pel\u00edcula. \u00a1Gracias! Por ordenar a\nsus sicarios, detener el ataque contra las fuerzas armadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYa paren todo, oiga, ya paren todo, ya me entregu\u00e9. Ya\nparen todo, por favor. Ya paren todo, ya tranquilos, ya ni modo. D\u00edgales que se\nretiren, pero d\u00edgales pues, ya, ya no quiero, que, que, que haya desmadres. Ya\nno quiero que haya desmadre, por favor\u201d. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pues pinche caso que le hicieron y por eso lo tuvieron qu\u00e9\nliberar. El caso, que tema de inter\u00e9s para los medios en la ma\u00f1anera de ayer,\nfue precisamente sobre qui\u00e9n recibi\u00f3 la llamada para negociar \u2013si se puede\nnombrar as\u00ed-, la entrega de Ovidio. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero en esta pel\u00edcula, hay dos villanos: Alfonso Durazo, el\njefe de Gabinete de Seguridad y el bueno para nada de Jes\u00fas Ram\u00edrez, que en\ncomunicaci\u00f3n de la Presidencia, no da una. Su renuncia es obligada, porque no\nsirven como funcionarios, no dan resultados y los contribuyentes pagamos sus\nimpuestos. Si L\u00f3pez Obrador es congruente con el tema de la corrupci\u00f3n, ya los\ndebe botar y poner en su lugar quienes si devenguen el salario\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atrapado Amlo en su red de mentiras y equ\u00edvocos<\/p>\n","protected":false},"author":3,"featured_media":9024,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,99,90],"tags":[],"class_list":["post-13495","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-ambigu","category-martha-elba-torres-martinez"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/13495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=13495"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/13495\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/9024"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=13495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=13495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=13495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}