{"id":13171,"date":"2019-10-21T21:24:47","date_gmt":"2019-10-21T21:24:47","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=13171"},"modified":"2023-07-21T15:13:24","modified_gmt":"2023-07-21T20:13:24","slug":"justiciaparafatima","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/justiciaparafatima\/","title":{"rendered":"F\u00e1tima, la justicia que a\u00fan no est\u00e1 completa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>* Pendiente la\nsentencia de uno de sus tres victimarios<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>* Casi cinco a\u00f1os\nde un brutal asesinato y una justicia ni pronta ni expedita<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lorena Vaniezcot<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 21 octubre 2019.-\nF\u00e1tima ten\u00eda 12 a\u00f1os, estudiaba la secundaria. Era una ni\u00f1a cuando fue\nbrutalmente violada, torturada y asesinada, los hechos ocurrieron el 5 de\nfebrero de 2015, en el municipio de Lerma, Estado de M\u00e9xico. Sin embargo, la\njusticia a\u00fan no est\u00e1 completa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su madre, Lorena Guti\u00e9rrez tiene reflejado\nen su rostro las huellas del dolor que le han dejado estos cuatro a\u00f1os y ocho\nmeses sin poder concretar que la justicia sea para su hija. Luis \u00c1ngel A.R. fue\nsentenciado a 76 a\u00f1os de c\u00e1rcel, pero Misael A.R., por ser menor de edad solo\nrecibi\u00f3 una condena de cinco a\u00f1os, mientras que Jos\u00e9 Juan H.T. espera\nsentencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El camino a la justicia ha estado plagado\nirregularidades dentro de las instituciones, pero tambi\u00e9n de amenazas de muerte\npor parte de las familias de los victimarios de F\u00e1tima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En enero pr\u00f3ximo, se podr\u00eda realizar la\naudiencia de Jos\u00e9 Juan H.T., quien anteriormente present\u00f3 unos videos que\nsupuestamente servir\u00edan de coartada, pues su pretensi\u00f3n era ser ubicado en su\ntrabajo, la escuela Sierra Nevada, donde supuestamente se encontraba al momento\ndel brutal asesinato de la ni\u00f1a F\u00e1tima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El material audiovisual presentado como\nprueba es una copia, con deficiencias para observar claramente que se trata del\ninculpado, pese a ello, la juez de control Janeth Pati\u00f1o Garc\u00eda admiti\u00f3 el\nvideo, lo que dej\u00f3 en libertad a Jos\u00e9 Juan H.T., pero de nueva cuenta la\nfamilia de F\u00e1tima logr\u00f3 que fuera reaprehendido y que el video fuera analizado\npor personas expertas, lo que ocurri\u00f3 en nuevas audiencias. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, la familia logr\u00f3 que otro juez\ndesestimara como prueba el material audiovisual, en tanto que la defensa de\nJos\u00e9 Juan interpuso un amparo que est\u00e1 en revisi\u00f3n, lo que ha retrasado la\nposibilidad de la sentencia condenatoria en su contra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy, la familia considera indispensable que\nlas autoridades no consideren de nueva cuenta el video como prueba a favor del\ninculpado y se termine de una vez por todas con la cadena de omisiones\ninstitucionales que pondr\u00edan en riesgo concluir el juicio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Una historia de\ninfamia y la lucha de una familia<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed un resumen del recuento hecho por\nMiklo Rivera, periodista de Los Machos nos matan en M\u00e9xico: F\u00e1tima ten\u00eda 12\na\u00f1os de edad. Sal\u00eda de la secundaria, a las dos de la tarde, cuando\npresuntamente Jos\u00e9 Juan H.T, Luis \u00c1ngel A. R, y Misael A. R., sus vecinos, la\nsometieron, hiri\u00e9ndola en cuello y cara con navaja, y la llevaron a un \u00e1rea\nboscosa en la carretera Toluca-Naucalpan. Ah\u00ed la torturaron, abusaron de ella,\ny la mataron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La se\u00f1ora Lorena, mam\u00e1 de F\u00e1tima, inici\u00f3 su\nb\u00fasqueda en compa\u00f1\u00eda de varios vecinos al ver que la peque\u00f1a no regresaba de la\nescuela. En un punto por donde ella pasaba de regreso, encontraron su sudadera\ny un cuchillo ensangrentados. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue entonces cuando vieron huir a los tres\nimputados. Uno de ellos llevaba la mochila de F\u00e1tima llena de sangre. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue su propia madre quien encontr\u00f3 el\ncuerpo de su hija parcialmente enterrado y oculto bajo una llanta. Al parecer\nla enterraron agonizante, pero a\u00fan viva, pues una mano y un pie sobresal\u00edan,\ndatos que comprobar\u00edan personal forense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s\nde ser detenidos por los propios vecinos, los tres j\u00f3venes iban a ser linchados\npero fue la propia Lorena Guti\u00e9rrez quien lo impidi\u00f3. Los tres fueron\nhospitalizados y posteriormente ingresados al penal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de ah\u00ed empezaron las\ncomplicaciones debido a que la carpeta de investigaci\u00f3n estaba plagada de\nerrores y omisiones por parte de la Fiscal\u00eda del Estado de M\u00e9xico; la peor de\nellas fue que el Ministerio P\u00fablico no contaba con tiras reactivas, y por ello\nno se compararon los perfiles gen\u00e9ticos de los implicados con las muestras de\nsangre en la ropa hallada en el domicilio de los hermanos Luis \u00c1ngel y Misael\nA.R., en el cuerpo de F\u00e1tima, y otras evidencias encontradas en el lugar de los\nhechos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto provoc\u00f3 que Jos\u00e9 Juan H. T., alias \u201cEl\npel\u00f3n\u201d, supuesto autor intelectual del feminicidio, fuera absuelto y puesto en\nlibertad, pese a que varios testigos lo vieron correr con la misma ropa llena\nde sangre que fue encontrada en casa de los A.R.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Juez de control Janeth Pati\u00f1o Garc\u00eda\ndecret\u00f3 que este brutal crimen no hab\u00eda sido un feminicidio (aunque\nposteriormente la se\u00f1ora Lorena y su esposo lograron que este crimen se\ntipificara correctamente). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta misma juez desestim\u00f3 a todos los\ntestigos y pruebas en contra de \u201cEl Pel\u00f3n\u201d, aunque curiosamente las mismas\npruebas y testigos fueron admitidas por ella para juzgar al mayor de los\nhermanos A.R.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n admiti\u00f3 los testimonios aportados\npor la escuela particular \u201cSierra Nevada\u201d, donde el director y el conserje de\ndicha instituci\u00f3n afirmaban que \u201cEl Pel\u00f3n\u201d era jardinero de dicha escuela, y\nese d\u00eda supuestamente hab\u00eda laborado en el horario en que ocurrieron los\nhechos, para lo cual presentaron un video antes mencionado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En septiembre de 2015, luego de una serie\nde llamadas con amenaza de muerte, y acoso en escuelas y trabajos de varios\nfamiliares, la casa de la se\u00f1ora Lorena fue baleada. Esto provoc\u00f3 que ella y su\nfamilia fueran desplazados constantemente por varios puntos del estado y la\nrep\u00fablica. Desde entonces no tienen un hogar fijo, les es dif\u00edcil conseguir\nempleo y constantemente viven con miedo, pero ni as\u00ed han desistido. Incluso la\nentonces subprocuradora para la Atenci\u00f3n de Delitos Vinculados a la Violencia\nde G\u00e9nero del Estado de M\u00e9xico, Dilcya Samantha Garc\u00eda Espinoza de los\nMonteros, hab\u00eda ofrecido ubicarlos en Canad\u00e1, lo que no se concret\u00f3 para no\ncontradecir las declaraciones sobre que en M\u00e9xico se garantizaban los derechos\nhumanos de las personas, en respuesta a los cuestionamientos que hab\u00eda hecho\nAmnist\u00eda Internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl Pel\u00f3n\u201d fue puesto en libertad el pasado\n8 de junio del a\u00f1o en curso, pero la se\u00f1ora Lorena y su esposo, Je\u00fas Quintana,\ninterpusieron un amparo que est\u00e1 en revisi\u00f3n. Jos\u00e9 Juan H. T., fue presentado\nbajo custodia preventiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/lv\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pendiente la sentencia de uno de sus tres victimarios<\/p>\n","protected":false},"author":3,"featured_media":13172,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[690,47,48],"tags":[],"class_list":["post-13171","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-no-mas-impunidad","category-no-mas-impunidad-no-mas-impunidad"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/13171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=13171"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/13171\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/13172"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=13171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=13171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=13171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}