{"id":12930,"date":"2019-10-15T16:43:18","date_gmt":"2019-10-15T16:43:18","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=12930"},"modified":"2023-07-21T15:12:49","modified_gmt":"2023-07-21T20:12:49","slug":"opinion-161","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/opinion-161\/","title":{"rendered":"Entresemana"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>\u00bfHonestos, honestos, honestos?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mois\u00e9s S\u00e1nchez Lim\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Cd.&nbsp; de M\u00e9xico. 15 de octubre&nbsp; de 2019.- En v\u00edas de aprobarse la Ley de Ingresos y la miscel\u00e1nea fiscal del 2020, el jueves de esta semana en la C\u00e1mara de Diputados, y con el resultado de la evaluaci\u00f3n de la pol\u00edtica de seguridad que ha dejado mal sabor de boca, sobre todo porque en la ma\u00f1ana que se presenta el informe en Palacio Nacional, en Michoac\u00e1n el poderoso y sanguinario Cartel Jalisco Nueva Generaci\u00f3n masacr\u00f3 a por lo menos 14 polic\u00edas estatales, aunque una informaci\u00f3n reservada alude a 27 uniformados, la pregunta es elemental: \u00bfse abate a la corrupci\u00f3n?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lamentablemente la corrupci\u00f3n es un mal contra el que no hay vacuna preventiva ni mecanismo sancionatorio que la frene, por m\u00e1s que se endurezcan penalidades y deslindes de venganzas pol\u00edticas en la aplicaci\u00f3n de la ley contra delincuentes de cuello blanco, porque incluso \u00e9stos pillos se han vinculado con el crimen organizado que se ha tornado sanguinario e inhumano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Usted lo sabe bien, porque ha escuchado en los m\u00e1s recientes procesos electorales el recurrente intercambio de acusaciones entre aspirantes a cargos de elecci\u00f3n popular de tener v\u00ednculos con el crimen organizado, de proteger a delincuentes cuando no incluso ser socio de ellos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y ha ocurrido, ah\u00ed est\u00e1 la informaci\u00f3n en redes sociales. Por supuesto hay la que tiene todo el halo del pago, el soborno, para hablar mal del contrincante; est\u00e1n las acusaciones sin sustento, \u00e9stas que se echan a andar con el objetivo de convertir en verdad a la mentira repetida mil veces y que acaba con famas p\u00fablicas y destruye reputaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero igual nos enteramos de c\u00f3mo un alcalde o un gobernador se asociaron con el crimen organizado. Y est\u00e1n en prisi\u00f3n personajes como Roberto Borge, Tom\u00e1s Yarrington Ruvalcaba o Javier Duarte, de comprobada complicidad y hasta jefatura en sociedades criminales de cuello blanco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O aquel matrimonio imperial integrado por el presidente municipal de Iguala, Guerrero, Jos\u00e9 Luis Abarca Vel\u00e1zquez y su es posa Mar\u00eda de los \u00c1ngeles Pineda Villa, a cuyos hermanos se vincul\u00f3 con la organizaci\u00f3n Guerreros Unidos, asociados con el cartel Beltr\u00e1n Leyva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Porque est\u00e1 visto que en esto de las sociedades delictivas, siglas e ideolog\u00eda son asunto secundario aunque el poder que implican sus prohombres en el estrellato de las ligas mayores o menores, son del mismo tama\u00f1o de los negocios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y los poderes f\u00e1cticos que representan en puntos estrat\u00e9gicos del pa\u00eds, se tejieron desde aquellos d\u00edas en que la Procuradur\u00eda General de la Rep\u00fablica entr\u00f3 en el tobog\u00e1n del descr\u00e9dito y su actuar fue sin\u00f3nimo de complicidades, como ocurri\u00f3 en el momento en que un diputado federal del PAN ascendi\u00f3 a Procurador General de la Rep\u00fablica para supuestamente procurar justicia y dar con los responsables de los asesinatos del cardenal Juan Jes\u00fas Posadas Ocampo, Luis Donaldo Colosio Murrieta y Jos\u00e9 Francisco Ruiz Massieu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfAlguien imagin\u00f3 en diciembre de 1994 que Fernando Antonio Lozano Gracia ser\u00eda un p\u00e9simo procurador que asumir\u00eda instrucciones presidenciales de dar con los autores de aquellos cr\u00edmenes a como diera lugar?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salvo quienes conoc\u00edan los antecedentes de quien fuera el fiscal de esos casos, Jos\u00e9 Pablo Chapa Bezanilla, p\u00fablicamente se le consider\u00f3 probo junto con Lozano Gracia por el hecho de ser, \u00e9ste, de un partido pol\u00edtico diferente al de Ernesto Zedillo Ponce de Le\u00f3n, es decir, el PRI, y Chapa un abogado si partido, metido a polic\u00eda al servicio del mejor postor como luego se confirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfHonestos? Se echaron campanas al vuelo y, bien que mal, en la PGR se estim\u00f3 que Lozano y Chapa integraban a una dupla que resolver\u00eda los casos. Y m\u00e1s hubo j\u00fabilo de pol\u00edticos y partidos de oposici\u00f3n al PRI, cuando fue detenido Ra\u00fal Salinas de Gortari, ni m\u00e1s ni menos que el hermano mayor del ex presidente Carlos Salinas de Gortari.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Golpe al PRI-gobierno asestado por uno de los suyos, el del m\u00e1ximo cargo, el Presidente de la Rep\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y luego, en tiempo r\u00e9cord Chapa Bezanilla solt\u00f3 a sus sabuesos junto con millones de pesos para comprar voluntades y armar el caso, fabricar delincuentes. Y lo mismo compr\u00f3 a una vidente, Francisca Zetina Ch\u00e1vez, que a testigos que se\u00f1alaron a Ra\u00fal Salinas como autor material e intelectual del asesinato de Jos\u00e9 Francisco,&nbsp; y a Oth\u00f3n Cort\u00e9s V\u00e1zquez en el papel de segundo tirador, c\u00f3mplice de Mario Aburto en el magnicidio de Luis Donaldo Colosio Murrieta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfAlguien recuerda estos justicieros? En su momento, calificados honestos al final resultaron delincuentes que usaron al sistema de justicia, a la procuraci\u00f3n e impartici\u00f3n de \u00e9sta para el servicio de fines pol\u00edticos. \u00bfY Ernesto Zedillo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El se\u00f1orpresidente Zedillo Ponce de Le\u00f3n qued\u00f3 a salvo de estos asuntos de corrupci\u00f3n en el gobierno, en casos en los que se usaron recursos p\u00fablicos y los jueves que trataron las denuncias contra Lozano Gracia y Chapa Bezanilla los exoneraron. El ex procurador pis\u00f3 los juzgados, fuera de la rejilla de pr\u00e1cticas, sin dormir en alguna celda del Reclusorio Sur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chapa huyo, fue detenido en Espa\u00f1a y antes de enfrentar un largo y costos juicio de extradici\u00f3n acept\u00f3 ser tra\u00eddo a M\u00e9xico, donde pas\u00f3 breve tiempo en el Reclusorio y luego, en libertad, fue absuelto de los cargos que se le imputaron; impune qued\u00f3 libre de cargos pese a que se le comprob\u00f3 todo, absolutamente todo de lo que se le acus\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lozano Gracia dirige un caro despacho de abogados con sede en las Lomas de Chapultepec, mientras Chapa Bezanilla se gana la vida litigando asuntos de mujeres solas, viudas y etc\u00e9tera, etc\u00e9tera, que le deja lo suficiente para vivir con comodidad en su residencia del Barrio del Ni\u00f1o Jes\u00fas, por los rumbos de Tlalpan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y el principal afectado por el uso faccioso de la procuraci\u00f3n e impartici\u00f3n de justicia, Oth\u00f3n Cort\u00e9s, junto con otros chivas expiatorios, algunos de ellos ya murieron, fueron marginados de la sociedad, se\u00f1alados como delincuentes y, pese a comprobarse su inocencia, que no fueron responsables m\u00e1s que estar en la hora y el lugar equivocados, han vivido en la desgracia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfHonestos, honestos, honestos? No hay vacuna contra la corrupci\u00f3n, el ADN de la corrupci\u00f3n y la deshonestidad est\u00e1 en los genes de estos pol\u00edticos y aprendices de brujo que arriban a las costas del poder en cada sexenio. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La secretaria de la Funci\u00f3n P\u00fablica, Irma Er\u00e9ndira Sandoval Ballesteros, dijo ante senadores que est\u00e1 comprometida a erradicar la corrupci\u00f3n de la vida p\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sostuvo que en la actual administraci\u00f3n, en la dependencia a su cargo, ya no hay intocables ni siguen existiendo perseguidos pol\u00edticos. Pero, inform\u00f3 que hay alrededor de 28 mil investigaciones en proceso por presuntas irregularidades, 30 por ciento m\u00e1s que en la administraci\u00f3n pasada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y hay otros datos duros que arroja esta tarea de do\u00f1a Irma Er\u00e9ndira. Bien por la advertencia de que ya no hay intocables pero, \u00bfC\u00f3mo est\u00e1 eso de que creci\u00f3 el n\u00famero de investigaciones en proceso? Se ha actuado en lo que va de la actual administraci\u00f3n contra funcionarios p\u00fablicos. Mire usted, del nivel que sean el hecho es que evidencian que la pus emana de una herida abierta que se llama corrupci\u00f3n. \u00bfHonestos? Digo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:sanchezlimon@gmail.com\" target=\"_blank\" rel=\"noreferrer noopener\">sanchezlimon@gmail.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.entresemana.mx\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.entresemana.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">@msanchezlimon<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfHonestos, honestos, honestos?<\/p>\n","protected":false},"author":3,"featured_media":8470,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[690,105,83],"tags":[],"class_list":["post-12930","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-entresemana","category-moises-sanchez-limon"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/12930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=12930"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/12930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/8470"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=12930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=12930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=12930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}