{"id":12894,"date":"2019-10-14T17:29:28","date_gmt":"2019-10-14T17:29:28","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=12894"},"modified":"2023-07-21T15:12:50","modified_gmt":"2023-07-21T20:12:50","slug":"cuba-18","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/cuba-18\/","title":{"rendered":"Cuba: Cadenas productivas, debates para el desarrollo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Dixie Edith<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/SEMlac. La Habana, Cuba. 14 de septiembre 2019.- &nbsp;Trabas burocr\u00e1ticas, falta de preparaci\u00f3n de\nfuncionarios y decisores y una mirada m\u00e1s dirigida a la oferta que a la demanda\nest\u00e1n entre los principales obst\u00e1culos para el desarrollo de cadenas\nproductivas, coincidieron integrantes de una red de trabajo solidario, en La\nHabana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abHay que tener en cuenta que las cadenas productivas\nexisten, pero no siempre est\u00e1n identificadas o bien articuladas\u00bb, explic\u00f3\nla doctora Betsy Anaya, directora del Centro de Estudios de la Econom\u00eda Cubana\n(CEEC).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta realidad, por tanto, representa un desaf\u00edo para un pa\u00eds\nque ha venido diversificando sus actores y formas de producci\u00f3n en los \u00faltimos\na\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCu\u00e1les son las condiciones de Cuba para potenciar el\ndesarrollo de encadenamientos productivos? \u00bfY los principales obst\u00e1culos? \u00bfCon\nqu\u00e9 experiencias se cuenta ya?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esas interrogantes inici\u00f3 el debate del V Encuentro de\nla Red de Trabajo Cooperado y Solidario, que reuni\u00f3 a productores y productoras\nde cooperativas, cuentapropistas, as\u00ed como actores de espacios comunitarios, de\nla academia y de la investigaci\u00f3n econ\u00f3mica y social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Convocado por el Grupo Am\u00e9rica Latina: Filosof\u00eda Social y\nAxiolog\u00eda (Galfisa), del Instituto de Filosof\u00eda, la sesi\u00f3n de trabajo puso la\nlupa sobre experiencias ya existentes de cadenas productivas o de valor, pero,\nsobre todo, en c\u00f3mo apoyar el desarrollo de esta importante modalidad\nproductiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El encuentro dio continuidad a citas anteriores, tambi\u00e9n\nobra de la iniciativa de Galfisa, grupo que promueve estudios e investigaciones\nsobre la realidad latinoamericana y los movimientos, redes sociales y\nalternativas emancipadoras en la regi\u00f3n, seg\u00fan declara su perfil en internet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es necesario buscar variantes, puntos de complementariedad\nque permitan establecer ciclos productivos entre formas diversas de gesti\u00f3n\ncomo las privadas, las cooperativas y las estatales, reflexion\u00f3 el doctor\nOvidio D&#8217;Angelo, investigador del Centro de Investigaciones Psicol\u00f3gicas y\nSociales (CIPS).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su juicio, \u00ablas recientes formas de gesti\u00f3n no\nestatal emergieron sin suficientes bases organizativas, econ\u00f3micas, legales,\nculturales, que podr\u00edan haberlas precedido para un mejor\ndesenvolvimiento\u00bb, abunda D&#8217;Angelo en su art\u00edculo \u00ab\u00bfEs posible una\neconom\u00eda social amplia y solidaria en nuestra realidad actual?\u00bb, publicado\nen la revista Temas, en el segundo semestre de 2018.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Anaya incluye el an\u00e1lisis del contexto donde\nse producir\u00e1 la cadena, el conocimiento de los mercados, de los precios y el\nacceso a servicios de apoyo, entre otros, como condiciones esenciales para su\nexistencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La experiencia de la cooperativa urbana de confecciones\ntextiles Model, en la capital cubana, permiti\u00f3 apreciar algunas maneras de\narticular esas cadenas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando tenemos mucha demanda, armamos encadenamientos\nproductivos con entidades estatales o con otras cooperativas, explicaron, a dos\nvoces, Elsida Ricardo y Eumelia Beltr\u00e1n, asociadas de la cooperativa textil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ellas contaron que, en momentos en que tienen muchos\nencargos, Model ha dado vida a talleres estatales que permanec\u00edan cerrados, o\nproduciendo a menor escala, a menudo por falta de materias primas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Igualmente, una vez que se termina la confecci\u00f3n b\u00e1sica de\nalguna pieza textil, tambi\u00e9n acuden a productores privados para completar\nlabores de bordado o de impresi\u00f3n serigr\u00e1fica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al final, aseguran Ricardo y Beltr\u00e1n, todas las partes salen\nbeneficiadas, pues mientras se consigue subir los ingresos de la cooperativa\ncon menos costo y satisfacer el mercado, tambi\u00e9n se ayuda a la vitalidad de\ntalleres estatales o de emprendimientos privados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los encadenamientos productivos han sido identificados como\nprioritarios para los planes de desarrollo del pa\u00eds. En febrero de 2019,\ndurante el balance del Ministerio de Industrias, el presidente Miguel\nD\u00edaz-Canel los reconoci\u00f3 como un \u00abpotencial para el desarrollo\u00bb,\nseg\u00fan public\u00f3 el diario Granma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s recientemente, en junio, el titular de Econom\u00eda y\nPlanificaci\u00f3n (MEP), Alejandro Gil, los calific\u00f3 de \u00abnecesidad\nimperiosa\u00bb ante unos 400 profesionales participantes en el VIII Congreso\nde la Asociaci\u00f3n Nacional de Economistas y Contadores (ANEC).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, se mantienen trabas legislativas y modos de\nplanear el desarrollo, a\u00fan muy centralizados, que no permiten que estos\nprocesos se organicen de manera exitosa, alert\u00f3 el doctor D&#8217;Angelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La dilataci\u00f3n en el tiempo de procesos, las carencias en las\nnormas legales que regulan los cambios econ\u00f3micos m\u00e1s recientes y la necesidad\nde mayor autonom\u00eda municipal para propiciar apoyos al desarrollo local y\ncomunitario fueron dificultades identificadas por el experto y compartidas por\ncasi todas las personas presentes en el encuentro convocado por Galfisa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otra realidad com\u00fan es la urgencia de encontrar mecanismos\nque permitan, de manera r\u00e1pida y sencilla, que cooperativas y emprendimientos\nprivados puedan aportar al desarrollo de las comunidades. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">dixiedith@gmail.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trabas burocr\u00e1ticas, falta de preparaci\u00f3n de funcionarios,  principales obst\u00e1culos para el desarrollo de cadenas productivas.<\/p>\n","protected":false},"author":3,"featured_media":12895,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,53],"tags":[],"class_list":["post-12894","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-internacional"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/12894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=12894"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/12894\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/12895"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=12894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=12894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=12894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}