{"id":12862,"date":"2019-10-14T15:22:24","date_gmt":"2019-10-14T15:22:24","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=12862"},"modified":"2023-07-21T15:12:51","modified_gmt":"2023-07-21T20:12:51","slug":"morelos-6","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/morelos-6\/","title":{"rendered":"Urgente coordinaci\u00f3n en la b\u00fasqueda de personas desaparecidas"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Plantea CIDH Morelos llevar a cabo acciones\ninterinstitucionales<\/strong><\/li><li><strong>Demandan ante la Fiscal\u00eda aplicaci\u00f3n de protocolos\nAmber y Alba<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cuernavaca, Mor., 14 octubre 2019.-Ante el creciente n\u00famero de desapariciones, es urgente que haya\ncoordinaci\u00f3n interinstitucional para la b\u00fasqueda y localizaci\u00f3n de todas las\npersonas desaparecidas en Morelos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed lo expone la Comisi\u00f3n Independiente de Derechos\nHumanos de Morelos, asociaci\u00f3n civil que sostiene que se requiere que todas las acciones se lleven a cabo dentro de un plan\nestatal de b\u00fasqueda que priorice acciones tendientes a localizar y recuperar\ncon vida a todas las mujeres, ni\u00f1as y j\u00f3venes que son quienes desaparecen en\nmayor medida. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ning\u00fan esfuerzo es menor para combatir \u00e9sta\nterrible pr\u00e1ctica de la desaparici\u00f3n forzada cometida por el Estado o por\nparticulares que cuentan con la omisi\u00f3n o aquiescencia de las autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Garantizar la vida y la seguridad de las v\u00edctimas\ncon una investigaci\u00f3n cient\u00edfica, sistem\u00e1tica y objetiva sobre las causas de\nlas desapariciones, acorde con lo establecido en la Ley para Prevenir, Atender\ny Sancionar la Desaparici\u00f3n Forzada y la Cometida por Particulares y el\nProtocolo Homologado de B\u00fasqueda de Personas Desaparecidas, demand\u00f3 la\norganizaci\u00f3n en un comunicado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 9 de\noctubre pasado, integrantes de la Comisi\u00f3n Independiente de Derechos Humanos de\nMorelos, se reunieron con Danae Vel\u00e1zquez Luna, secretaria Ejecutiva de la\nFiscal\u00eda General, y Zayra Lulo Juan, titular de la Fiscal\u00eda Especializada en\nDesaparici\u00f3n Forzada, quienes informaron sobre las actividades realizadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las y los\nintegrantes de la CIDH-Morelos solicitaron se redoblen los esfuerzos y\nacciones, as\u00ed como una estrategia efectiva para implementar el Protocolo Alba, instrumento\nlegal que se aplica en casos de mujeres adultas desaparecidas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese\nsentido la Fiscal Zayra Lulo reconoci\u00f3 que todav\u00eda les hace falta trabajarlo\npara aplicarlo a las condiciones del Estado de Morelos, ya que actualmente\ndepende de la Fiscal\u00eda General de la Rep\u00fablica. Dijo que tambi\u00e9n se carece de\npersonal especializado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La\nasociaci\u00f3n civil defensora de los derechos humano tambi\u00e9n demand\u00f3 la aplicaci\u00f3n\nrigurosa de la Alerta Amber, que se aplica en caso de desaparici\u00f3n de ni\u00f1as y\nni\u00f1os menores de 17 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fiscal\u00eda\ninform\u00f3 que cuenta con una base de datos actualizada, sin embargo, es urgente\ncontar con un estudio profundo sobre las desapariciones, ello implica hacer\ninvestigaciones con la participaci\u00f3n de especialistas en antropolog\u00eda, medicina\nforense, especialistas en estudios gen\u00f3micos, as\u00ed como contar con instrumentos\nde b\u00fasqueda y geolocalizaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, de una\nbase de datos que permita cruzar la informaci\u00f3n con todas las dependencias\nestatales y nacionales para agilizar la respuesta, que debe ser inmediata y\nacorde con el protocolo homologado, que permita a las autoridades como a los\nfamiliares de v\u00edctimas y a la sociedad en su conjunto para tener conciencia de\nla magnitud y las consecuencias que tiene cada desaparici\u00f3n para quienes la\nviven directamente y para sus familiares y conocidos e impedir que la mayor\u00eda\nde los casos permanezcan en la impunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de\nconcretar mayores acciones de coordinaci\u00f3n con el Mecanismo Nacional de\nB\u00fasqueda mediante la instalaci\u00f3n de la Comisi\u00f3n Estatal de B\u00fasqueda, donde la\nCIDH-Morelos ser\u00e1 parte del Consejo Ciudadano, junto con familiares de v\u00edctimas\nde desaparici\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las\npersonas desaparecidas deben ser buscadas mediante planes de acci\u00f3n y con una\nmetodolog\u00eda bien estructurada en: Hospitales Psiqui\u00e1tricos, cl\u00ednicas, centros\npara el combate a las adicciones, c\u00e1rceles clandestinas, cuarteles militares,\nprisiones de alta seguridad, asilos, bares y centros nocturnos donde se presuma\ntrata de personas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En dicho\ncontexto pensamos que no se debe bajar la guardia en cuanto al seguimiento\nlegal de los distintos casos hist\u00f3ricos y emblem\u00e1ticos por desaparici\u00f3n en\nMorelos y que jur\u00eddicamente a\u00fan contin\u00faan abiertos tal como es el caso del\ncompa\u00f1ero Jos\u00e9&nbsp;Ram\u00f3n Garc\u00eda G\u00f3mez desaparecido por agentes del Estado en\nel a\u00f1o de 1988, se\u00f1ala la CIDH-Morelos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plantea CIDH Morelos llevar a cabo acciones interinstitucionales<\/p>\n","protected":false},"author":3,"featured_media":12863,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,54],"tags":[],"class_list":["post-12862","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-mujeres"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/12862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=12862"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/12862\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/12863"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=12862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=12862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=12862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}