{"id":12858,"date":"2019-10-14T15:15:35","date_gmt":"2019-10-14T15:15:35","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=12858"},"modified":"2023-07-21T15:12:51","modified_gmt":"2023-07-21T20:12:51","slug":"cultura-5","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/cultura-5\/","title":{"rendered":"Subastar\u00e1n dibujo a l\u00e1piz de Remedios Varo"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Esta obra sale a la luz coincidiendo con su 56\naniversario luctuoso.<\/strong><\/li><li><strong>Ser\u00e1 expuesta con entrada libre en Morton Subastas\njunto con 353 lotes m\u00e1s que componen la Subasta de Arte Mexicano<\/strong><strong><\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Se<\/strong>mM\u00e9xco, Cd. de M\u00e9xico, 14 octubre 2019.- Un dibujo a l\u00e1piz de grafito sobre papel de 36.3 x 17 cm de la pintora surrealista Remedios Varo, nunca antes visto p\u00fablicamente, ser\u00e1 puesto a la venta en subasta, con estimados de 450 mil pesos y 600 mil pesos, el pr\u00f3ximo mi\u00e9rcoles 16 de octubre a las 5 de la tarde en el sal\u00f3n de Morton Subastas, ubicado en Monte Athos 179, colonia Lomas de Chapultepec, en la Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a\nlos especialistas, que confirmaron su autenticidad, se trata de una pieza \u00fanica\nque pudo haber sido un boceto o estudio previo a las conocidas obras Locomoci\u00f3n\ncapilar (1959) o Visita inesperada (1958) en donde aparece un personaje muy\nsimilar al del dibujo que ser\u00e1 subastado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De hecho, las mujeres que pintaba Remedios Varo, tienen facciones muy parecidas a las suyas, aunque no se sabe con exactitud si ella pretend\u00eda hacer autorretratos o no.\u00a0Esta obra adquiere relevancia al ser un boceto, pues para la artista el proceso creativo era mucho m\u00e1s importante que la obra final, se\u00f1ala un bolet\u00edn de prensa de Morton Subastas.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2019\/10\/VARO-465x1024.jpg\" alt=\"\" class=\"wp-image-12859\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La obra de Remedios Varo es muy codiciada entre coleccionistas nacionales y extranjeros.\u00a0Fue una de las primeras mujeres en estudiar arte en Madrid y, debido a la guerra, se exili\u00f3 en M\u00e9xico para nunca m\u00e1s volver a Europa. Su pintura busc\u00f3 reflejar los estados internos del alma.\u00a0Muri\u00f3 a los 55 a\u00f1os, el 8 de octubre de 1963, hace exactamente 56 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cat\u00e1logo\nde la Subasta de Arte Mexicano cuenta con 354 lotes de artistas de nuestro pa\u00eds\ny de autores que, como en el caso de Remedios Varo, se nacionalizaron mexicanos\ny su producci\u00f3n la realizaron en nuestro pa\u00eds. Algunos de ellos son Jos\u00e9 Ch\u00e1vez\nMorado, Alfonso Michel, Fernando Garc\u00eda Ponce, Arnold Belkin y Arturo Souto,\nentre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todas ellas estar\u00e1n expuestas del 9 al 15 de octubre del 2019 en Monte Athos 179, Lomas de Chapultepec, con entrada libre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias a la\npresencia de obras dignas de museo, la Subasta de Arte Mexicano que se realiza\na\u00f1o con a\u00f1o, es uno de los foros m\u00e1s importantes para los coleccionistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un dibujo a l\u00e1piz de grafito sobre papel de 36.3 x 17 cm de la pintora surrealista Remedios Varo, nunca antes visto p\u00fablicamente, ser\u00e1 puesto a la venta en subasta, con estimados de 450 mil pesos y 600 mil pesos, el pr\u00f3ximo mi\u00e9rcoles 16 de octubre a las 5 de la tarde en el sal\u00f3n de Morton Subastas, ubicado en Monte Athos 179, colonia Lomas de Chapultepec, en la Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a\nlos especialistas, que confirmaron su autenticidad, se trata de una pieza \u00fanica\nque pudo haber sido un boceto o estudio previo a las conocidas obras Locomoci\u00f3n\ncapilar (1959) o Visita inesperada (1958) en donde aparece un personaje muy\nsimilar al del dibujo que ser\u00e1 subastado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De hecho, las mujeres que pintaba Remedios Varo, tienen facciones muy parecidas a las suyas, aunque no se sabe con exactitud si ella pretend\u00eda hacer autorretratos o no.\u00a0Esta obra adquiere relevancia al ser un boceto, pues para la artista el proceso creativo era mucho m\u00e1s importante que la obra final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La obra de Remedios Varo es muy codiciada entre coleccionistas nacionales y extranjeros.\u00a0Fue una de las primeras mujeres en estudiar arte en Madrid y, debido a la guerra, se exili\u00f3 en M\u00e9xico para nunca m\u00e1s volver a Europa. Su pintura busc\u00f3 reflejar los estados internos del alma.\u00a0Muri\u00f3 a los 55 a\u00f1os, el 8 de octubre de 1963, hace exactamente 56 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cat\u00e1logo\nde la Subasta de Arte Mexicano cuenta con 354 lotes de artistas de nuestro pa\u00eds\ny de autores que, como en el caso de Remedios Varo, se nacionalizaron mexicanos\ny su producci\u00f3n la realizaron en nuestro pa\u00eds. Algunos de ellos son Jos\u00e9 Ch\u00e1vez\nMorado, Alfonso Michel, Fernando Garc\u00eda Ponce, Arnold Belkin y Arturo Souto,\nentre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todas ellas estar\u00e1n expuestas del 9 al 15 de octubre del 2019 en Monte Athos 179, Lomas de Chapultepec, con entrada libre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias a la\npresencia de obras dignas de museo, la Subasta de Arte Mexicano que se realiza\na\u00f1o con a\u00f1o, es uno de los foros m\u00e1s importantes para los coleccionistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Morton\nSubastas-Kristina Velfu<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/sl\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta obra sale a la luz coincidiendo con su 56 aniversario luctuoso.<\/p>\n","protected":false},"author":3,"featured_media":12860,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,45,46],"tags":[],"class_list":["post-12858","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-cultura","category-cultura-cultura"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/12858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=12858"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/12858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/12860"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=12858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=12858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=12858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}