{"id":12854,"date":"2019-10-14T15:07:28","date_gmt":"2019-10-14T15:07:28","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=12854"},"modified":"2023-07-21T15:12:51","modified_gmt":"2023-07-21T20:12:51","slug":"opinion-157","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/opinion-157\/","title":{"rendered":"Alfa Omega"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>La Medalla Belisario Dom\u00ednguez ser\u00e1, para una mujer, por octava ocasi\u00f3n<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jorge Herrera Valenzuela<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico.\n14 de octubre 2019.- El 20 de Noviembre de 2006 la senadora perredista <strong>Mar\u00eda del Rosario Ibarra de la Garza <\/strong>le\ntom\u00f3 protesta como \u201cpresidente leg\u00edtimo\u201d e impuso la banda presidencial con el\n\u00e1guila juarista al tabasque\u00f1o que no acept\u00f3 su derrota en las elecciones\npresidenciales de ese a\u00f1o. El 23 de octubre de 2019 el Presidente de M\u00e9xico, <strong>Andr\u00e9s Manuel L\u00f3pez Obrador<\/strong>, ser\u00e1\ntestigo en la ceremonia en que la luchadora social <strong>Rosario Ibarra de Piedra<\/strong>, reciba la Medalla Belisario Dom\u00ednguez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La C\u00e1mara de\nSenadores aprob\u00f3 entregar la presea a una mexicana que desde 1974 est\u00e1\nentregada en una tarea que comenz\u00f3 al desaparecer su hijo <strong>Jes\u00fas Piedra Ibarra<\/strong>, luego de ser detenido bajo el cargo de\npertenecer a la Liga Comunista 23 de Septiembre y ser acusado de participar en\nla muerte del polic\u00eda Guillermo Villarreal Valdez, seg\u00fan consta en las publicaciones\nde la \u00e9poca. La incansable se\u00f1ora Ibarra de Piedra, originaria de Saltillo,\nCoahuila, a los 91 a\u00f1os de edad recibir\u00e1 el reconocimiento por esa incansable\nlucha que abarca a todas las v\u00edctimas de la violencia que vivimos desde hace\nm\u00e1s de medio siglo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Do\u00f1a Rosario Ibarra de Piedra<\/strong> ser\u00e1 la octava mujer condecorada con\nla medalla que por primera ocasi\u00f3n fue otorgada, en 1954, a la profesora sudbajacaliforniana\n<strong>Mar\u00eda Rosaura Zapata Cano<\/strong>. Ocho a\u00f1os\ndespu\u00e9s la distinci\u00f3n fue para la actriz defe\u00f1a <strong>Mar\u00eda Tereza Montoya Pardav\u00e9<\/strong>. En 1963 el reconocimiento correspondi\u00f3\na la veracruzana <strong>Mar\u00eda Hern\u00e1ndez Zarco<\/strong>,\nquien expuso su vida en 1913 al imprimir y distribuir el discurso que pronunci\u00f3\nel <strong>senador Belisario Dom\u00ednguez Palencia<\/strong>,\nel 23 de septiembre del a\u00f1o citado, contra el usurpador <strong>Victoriano Huerta<\/strong>, calific\u00e1ndolo de \u201csoldado sanguinario y feroz\nasesino\u201d. El 7 de octubre, hace 106 a\u00f1os, el valiente m\u00e9dico chiapaneco fue\nacribillado a tiros en el pante\u00f3n de Xoco, al Sur de la Capital del Pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el a\u00f1o\n1969 los integrantes de la comisi\u00f3n senatorial que determina a quien entregan\nla multicitada medalla, hicieron un doble reconocimiento al aprobar la\ndistinci\u00f3n para la mer\u00edtense <strong>Mar\u00eda\nC\u00e1mara Vales<\/strong>, esposa del \u00faltimo Vicepresidente que hubo en M\u00e9xico, el\nabogado y periodista tabasque\u00f1o <strong>Jos\u00e9\nMar\u00eda Pino Su\u00e1rez<\/strong>, asesinado junto con <strong>Francisco\nI. Madero<\/strong>, por \u00f3rdenes de Victoriano Huerta, durante la triste \u201cDecena\nTr\u00e1gica\u201d en febrero de 1913, en el exterior de la Penitenciar\u00eda del Distrito\nFederal. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Transcurrieron\n16 a\u00f1os para que nuevamente una mujer fuera merecedora de la Medalla Belisario\nDom\u00ednguez y ella fue la profesora y jurista campechana <strong>Mar\u00eda Lavalle Urbina<\/strong>, en 1985&nbsp;\ny a la poeta, escritora y primera gobernadora en el pa\u00eds, <strong>Griselda \u00c1lvarez Ponce de Le\u00f3n<\/strong>, le\ncorrespondieron los honores en 1996, a cuatro a\u00f1os de cumplir los 100. En el\npresente siglo la primera en ser distinguida fue la bi\u00f3loga <strong>Julia Carabias Lillo<\/strong>, en 2017, siendo\nla m\u00e1s joven de las recipiendarias, pues ten\u00eda 63 a\u00f1os de edad y adem\u00e1s es la\n\u00fanica superviviente del grupo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TRAYECTORIA DE DO\u00d1A ROSARIO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No pocas\npersonas se extra\u00f1aron que la Medalla Belisario Dom\u00ednguez sea entregada, en\neste a\u00f1o, a <strong>Rosario Ibarra de Piedra<\/strong>,\nsi ella se ha enfrentado permanentemente a los gobiernos constitucionales. La\nrespuesta es simple: los tiempos han cambiado y seguramente quienes la\npropusieron y quienes la aprobaron, tomaron en cuenta los a\u00f1os en que la\nsaltillense ha dedicado su tiempo a la b\u00fasqueda de su hijo, a la defensa de las\nv\u00edctimas de la \u201cGuerra Sucia\u201d y la cercan\u00eda personal de la se\u00f1ora Rosario, desde\nhace a\u00f1os, con quien ahora es el Presidente de la Rep\u00fablica. Recuerdo el\nrevuelo que se produjo cuando en 1979 los priistas le impusieron esa medalla al\nl\u00edder de la CTM, <strong>Fidel Vel\u00e1zquez S\u00e1nchez<\/strong>;\nen \u201cLa Docena Azul\u201d los presidentes Vicente Fox y Felipe Calder\u00f3n impulsaron\nlas propuestas a favor de <strong>Carlos\nCastillo Peraza <\/strong>y de <strong>Luis H. \u00c1lvarez<\/strong>,\nen 2007 y en 2010, respectivamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En reg\u00edmenes\nPRIistas otros dos ilustres PANistas fueron recipiendarios de la medalla. En\n1998, el licenciado <strong>Jos\u00e9 \u00c1ngel Conchello\nD\u00e1vila<\/strong> y don <strong>Manuel G\u00f3mez Mor\u00edn<\/strong>,\nfundador del partido blanquiazul, en 2013. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bueno, pero\nretomo el comentario con la trayectoria de do\u00f1a Rosario que en 1977 fund\u00f3 un\norganismo de largo nombre y que encierra en s\u00ed su cometido; Comit\u00e9 Pro Defensa\nde Presos, Perseguidos, Desaparecidos y Exiliados Pol\u00edticos. Un a\u00f1o despu\u00e9s, en\nsu movimiento determina hacer huelgas de hambre para que el gobierno decrete\nuna amnist\u00eda para los presos pol\u00edticos y en ese mismo a\u00f1o el presidente <strong>Jos\u00e9 L\u00f3pez Portillo<\/strong> concede la\namnist\u00eda. Esta luchadora social se une a la Federaci\u00f3n Latinoamericana de\nAsociaciones de Familiares de Detenidos Desaparecidos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como ya era\nmuy conocida, esta activista es arropada por el Partido Revolucionario de los\nTrabajadores (PRT) y es diputada federal. En 1982 queda registrada como\ncandidata presidencial, tambi\u00e9n por el PRT y volver\u00eda a figurar como aspirante\na la Presidencia de M\u00e9xico, en 1988. Despu\u00e9s se sum\u00f3 al grupo del ingeniero <strong>Cuauht\u00e9moc C\u00e1rdenas Sol\u00f3rzano<\/strong>&nbsp; y consigui\u00f3 ser senadora del 2006 al 2012.En\ncuatro ocasiones estuvo propuesta para el Premio Nobel de la Paz: 1986, 1987,\n1989 y 2006.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro\npersonaje, fue hija de un ingeniero agr\u00f3nomo y militar revolucionario. Su\nesposo identificado como militante activo del Partido Comunista Mexicano y en\nsu \u00e9poca estudiantil fue l\u00edder socialista en la Universidad Aut\u00f3noma de Nuevo\nLe\u00f3n. Su yerno Germ\u00e1n Escobedo Segovia particip\u00f3 en el secuestro de un avi\u00f3n de\nCMA que sali\u00f3 del D. F. y lo llevaron a La Habana, Cuba, en 1972.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las\nelecciones del pasado 1 de julio de 2018, <strong>L\u00f3pez\nObrador <\/strong>&nbsp;dijo haber emitido su voto,\npara Presidenta de M\u00e9xico, a favor de do\u00f1a Rosario Ibarra de Piedra, como un\nhomenaje a su labor y a la mujer. La sesi\u00f3n solemne de la C\u00e1mara de Senadores\ntendr\u00e1 lugar, en la fecha antes se\u00f1alada, en la antigua sede de esa\nlegisladora, en la Plaza Xicot\u00e9ncatl, el acceso ser\u00e1 mediante rigurosa\ninvitaci\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>BUEN JEFE POLIC\u00cdACO, EN LA CDMX<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El\nnombramiento de <strong>Oscar Garc\u00eda Harfuch<\/strong>\ncomo responsable de las acciones polic\u00edacas y protecci\u00f3n ciudadana, estoy\nseguro de que en poco tiempo ser\u00e1 aplaudido por los millones de habitantes que\nviven o laboran en la Ciudad de M\u00e9xico. La jefa de Gobierno <strong>Claudia Sheinbaum Pardo<\/strong> debe darle todo\nel apoyo y su plena confianza al joven de 37 a\u00f1os de edad y con una\nexperiencia, pese a su corta edad, de mucha val\u00eda en la materia que se le\nencomienda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De ninguna\nmanera se trata de elogiar a <strong>Garc\u00eda\nHarfuch<\/strong>, a quien conozco en fotograf\u00eda y videos, pero estoy de acuerdo con\nmi fraternal colega <strong>Abraham Mohamed<\/strong>,\nquien describe al prometedor funcionario en los siguientes t\u00e9rminos: \u201ctrae en\nsu sangre los genes del patriotismo, del honor, de la honestidad, de la\ndisciplina, del respeto y de servicio al pueblo, que le heredaron su abuelo y\nsu padre\u201d. \u00bfSaben qui\u00e9nes son esos dos personajes? Pues, nada m\u00e1s ni nada\nmenos, que el <strong>general de divisi\u00f3n\nMarcelino Garc\u00eda Barrag\u00e1n <\/strong>y su hijo <strong>Javier\nGarc\u00eda Paniagua<\/strong>, de quienes he de comentar otro d\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un dato\nsentimental y lo comento porque soy su admirador de siempre, la mam\u00e1 de Oscar\nes la actriz <strong>Mar\u00eda Sort\u00e9<\/strong>, Mar\u00eda\nHarfuch Hidalgo para los efectos oficiales.Fue la estrella al lado de<strong> Mario\nMoreno, Cantinflas, <\/strong>en la divertida pel\u00edcula \u201cEl Barrendero\u201d; por supuesto\nque la actriz actu\u00f3 en otras cintas cinematogr\u00e1ficas y en la televisi\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P.D. <\/strong>La semana que termina en este s\u00e1bado\n12 de Octubre, <strong>D\u00eda de la Raza, D\u00eda del\nDescubrimiento de Am\u00e9rica, D\u00eda de la Hispanidad,<\/strong> nos quedar\u00e1 en la memoria\nque cualquier grupo de personas, gremio laboral o ciudadano com\u00fan y corriente,\npuede cerrar la circulaci\u00f3n de veh\u00edculos en la <strong>Ciudad de M\u00e9xico<\/strong>, bloquear calles y avenidas, sin importar el da\u00f1o\ny molestias que se causan a terceros\u2026. <strong>Cuando\nmenos hasta octubre de 20124<\/strong> las autoridades municipales, estatales y\nfederales jam\u00e1s reprimir\u00e1n las manifestaciones callejeras, no interferir\u00e1n en\nlas marchas aunque sea de cinco o diez persona, como tampoco impedir\u00e1n\nbloqueos, excepto en Tabasco donde se aplicar\u00eda la \u201c<strong>Ley Garrote<\/strong>\u201d. En la Ciudad de M\u00e9xico, los taxistas entorpecieron\nlas labores de miles de personas, por espacio de casi 12 horas y do\u00f1a <strong>Claudia Sheinbaum<\/strong> no apareci\u00f3 y el\nproblema se lo turnaron a do\u00f1a <strong>Olga\nS\u00e1nchez Cordero<\/strong>, a quien tambi\u00e9n le encargaron el asunto los de estudiantes\nde una Escuela de Tener\u00eda, Estado de M\u00e9xico, que secuestraron 92 autobuses con\ntodo y los choferes para exigir plazas laborales, becas y un campo de f\u00fatbol &nbsp;y su peticiones fueron atendidas\ninmediatamente, porque as\u00ed lo determinan desde Palacio Nacional. La noche del jueves\npasado se inform\u00f3 que las estudiantes de una escuela poblana actuaron igual que\nlos j\u00f3venes de Tener\u00eda. Queda entendido que se presiona a la autoridad y se\ncumplen los deseos. El ejemplo cunde. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>jherrerav@live.com.mx<\/strong>&nbsp;\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Medalla Belisario Dom\u00ednguez ser\u00e1, para Una Mujer, por Octava Ocasi\u00f3n<\/p>\n","protected":false},"author":3,"featured_media":12855,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[690,94,110],"tags":[],"class_list":["post-12854","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-jorge-herrera-valenzuela","category-la-opinion-columnas"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/12854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=12854"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/12854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/12855"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=12854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=12854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=12854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}