{"id":12280,"date":"2019-09-26T23:04:50","date_gmt":"2019-09-26T23:04:50","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=12280"},"modified":"2023-07-21T15:11:33","modified_gmt":"2023-07-21T20:11:33","slug":"violencia-de-genero-prevencion-de-las-relaciones-de-maltrato","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/violencia-de-genero-prevencion-de-las-relaciones-de-maltrato\/","title":{"rendered":"Violencia de g\u00e9nero, prevenci\u00f3n de las relaciones de maltrato"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>* <\/strong><strong>Hombres que al principio se disfrazan de\nencantadores<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>* Puede ser un \u201cmaltratador azul\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Marisa Babiano<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/Periodistas en Espa\u00f1ol, M\u00e9xico, 26 septiembre 2019.- Hay que\ntener m\u00e1s que cuidado, en vista de lo que sucede con respecto a la violencia de\ng\u00e9nero, es decir el riesgo que supone establecer relaciones de pareja, tener\nhijos\u2026 cuando existe el peligro de que en dicho proceso, se tenga la mala\nsuerte de tropezarse con un maltratador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hombres que al principio se disfrazan de encantadores, en consonancia\ncon la idea de amor rom\u00e1ntico, por ejemplo: que si t\u00fa eres mi reina, que si\ntoma este ramo de rosas, que quiero que seas la madre de mis hijos\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta que un buen d\u00eda, la mujer harta del control y&nbsp;<a href=\"https:\/\/periodistas-es.com\/la-violencia-tiene-genero-133912\">vejaciones\nal que la somete<\/a>&nbsp;ese \u201cmaltratador azul\u201d de\nturno, decide dejarle. Entonces \u00e9ste, puede llegar a provocar una desgracia,\nporque no sabe lo que es querer y no lo quiso aprender, ya que controlar y\nsometer nunca ha sido ni ser\u00e1 amar.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y mientras la cultura y la educaci\u00f3n sigan siendo machistas,\ny&nbsp;normalicen las relaciones de poder-sumisi\u00f3n-dependencia, en vez de\nreciprocidad-respeto-responsabilidad\u2026 \u00a1n\u00e1 de n\u00e1\u2026!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mucus la inteligencia mocarra esputa:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Si lo que quieres es dar y recibir afecto,<br> \u00a1un yorkshire, que es gracioso y correcto!<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sem\/PeE\/mb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hombres que al principio se disfrazan de encantadores<\/p>\n","protected":false},"author":3,"featured_media":12281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[690,53],"tags":[],"class_list":["post-12280","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-internacional"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/12280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=12280"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/12280\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/12281"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=12280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=12280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=12280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}