{"id":12072,"date":"2019-09-21T21:13:56","date_gmt":"2019-09-21T21:13:56","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=12072"},"modified":"2023-07-21T15:09:57","modified_gmt":"2023-07-21T20:09:57","slug":"carta-replica","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/carta-replica\/","title":{"rendered":"Carta r\u00e9plica"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-style-large is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>En cumplimiento a solicitud de derechos de r\u00e9plica.<\/strong><\/p><cite><em>Informaci\u00f3n a referencia:  \u00abViolencia de g\u00e9nero en ambiente acad\u00e9mico por utilizar metodolog\u00eda feminista\u00bb <\/em>(publicada 18 de septiembre 2019) <\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Ciudad de M\u00e9xico. 21 de septiembre 2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(Texto de la carta\/solicitud, se publica \u00edntegra)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Buenas noches:<br>Agradezco la atenci\u00f3n de ustedes al contestar y dar espacio para r\u00e9plica de esta informaci\u00f3n. Dada la importancia de fortalecer los espacios de periodismos feministas, es fundamental que se realicen investigaciones y publicaciones que permitan evidenciar las diversas realidades que nos aquejan a las mujeres.<br>Como lectora habitual de este medio digital, he le\u00eddo ya dos notas respecto a la \u00abviolencia que denuncia una profesora de la UACM\u00bb que efectivamente es acompa\u00f1ada de otra profesora y una ex acad\u00e9mica de la UACM quienes han dado por cierta la informaci\u00f3n difundida por la C. Dom\u00ednguez.<br>Sin embargo, haciendo uso del derecho de r\u00e9plica que ahora nos brindan quiero hacer algunas aclaraciones:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>1. Se hace referencia a que hubo retenci\u00f3n de la profesora y 4 alumnas que le acompa\u00f1an. Esto no ha sido as\u00ed, alumnas y alumnos del Posgrado de Derechos Humanos de la UACM el d\u00eda 28 de agosto realizaron una manifestaci\u00f3n pac\u00edfica en el patio central del plantel del Valle sin que siquiera se acercaran a la profesora quienes se encontraban en la planta alta y dentro de la Coordinaci\u00f3n del Plantel porque as\u00ed lo decidi\u00f3 la propia profesora Dom\u00ednguez. (Existe un informe de un Observatorio de Derechos Humanos que document\u00f3 la manifestaci\u00f3n, material audiovisual y testimonios que as\u00ed lo comprueban y se ponen a su disposici\u00f3n).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>2. El motivo de la manifestaci\u00f3n que se realiz\u00f3 el d\u00eda se\u00f1alado fue la imposici\u00f3n de la profesora por autoridades acad\u00e9micas para que impartiera (como profesora invitada) una materia en el Plantel\u00a0 durante el semestre en curso, no obstante hace m\u00e1s de un a\u00f1o diversas alumnas han denunciado a la profesora por ejercer violencia y discriminaci\u00f3n hacia ellas en sus clases, las referencias constantes a compa\u00f1eras adultas mayores, a formas de vestir, a no \u00abejercer el feminismo\u00bb como ella considera adecuado, agresiones espec\u00edficas hacia alumnas abogadas, fueron motivo para que el Posgrado suspendiera un proceso de adscripci\u00f3n de esta profesora al Plantel. Cabe aclarar que los derechos laborales de la profesora no se han menoscabado en tanto ella se encuentra adscrita y con carga acad\u00e9mica en otro plantel de la UACM denominado \u00abCuautepec\u00bb. (Existen una serie de testimonios que incluso han sido presentados a la Encargada de Despacho de la Oficina General del Abogado, al Coordinador Acad\u00e9mico, Coordinadora de Colegio, Coordinadora del Plantel mismos que se encuentran en estado de an\u00e1lisis para determinar las acciones de protecci\u00f3n solicitadas por las alumnas. Respecto a la adscripci\u00f3n de la profesora, \u00e9sta puede consultarse en la p\u00e1gina de internet de la propia universidad).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>3. Debido a que las alumnas de manera valiente decidieron denunciar el maltrato de esta profesora, y dado el comportamiento agresivo del que han dado testimonio escrito y oral, las denuncias en falso carentes de pruebas contra otros profesores del posgrado, la violencia digital en contra de otra profesora del Posgrado, las alumnas temen por su integridad ya que la profesora cuenta con el respaldo institucional del que carecen las alumnas quienes temen por su seguridad jur\u00eddica, de ah\u00ed que la manifestaci\u00f3n se realizara para solicitar medidas de protecci\u00f3n a las autoridades universitarias por posibles actos en contra de ellas tal como pudieran ser arrestos arbitrarios -cabe se\u00f1alar que la profesora ha solicitado contar con polic\u00edas dentro de la universidad y en la entrada de la misma, raz\u00f3n por la cual el arresto proceder\u00eda de manera inmediata sin que se realizara investigaci\u00f3n previa a los dichos de la profesora-.<br>4. Desde la suspensi\u00f3n de ad<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">scripci\u00f3n de la profesora, se ha dedicado a denigrar, denostar y a generar un clima de odio hacia profesores y profesoras argumentando que se trata de un tema de g\u00e9nero, si bien se ha demostrado que esto no es procedente en tanto no existe tal discriminaci\u00f3n por las perspectivas que utiliza la profesora en sus clases, las alumnas que han sido violentadas por ella en clase ahora se ven en la misma situaci\u00f3n que las profesoras y profesores del Posgrado de Derechos Humanos quienes ahora encuentran comunicados como el que difunde su medio y otros, cabe aclarar que no todos han respondido como generosamente lo hacen ustedes, el desgaste en las alumnas ante tal descr\u00e9dito es evidente, una de ellas decidi\u00f3 no continuar sus estudios temerosa de las represalias por haber denunciado ante el Enlace del Posgrado el maltrato de la profesora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>5. Dado el comportamiento de la profesora contra las alumnas, la falta de respuesta institucional y ante la carencia de grupos feministas que apoyen a las compa\u00f1eras en tanto ellas no pertenecen a ninguna red, sino que son estudiantes que si bien se reivindican como feministas no son militantes, ellas se encuentran hoy d\u00eda en un estado de indefensi\u00f3n y riesgo ya que al no contar con la protecci\u00f3n a la integridad que las autoridades universitarias est\u00e1n obligadas a garantizar conforme al art\u00edculo 1o de la Constituci\u00f3n Pol\u00edtica de los Estados Unidos Mexicanos y 5, 6 B, 11C y dem\u00e1s aplicables de la Constituci\u00f3n Pol\u00edtica de la Ciudad de M\u00e9xico y la Ley de Acceso de la Ciudad de M\u00e9xico para el acceso a las mujeres a una vida libre de violencia y ante la difusi\u00f3n masiva de comunicados como el que referimos y por el cual solicitamos el derecho de r\u00e9plica, consideramos se hace necesario no s\u00f3lo otorgar espacios para la r\u00e9plica, sino realizar investigaciones que permitan evidenciar y visibilizar las diversas caras que una historia puede presentar, tal como es este caso.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>6. Tanto las alumnas violentadas, como el resto del grupo de estudiantes han se\u00f1alado en reiteradas ocasiones que no tienen problema alguno con las compa\u00f1eras que acompa\u00f1an a la profesora, incluso mantienen comunicaci\u00f3n con ellas, y coinciden con ellas de tal manera que como estudiantes de un Posgrado de Promoci\u00f3n y Defensa de Derechos Humanos han realizado pronunciamientos sobre la necesidad de implementar mecanismos para detectar y atender la violencia contra las mujeres en el \u00e1mbito escolar, sin embargo esta debe ser atendida con independencia del sexo\/g\u00e9nero de la persona agresora, no obstante debido al sexo de quien las ha agredido, este caso complica mucho m\u00e1s para las alumnas el que las autoridades universitarias crean en su dicho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>7. Las alumnas violentadas han acudido ante autoridades universitarias y se encuentran a la espera de una respuesta institucional que garantice un espacio libre de violencia, protecci\u00f3n a su integridad, seguridad jur\u00eddica y a su dignidad, por tal motivo hasta hoy ellas no han acudido a otras instancias y espacios para denunciar en tanto consideran que primero deben agotarse los espacios universitarios e institucionales y solamente pedimos derecho de r\u00e9plica a efecto de mostrar otra versi\u00f3n que confronte las comunicaciones que atentan contra su integridad personal y que pudiera afectar otros derechos humanos tales como: educaci\u00f3n, prestigio, acceso a la justicia.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Por lo anterior, y en aras de favorecer un periodismo incluyente y plural, atendiendo a un principio de justicia feminista de creer sin prejuzgar en el dicho de las v\u00edctimas para escuchar sus testimonios invitamos a periodistas de su redacci\u00f3n a visitar el plantel y escuchar de viva voz a las alumnas e incluso a la profesora v\u00edctima de violencia digital y mostrar pruebas respecto a lo que en esta r\u00e9plica ahora formulo a efecto de documentar casos de violencia contra mujeres en el \u00e1mbito acad\u00e9mico.\u00a0<br>Aclaro que esta informaci\u00f3n la proporciono como abogada feminista que ha acompa\u00f1ado pro bono a las alumnas en el proceso de salvaguardar su integridad, y a un profesor a qui\u00e9n la C. Dom\u00ednguez ha denunciado sin presentar una sola prueba de su dicho, motivo por el cual se han presentado las quejas respectivas ante \u00f3rganos no jurisdiccionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En caso que decidan atender a esta invitaci\u00f3n, les pido me lo hagan saber por esta v\u00eda o al n\u00famero que dejo en este correo. Por el momento solicitamos la publicaci\u00f3n de esta r\u00e9plica y tomamos la decisi\u00f3n de mantener el anonimato de las alumnas a efecto de salvaguardar su seguridad jur\u00eddica y proteger sus datos personales, no obstante, tal como ya lo hicieron con otros medios que s\u00ed las escucharon, podr\u00e1n platicar con ellas y ya determinar\u00e1n dar a conocer o no sus identidades a las periodistas que acudan.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quedo a la espera de su amable respuesta, y reitero mi reconocimiento por el respeto a un derecho fundamental de las audiencias y por dar voz a todas las mujeres.<br>Saludos<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Elena Espinosa Morales<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Abogada feminista<\/em> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>En cumplimiento a solicitud de derechos de r\u00e9plica. Informaci\u00f3n a referencia: \u00abViolencia de g\u00e9nero en ambiente acad\u00e9mico por utilizar metodolog\u00eda feminista\u00bb (publicada 18 de septiembre 2019) Ciudad de M\u00e9xico. 21 de septiembre 2019. (Texto de la carta\/solicitud, se publica \u00edntegra) Buenas noches:Agradezco la atenci\u00f3n de ustedes al contestar y dar espacio para r\u00e9plica de esta [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12073,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,54],"tags":[],"class_list":["post-12072","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-mujeres"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/12072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=12072"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/12072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/12073"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=12072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=12072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=12072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}