{"id":11941,"date":"2019-09-18T22:02:25","date_gmt":"2019-09-18T22:02:25","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=11941"},"modified":"2023-07-21T15:10:00","modified_gmt":"2023-07-21T20:10:00","slug":"guerrero-38","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/guerrero-38\/","title":{"rendered":"Solicitan comparecencia del secretario de Salud en Guerrero por abuso sexual en contra de mujer embarazada en unidad de parter\u00eda"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Josefina Aguilar Pastor&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Chilpancingo Guerrero, 18 de septiembre de 2019.- Activistas feministas, solicitaran al Congreso del Estado, llame a comparecer al Secretario de Salud, Carlos de la Pe\u00f1a Pintos, y a la titular de la Secretar\u00eda de la Mujer (Semujer), Maira Gloribel Mart\u00ednez Pineda, respecto del abuso sexual contra de una mujer embarazada en la unidad de parter\u00eda de Chilpancingo, califican como grave que traten de minimizar este hecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viridiana Guti\u00e9rrez Sotelo, integrante del\u00a0Observatorio Ciudadano de Violencia hacia las Mujeres en Guerrero (Obvio-Guerrero), dio a conocer que este jueves, acudir\u00e1n al Congreso del Estado, a solicitar por escrito, que de la Pe\u00f1a Pintos y Mart\u00ednez Pineda sean llamados a explicar el caso de la mujer embarazada, las acciones que han emprendido no solo para resarcir el da\u00f1o, sino para que un hecho similar no vuelva a ocurrir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata recalc\u00f3, de un hecho muy grave, en el que el Secretario de Salud, no puede justificarse bajo el argumento que el delito fue cometido por alguien que prestaba un servicio subrogado. Record\u00f3 que el dictamen de Alerta de Violencia de Genero (AVG), emitida en 2017 para el Estado de Guerrero, se\u00f1ala que el Gobierno tiene la obligaci\u00f3n de difundir los alcances de la alerta, por lo que todos y todas en Guerrero, deber\u00edan a estas alturas saber sobre el tema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cY alguien que trabaja para el Estado directa o directamente tendr\u00eda que saber lo que constituye violar solamente los derechos de una instituci\u00f3n p\u00fablica, pero materializar la violaci\u00f3n sexual como sucedi\u00f3 en la cl\u00ednica de Chilpancingo, tiene mayores alcances\u201d, subray\u00f3 Guti\u00e9rrez Sotelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las mujeres, no solo deben cuidarse de la violencia familiar en casa, en la calle de la violencia generalizada, ahora tambi\u00e9n en las instituciones donde se entrega la confianza y son mucho m\u00e1s vulnerables por la desnudez del cuerpo, y cualquiera puede aprovechar esta vulnerabilidad, acus\u00f3 la activista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este caso, el Estado deber\u00eda aceptar que, si es su responsabilidad, \u201cporque fue dentro de su instituci\u00f3n, con una empresa que ellos contrataron\u201d, diferente habr\u00eda sido, si fuera un hombre que se hubiese metido a la fuerza, amagado con una pistola, eso no habr\u00eda sido su responsabilidad, pero aqu\u00ed, es un tipo que conoc\u00edan, al que el Estado le abri\u00f3 la puerta bajo un contrato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fustig\u00f3 que la Secretar\u00eda de Salud, ni siquiera ha dado a conocer la cancelaci\u00f3n del contrato del supuesto agresor, o de la empresa, como lo ha declarado de la Pe\u00f1a Pintos, y tendr\u00edan que hacerlo p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De la declaraci\u00f3n hecha por el Secretario de Salud, de que no fincar\u00e1n alguna responsabilidad por este hecho a ning\u00fan funcionario de la dependencia, Guti\u00e9rrez Sotelo se\u00f1al\u00f3 que es una muestra del valor que para el funcionario tienen los derechos de las mujeres, tambi\u00e9n lament\u00f3 que no haya un solo pronunciamiento a favor de la justicia para este caso, como lo ha habido en otros, como el del asesinato de un fot\u00f3grafo que trabajaba en una empresa extranjera internacional, que s\u00ed mereci\u00f3 la atenci\u00f3n del Estado, de la Fiscal\u00eda General del Estado (FGE), y de otros actores pol\u00edticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No ha habido ni una sola reacci\u00f3n de ning\u00fan funcionario, funcionaria, legislador o legisladora, de nadie que haya hecho replica a la petici\u00f3n de justicia, ni siquiera de la propia Secretaria de la Mujer, Maira Mart\u00ednez P\u00edneda, quien el d\u00eda de los hechos acudi\u00f3 al lugar, y su silencio se presta a muchas especulaciones, hasta incluso, que lleg\u00f3 para acallar la denuncia de la v\u00edctima,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La representante de obvio- Guerrero, precis\u00f3 que la petici\u00f3n hacia el Legislativo, va tambi\u00e9n en funci\u00f3n de todas las omisiones que ambos funcionarios \u2013Secretario de Salud y Secretaria de la Mujer-, han cometido para cumplir con las obligaciones que el Estado tiene con los derechos de las mujeres.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Secretario de Salud, no puede justificarse bajo el argumento que el delito fue cometido por alguien que prestaba un servicio subrogado. <\/p>\n","protected":false},"author":3,"featured_media":11942,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,54],"tags":[],"class_list":["post-11941","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-mujeres"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/11941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=11941"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/11941\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/11942"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=11941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=11941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=11941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}