{"id":11496,"date":"2019-09-02T21:00:34","date_gmt":"2019-09-02T21:00:34","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=11496"},"modified":"2023-07-21T14:53:35","modified_gmt":"2023-07-21T19:53:35","slug":"oaxaca-38","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/oaxaca-38\/","title":{"rendered":"Siguen feminicidios en Oaxaca"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Ocurre\nen Pinotepa Nacional, uno de los 40 municipios con AVG<\/strong><\/li><li><strong>El\nasesinato ocurre en la Costa<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Patricia\nBrise\u00f1o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Oaxaca, 2 septiembre 2019.- El cuerpo sin\nvida de una mujer fue localizado ayer domingo en el paraje Motillas, en el\nmunicipio de Pinotepa Nacional, en la regi\u00f3n de la Costa, uno de los 40\nmunicipios de la entidad con Alerta de Violencia de G\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan los primeros datos, la v\u00edctima presentaba\nheridas profundas en el cuello, al parecer provocadas con arma blanca, que le\nhabr\u00eda provocado la muerte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Vicefiscal\u00eda en la regi\u00f3n de la Costa acudi\u00f3 al\nsitio del hallazgo donde orden\u00f3 el levantamiento del cuerpo y trasladarlo al\nanfiteatro de Pinotepa Nacional, donde permanece en calidad de desconocida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio P\u00fablico abri\u00f3 la carpeta de\ninvestigaci\u00f3n correspondiente por el delito de feminicidio, por las condiciones\nen las que se localiz\u00f3 a la v\u00edctima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pasado viernes se cumpli\u00f3 un a\u00f1o de la\ndeclaratoria de la Alerta por Violencia de G\u00e9nero (AVG) contra las mujeres en\n40 municipios de Oaxaca, las organizaciones feministas y defensoras de los\nderechos humanos en esa fecha se pronunciaron por lo que consideraron el\nincumplimiento oficial en materia de justicia que deja un saldo ominoso de 126\nmujeres y ni\u00f1as oaxaque\u00f1as asesinadas, \u00aba quienes les negaron el derecho\nde vivir, a la libertad y la seguridad\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las organizaciones civiles consideran que las\ndependencias encargadas de la prevenci\u00f3n, atenci\u00f3n, sanci\u00f3n y erradicaci\u00f3n de\neste delito han sido omisas, dando paso a la impunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para rememorar las vidas apagadas por los\nfeminicidios, registrados en este \u00faltimo a\u00f1o &#8211;del 30 de agosto de 2018 a la\nfecha- la organizaci\u00f3n Taller de Teatro Casa las M\u00e1scaras instal\u00f3 126 m\u00e1scaras\nelaboradas manualmente con cera, madera y cart\u00f3n, sugiriendo el rostro de las\nmujeres fallecidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/pb\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ocurre en Pinotepa Nacional, uno de los 40 municipios con AVG<\/p>\n","protected":false},"author":3,"featured_media":11497,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,47,48],"tags":[],"class_list":["post-11496","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-no-mas-impunidad","category-no-mas-impunidad-no-mas-impunidad"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/11496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=11496"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/11496\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/11497"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=11496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=11496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=11496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}