{"id":11471,"date":"2019-09-02T19:47:10","date_gmt":"2019-09-02T19:47:10","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=11471"},"modified":"2023-07-21T14:53:35","modified_gmt":"2023-07-21T19:53:35","slug":"oaxaca-37","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/oaxaca-37\/","title":{"rendered":"Oaxaca, estado con el peor nivel de procuraci\u00f3n de justicia en violencia contra las mujeres: Patricia Olamendi"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Rodrigo Islas Brito<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/ Tres Grados News. Oaxaca. Oax. 02 de septiembre\n2019.- La abogada y doctora en derecho Patricia Olamendi Torres se\u00f1ala rauda\nque el poder judicial del&nbsp; estado de\nOaxaca y el aparato legal procurador de justicia que lo rodea es el peor en\ncuanto a hacer valer los derechos humanos de las mujeres en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTodav\u00eda tiene un modelo no acorde con los derechos humanos\naprobados en materia de derechos humanos de las mujeres. No ha transformado\nprocedimientos para efectos de juzgar con perspectiva de g\u00e9nero\u201d, apunta la\nintegrante del grupo de trabajo del Consejo de Derechos Humanos de la ONU,\nsobre los temas de discriminaci\u00f3n en la ley hacia las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe tiene jueces y criterios muy antiguos. Llama\npoderosamente la atenci\u00f3n de que en Oaxaca tampoco se hayan promovido cambios\nen el orden familiar, pues estos siguen siendo procedimientos del orden civil.\nEso preocupa porque al final de cuentas las mujeres se quedan sin acceso a la\njusticia\u201d, resalta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de su m\u00e1s reciente visita a la ciudad de Oaxaca,\nluego de haber dictado la pl\u00e1tica: \u201cDerechos sexuales y reproductivos de las\nmujeres en M\u00e9xico. Mitos y desaf\u00edos\u201d, la abogada feminista juzga en entrevista\nque en la accesibilidad de las mujeres oaxaque\u00f1as a la justicia deber\u00eda de\nhaber cambios y se deber\u00edan buscar reformas para generar nuevos juzgados\nespecializados en materia de violencia contra las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apunta que en Oaxaca como en el resto del pa\u00eds en lo respectivo a la violencia contra las mujeres no ha disminuido sino que \u00e9sta solo se hace m\u00e1s grande. Se le pregunta si su precepto de que hoy la ley en Oaxaca no protege a las mujeres, es realmente tan extremo en la pr\u00e1ctica. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSi lo es. No tener un c\u00f3digo familiar, estar por un c\u00f3digo\nde procedimientos. Con un c\u00f3digo penal que no est\u00e1 actualizado. La mujer en\nOaxaca no est\u00e1 protegida. Al final de cuentas como mujer \u00bfd\u00f3nde te amparas? En\nOaxaca, procedimiento administrativos es un campo casi inexistente para los\ntemas de la violencia contra la mujer\u201d, analiza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con una Alerta de Genero que ya va por su a\u00f1o un mes de\nhaber sido emitida en el estado de Oaxaca, la autora de libros sobre las leyes\ndiscriminatorias como \u201cDelitos contra las Mujeres\u201d, \u201cMujeres, familias y\nciudadan\u00eda\u201d y \u201cFeminicidio en M\u00e9xico\u201d y&nbsp;\nel \u201cProtocolo para la Investigaci\u00f3n del Delito de Violaci\u00f3n\u201d, observa\nque de los 517 municipios oaxaque\u00f1os tampoco hay acciones para poder sancionar\no prevenir la violencia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCon lo que tienes un aparato burocr\u00e1tico poco eficiente\npara las nuevas realidades. Es tiempo de cambiarlo. El resto del pa\u00eds tambi\u00e9n\nest\u00e1 en la misma situaci\u00f3n, pero Oaxaca tiene una particularidad que tiene que\natenderse, una composici\u00f3n de poblaci\u00f3n ind\u00edgena, sobre todo mujeres, que\nsiguen bajo el yugo de los usos y costumbres (tambi\u00e9n conocidos como Sistemas\nNormativos Internos)\u201d, declara la abogada quien form\u00f3 parte de la terna final\nde mujeres propuestas para encabezar el Instituto Nacional de las Mujeres en\nactual gobierno federal de Andr\u00e9s Manuel L\u00f3pez Obrador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cY a esas mujeres las estas dejando todav\u00eda m\u00e1s\ndesprotegidas cuando es la comunidad que ha mantenido esas costumbres de opresi\u00f3n\nla que sigue decidiendo por ellas. Oaxaca tiene una urgencia&nbsp; en ese sentido\u201d, considera Olamendi quien\nafirma como jurista no estar tan de acuerdo con legislaci\u00f3n sobre usos y\ncostumbres que en Oaxaca comprende a 418 municipios que eligen a sus autoridades\npor asamblea comunitaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201dSiguen tocando los temas de la mujer desde la perspectiva\nde la costumbre.&nbsp; Y si algo nos ha\nafectado precisamente a las mujeres en este pa\u00eds es ese tipo de pr\u00e1ctica, el\nque las costumbres se mantengan\u201d, apunta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se le comenta a Olamendi, quien gener\u00f3 el protocolo para la\ninvestigaci\u00f3n del feminicidio que se ha propuesto como gu\u00eda de investigaci\u00f3n\npara Am\u00e9rica Latina, que los usos y costumbres parecen formar parte de la\nconcepci\u00f3n de un entorno sagrado para las comunidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo lo es, la Constituci\u00f3n es para todos y los derechos\nhumanos tambi\u00e9n\u201d, responde. Se le comenta al respecto que otro concepto que\npermea esta forma de gobierno es la consecuci\u00f3n de una autonom\u00eda<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl pa\u00eds se rige por la Constituci\u00f3n general de la Rep\u00fablica\ny los tratados internacionales en materia de derechos humanos. No se pueden\ntener espacios de excepci\u00f3n y menos cuando se habla de derechos humanos\u201d,\ninsiste Olamendi, quien para la primera semana de septiembre est\u00e1 convocando\njunto con legisladoras a un encuentro nacional de diputadas federales y locales\ncon organizaciones de la sociedad civil para discutir temas relativos a\npresupuestos y pol\u00edticas p\u00fablicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De la marcha del pasado 16 de agosto donde miles de mujeres\nsalieron a las calles para protestar contra la invisibilidad con la que se\ntrata por parte de las autoridades la violencia contra la mujer en un pa\u00eds de\nfeminicidios en escala sostenida, Olamendi desea que \u201cojala y vengan m\u00e1s\nmarchas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De comentarios sobre que pintar y destruir propiedad p\u00fablica\nno son las formas para protestar sobre nada que han apoyado incluso el\npresidente Andr\u00e9s Manuel L\u00f3pez Obrador (quien en su informe de gobierno de este\ndomingo no mencion\u00f3 en lo absoluto lo referente a los asesinatos sistem\u00e1ticos\nde mujeres en el pa\u00eds) y su esposa Beatriz Rodr\u00edguez M\u00fcller quien segura\ndeclar\u00f3 en un foro p\u00fablico hace unos d\u00edas que en M\u00e9xico \u201cse puede protestar,\npero no rayar el patrimonio\u201d, Olamendi no se muestra de acuerdo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsperan que las mujeres tengamos un comportamiento\nestereotipado. \u00bfQu\u00e9?, \u00edbamos a salir en tacones a desfilar. A decir disc\u00falpenos\npero nos est\u00e1n matando en las calles. Hay hartazgo, molestia, falta de\nrespuesta. Mejor que las autoridades atiendan los se\u00f1alamientos y se pongan a\nhacer su trabajo\u201d, abunda la abogada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dice que espec\u00edficamente el gobierno de la Ciudad de M\u00e9xico\napenas est\u00e1 empezando a reaccionar sobre el tema, despu\u00e9s de llamar provocaci\u00f3n\na las protestas de mujeres sobre dejar libres a cuatro polic\u00edas capitalinos\nacusados de violaci\u00f3n y encima informar que volver\u00edan a sus cargos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cOjala y la reacci\u00f3n sea positiva. Eso esperamos. Eso\nqueremos, Claudia Sheinbaum (jefa de gobierno) dijo que un mes anunciar\u00eda todo\nel programa al respecto. Al final todo lo provoc\u00f3 la autoridad. Ellos dieron a\nconocer el nombre de la chica. Hay violencia y falta de cuidado con lo que la\nley decide, desde cuestiones como el que no puedes filtrar los datos de una\nmujer que acusa haber sido v\u00edctima de una violaci\u00f3n y m\u00e1s cuando los\ninvolucrados son polic\u00edas. Imag\u00ednate, si de por s\u00ed ya debemos cuidarnos del\ncrimen organizado, \u00bfahora de los polic\u00edas? es grav\u00edsimo\u201d, considera Patricia\nOlamendi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apunta que la citada protesta va a tener que seguir porque\nla problem\u00e1tica no se ha resuelto. \u201cVan a tener que haber m\u00e1s marchas y m\u00e1s\nmovimiento que ponga en evidencia a la impunidad. Este es el momento en M\u00e9xico\nde la defensa de los derechos de las mujeres\u201d, define la entrevistada sin\ndudarlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe le comenta que hay gente que dice que hoy le va m\u00e1s a\nlas feministas que al Estado. \u201cCreo que s\u00ed, hemos he sido m\u00e1s eficientes. Por\nlo menos hemos cambiado en buena medida las leyes del pa\u00eds y del mundo\u201d,&nbsp; finaliza Patricia Olamendi Torres, actual\npresidenta del Instituto de Formaci\u00f3n en Justicia y Derechos Humanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mujer en Oaxaca no est\u00e1 protegida. Al final de cuentas como mujer \u00bfd\u00f3nde te amparas? , se\u00f1ala<\/p>\n","protected":false},"author":3,"featured_media":11472,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[690,56],"tags":[],"class_list":["post-11471","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-redes"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/11471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=11471"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/11471\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/11472"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=11471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=11471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=11471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}