{"id":11307,"date":"2019-08-27T00:49:49","date_gmt":"2019-08-27T00:49:49","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=11307"},"modified":"2023-07-21T14:52:56","modified_gmt":"2023-07-21T19:52:56","slug":"cuba-7","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/cuba-7\/","title":{"rendered":"Cuba: La historia est\u00e1 en deuda con las mujeres negras"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Celebran 59 a\u00f1os de la Federaci\u00f3n de Mujeres Cubanas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mar\u00eda D\u00e1masa Jova, primera afrocubana propietaria de una imprenta en la isla<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/SEMlac,\nLa Habana, 26 agosto 2019.- Llenar los vac\u00edos que la historiograf\u00eda y narrativa\nhist\u00f3rica tiene a\u00fan respecto al papel de las&nbsp;<a href=\"http:\/\/www.redsemlac-cuba.net\/sociedad-cultura\/red-de-mujeres-afrodescendientes-marca-pautas-para-2019.html\" target=\"_blank\" rel=\"noreferrer noopener\">mujeres negras<\/a>&nbsp;en las luchas de las\ncubanas por sus derechos, as\u00ed como en la forja de la identidad y la naci\u00f3n, es\nuna deuda a saldar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ello coincidieron activistas e intelectuales durante un encuentro del proyecto cultural <a rel=\"noreferrer noopener\" href=\"http:\/\/www.afrocubaweb.com\/club-espendru.html\" target=\"_blank\">El Club del Espendr\u00fa<\/a>, en el cual se record\u00f3 la fundaci\u00f3n hace 59 a\u00f1os de la Federaci\u00f3n de Mujeres Cubanas y se disert\u00f3 sobre una destacada intelectual negra: la maestra\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/directoriodeafrocubanas.com\/2018\/05\/27\/damasa-jova\/\" target=\"_blank\">Mar\u00eda D\u00e1masa Jova (1890-1940)<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el investigador <a rel=\"noreferrer noopener\" href=\"http:\/\/www.afrocubaweb.com\/tomasfr-cv.htm\" target=\"_blank\">Tom\u00e1s Fern\u00e1ndez Robaina<\/a>, \u00abrecordar a una de las figuras m\u00e1s significativas del pensamiento\u00a0<a rel=\"noreferrer noopener\" href=\"http:\/\/www.redsemlac-cuba.net\/sociedad-cultura\/rutas-para-estudiar-racialidad-y-racismo.html\" target=\"_blank\">antirracista<\/a>\u00a0cubano, que al igual que otras mujeres y hombres luch\u00f3 por una Cuba equitativa donde se respete la diferencia y la diversidad\u00bb, es un peque\u00f1o aporte en el empe\u00f1o de visibilizar el legado de la poblaci\u00f3n afrodescendiente.<br> <br> <strong>Intelectual, negra y feminista<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aracely Rodr\u00edguez, quien investig\u00f3 para su Tesis de Maestr\u00eda la vida de la insigne pedagoga Mar\u00eda D\u00e1masa Jova, destac\u00f3 la trascendencia de esta mujer, nacida en la antigua provincia de Las Villas, en el centro del pa\u00eds. \u00abCon su intelecto cre\u00f3 espacios de formaci\u00f3n de conciencias colectivas y sociales, traspasando los muros del saber y del poder establecidos por la <a rel=\"noreferrer noopener\" href=\"http:\/\/www.redsemlac-cuba.net\/sociedad-cultura\/racismo-desde-el-silencio-no-se-puede-construir-consenso-,-asegura-investigadora1.html\" target=\"_blank\">colonialidad<\/a>\u00ab, dijo la investigadora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con la activista, aunque la vida de D\u00e1masa Jova estuvo marcada por el magisterio, sobresali\u00f3 adem\u00e1s como poeta, escritora, periodista, feminista e incluso en la vida pol\u00edtica. \u00abInstituy\u00f3 nuevas metodolog\u00edas para que maestras y maestros tuvieran herramientas y lograran protagonismo en sus aulas, una ense\u00f1anza m\u00e1s din\u00e1mica y postmodernista\u00bb, explic\u00f3 Rodr\u00edguez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue la primera mujer afrocubana propietaria de una imprenta en la isla, la que compr\u00f3 con su salario para editar las revistas Ninfas y Umbrales, de las cuales ser\u00eda fundadora y directora art\u00edstica, literaria y t\u00e9cnica. \u00abPero tambi\u00e9n para ense\u00f1ar litograf\u00eda a ni\u00f1os y ni\u00f1as que no pod\u00edan continuar sus estudios, llegando a formar a m\u00e1s de 200 en este oficio\u00bb, refiri\u00f3 la especialista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abHablamos de una mujer negra que escribi\u00f3 &#8216;Arpegios \u00edntimos&#8217;, texto que mereci\u00f3 varios premios en su \u00e9poca; de una mujer negra que ten\u00eda un espacio fijo en el liceo de Santa Clara, donde tocaba viol\u00edn, recitaba poes\u00edas y recaudaba dinero que devolv\u00eda en acciones para los ni\u00f1os desamparados. Estamos frente a una mujer que logr\u00f3 hacerse respetar en un espacio que estaba destinado para determinada clase y color. Una mujer intelectual que, aunque se codeaba con la alta sociedad, ten\u00eda conciencia con la gente de su raza, lo cual se observa en su poes\u00eda, con un pensamiento feminista en torno a las problem\u00e1ticas de la mujer y el hombre negros\u00bb, sostuvo Rodr\u00edguez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan mencion\u00f3 la investigadora, D\u00e1masa Jova fue la primera mujer negra que al participar en el <a rel=\"noreferrer noopener\" href=\"http:\/\/www.redsemlac-cuba.net\/comunicacion\/documental-rescata-luchas-feministas.html\" target=\"_blank\">Congreso Nacional Femenino de 1939<\/a>, en La Habana, expres\u00f3 sus preocupaciones sobre la marginaci\u00f3n de las mujeres afrocubanas, y su discurso fue fundacional en la construcci\u00f3n y el desarrollo de un pensamiento feminista negro cubano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> En ese mismo a\u00f1o se uni\u00f3 al partido Conjunto Nacional Democr\u00e1tico y fue elegida como la candidata regional para el Congreso de la Rep\u00fablica; sin embargo, la junta electoral provincial desautoriz\u00f3 su candidatura. Fue propuesta como representante de las mujeres en la Constituyente de 1940, junto a las destacadas feministas Elma P\u00e9rez y Ofelia Navarro Dom\u00ednguez, pero la muerte la sorprendi\u00f3 en los primeros d\u00edas de enero de ese a\u00f1o.<br> <br> <strong>Rescatar una parte \u00abinvisible\u00bb de la historia<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" href=\"https:\/\/directoriodeafrocubanas.com\/2016\/01\/20\/yulexis-almeida-junco\/\" target=\"_blank\">Yulexis Almeida<\/a>, investigadora e integrante del colectivo Afrocubanas, llam\u00f3 la atenci\u00f3n sobre la necesidad de comenzar a compilar y publicar textos como el de la investigaci\u00f3n de Rodr\u00edguez sobre D\u00e1masa, que ha logrado reunir tanta informaci\u00f3n dispersa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Ello contribuir\u00eda a sacar a la luz la obra de muchas mujeres negras y su contribuci\u00f3n al legado cultural de la naci\u00f3n, dijo la especialista durante el encuentro, realizado en la biblioteca Rub\u00e9n Mart\u00ednez Villena, ubicada en el municipio capitalino Habana Vieja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para la periodista y activista <a rel=\"noreferrer noopener\" href=\"https:\/\/directoriodeafrocubanas.com\/2016\/03\/02\/gisela-arandia-covarrubias\/\" target=\"_blank\">Gisela Arandia<\/a>, la investigaci\u00f3n sobre D\u00e1masa Jova va m\u00e1s all\u00e1 de rescatar una historia olvidada, al visibilizar el papel de las maestras, un rol donde las mujeres negras se involucraron hist\u00f3ricamente y que sigue siendo una tarea pendiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A juicio del escritor <a rel=\"noreferrer noopener\" href=\"http:\/\/www.afrocubaweb.com\/robertozurbano.htm\" target=\"_blank\">Roberto Zurbano<\/a>, \u00abreescribir la historia puede ser un ejercicio acad\u00e9mico, familiar, de la memoria; pero es tambi\u00e9n un ejercicio pol\u00edtico y filos\u00f3fico importante. Con este trabajo se reescriben dos o tres formas de historia: la de la mujer negra en Cuba, la historia intelectual que ha excluido a muchas de estas personas, y la historia de la educaci\u00f3n en el pa\u00eds, a menudo concebida desde una visi\u00f3n dogm\u00e1tica, donde la raza no pod\u00eda estar ni en el centro ni en los bordes, sencillamente no estaba. Todas necesitan ser suficientemente visibles\u00bb, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En opini\u00f3n de la investigadora Aracelys Rodr\u00edguez, son elementos que tributan a la agenda de las mujeres en Cuba hoy, que pasa por asumir que existe un feminismo negro, diferente. \u00abNo porque nosotras seamos distintas, sino porque venimos con un <a rel=\"noreferrer noopener\" href=\"http:\/\/www.redsemlac-cuba.net\/sociedad-cultura\/racismo-lo-que-no-se-nombra-no-existe.html\" target=\"_blank\">pasado hist\u00f3rico<\/a>\u00a0y eso hay que reflejarlo en la agenda para que todas y todos podamos decir ma\u00f1ana que tenemos un feminismo integrado, \u00fanico; en el cual est\u00e9n las mujeres negras y su pensamiento, que tanto han aportado y el cual muchas veces queda a la sombra\u00bb, concluy\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM-SEMlac<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mar\u00eda D\u00e1masa Jova, primera afrocubana propietaria de una imprenta en la isla<\/p>\n","protected":false},"author":3,"featured_media":11308,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,53],"tags":[],"class_list":["post-11307","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-internacional"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/11307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=11307"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/11307\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/11308"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=11307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=11307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=11307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}