{"id":10813,"date":"2019-08-15T00:55:32","date_gmt":"2019-08-15T00:55:32","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=10813"},"modified":"2023-07-21T14:52:28","modified_gmt":"2023-07-21T19:52:28","slug":"cdmx-5","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/cdmx-5\/","title":{"rendered":"Instala Gobierno de la CDMX mesa de di\u00e1logo con organizaciones de la sociedad civil"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Llama Sheinbaum a un acuerdo para avanzar hacia una\nciudad que erradique la violencia de g\u00e9nero<\/strong><\/li><li><strong>No se criminalizar\u00e1 la protesta social pero tampoco se\npermitir\u00e1 la violencia: Godoy Ramos<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 14 de agosto de 2019.- En el\nDi\u00e1logo \u00abCero impunidad y justicia absoluta para las mujeres y ni\u00f1as\nv\u00edctimas de violencia\u201d, funcionarias y legisladoras federales y locales dieron\nsu respaldo a la jefa de Gobierno de la Ciudad de M\u00e9xico, Claudia Sheinbaum\nPardo, por las acciones que su administraci\u00f3n ha emprendido contra la violencia\nhacia las mujeres, en tanto que integrantes de organizaciones feministas\nadvirtieron que continuar\u00e1n con sus demandas y exigencias. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sheinbaum indic\u00f3 que esta mesa de trabajo es un acuerdo\npara avanzar hacia una ciudad que erradique la violencia de g\u00e9nero. Por su\nparte, la secretaria de las Mujeres, Gabriela Rodr\u00edguez, se pronunci\u00f3 por cero\nimpunidad y una justicia absoluta para las mujeres, en tanto que la procuradora\nde Justicia de la CDMX, Ernestina Godoy Ramos, reiter\u00f3 que no se criminalizar\u00e1\nla protesta social pero no se permitir\u00e1 la impunidad ni la \u201cviolencia que se\ninfiltra entra nosotras\u201d. Si queremos un trato justo \u201cv\u00e1monos respetando y\nvamos respetando todos los derechos de las mujeres\u201d, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre las actividades que se han llevado a cabo,\nSheinbaum y Rodr\u00edguez mencionaron la creaci\u00f3n de la Secretar\u00eda de las Mujeres\n(Semujeres), el Gabinete de G\u00e9nero, la capacitaci\u00f3n con perspectiva de g\u00e9nero a\nministerios p\u00fablicos, la Red de Mujeres, los 27 centros de atenci\u00f3n (Lunas),\nlos centros de justicia de la procuradur\u00eda local, los recursos para refugios de\norganizaciones y el uniforme neutro en las escuelas. La reclasificaci\u00f3n de\ndelitos, <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el Programa de Abogadas de las Mujeres se han\nasesorado a m\u00e1s de 20 mil mujeres y abierto de marzo a la fecha 3,579 carpetas\nde investigaci\u00f3n. En los m\u00f3dulos y las l\u00edneas de la Semujeres se han atendido a\n60 mil mujeres, adem\u00e1s de que se han capacitado a 4,560 servidoras\/es\np\u00fablicas\/os. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las secretar\u00edas y alcald\u00edas est\u00e1n colaborando para la\nintegraci\u00f3n del Programa de Atenci\u00f3n, Prevenci\u00f3n y Acceso para una Vida Libre\nde Violencia, dando atenci\u00f3n directa a las recomendaciones de la Comisi\u00f3n\nNacional para Prevenir y Erradicar la Violencia contra las Mujeres (Conavim).\nSe firmar\u00e1 un convenio para la formaci\u00f3n con una visi\u00f3n de g\u00e9nero de la polic\u00eda\nde investigaci\u00f3n, la auxiliar y preventiva y para el gobierno, en general, as\u00ed\ncomo una campa\u00f1a educativa y pedag\u00f3gica que erradique el machismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Godoy Ramos reconoci\u00f3 que en los procesos de cambio y de\ndise\u00f1os institucionales en favor de la democracia, los derechos humanos y la\npaz, las organizaciones de la sociedad civil, los movimientos sociales, la\nacademia, entre otros actores, han jugado un papel importante. Muchas\ninstituciones actuales no podr\u00edan explicarse sin tomar en cuenta la\nintervenci\u00f3n estrat\u00e9gica de todas ellas. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2019\/08\/NOTA-LUPITA-2-1024x1024.jpg\" alt=\"\" class=\"wp-image-10815\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ante integrantes de unas 15 organizaciones feministas,\nlas convoc\u00f3 a generar dos acciones espec\u00edficas: el Plan de Atenci\u00f3n a la\nViolencia Feminicida y el Programa de Prevenci\u00f3n, Atenci\u00f3n, Sanci\u00f3n y\nErradicaci\u00f3n de la Violencia contra las Mujeres, a trav\u00e9s de una Mesa T\u00e9cnica de\nAn\u00e1lisis. Detall\u00f3 otras propuestas que retom\u00f3 de las organizaciones que\nincluyen capacitaci\u00f3n, revisi\u00f3n de protocolos, modelos y metodolog\u00edas en\natenci\u00f3n a la violencia. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta del Instituto Nacional de las Mujeres,\nNadine Gasman, las senadoras Citlali Hern\u00e1ndez Mora y Mal\u00fa M\u00edcher, y la\npresidenta de la Comisi\u00f3n de Derechos Humanos de la CDMX, Nashieli Ram\u00edrez\nHern\u00e1ndez, reconocieron el trabajo que Sheinbaum ha llevado a cabo y\nrespaldaron las iniciativas gubernamentales. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hern\u00e1ndez Mora hizo un llamado a mujeres cuya primera\nbandera es la lucha feminista a que entiendan que este gobierno est\u00e1 dispuesto\na trabajar de manera conjunta. Las causas se articulan con propuestas,\ndenuncias y exigencias claras y firmas, pero de manera respetuosa y articulada,\npuesto que hoy hay autoridades que escuchan. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, Julia P\u00e9rez, de Vereda Themis, afirm\u00f3 que\nel movimiento feminista es el que ha logrado m\u00e1s avances en favor de las\nmujeres. A pesar de que las activistas sean atacadas y denostadas, seguir\u00e1n\ntrabajando para construir un Estado de derecho y para dialogar, pero sin ceder\nen ninguna de las demandas, como lo es el derecho a decidir. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda de la Luz Estrada, del Observatorio Ciudadano\nNacional del Feminicidio, al igual que las otras participantes de las\norganizaciones que fueron invitadas al di\u00e1logo, pidieron acciones concretas\npara acabar con la impunidad y frenar la violencia. Apunt\u00f3 que en 2018 fueron\nasesinadas 167 mujeres y solo el 25% se iniciaron investigaciones como\nfeminicidio, con lo que sigue viendo grandes fallas en investigaci\u00f3n criminal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, en el primer trimestre de 2019 se registraron\n369 casos de violencia sexual, principalmente en las alcald\u00edas de Gustavo A.\nMadero, Iztapalapa e Iztacalco. A pesar de las iniciativas mencionadas, sigui\u00f3,\nlas organizaciones desconocen sus avances, por lo que es necesaria una mesa de\ninformaci\u00f3n para conocer lo que ha pasado con la Fiscal\u00eda para el feminicidio,\ncon la procuraci\u00f3n de justicia o con los hechos de violencia ocurridos en el\nSistema de Transporte Colectivo, Metro, para no actuar solo en coyunturas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anayeli P\u00e9rez Garrido, de Justicia Pro Personas,\npuntualiz\u00f3 que el contexto de violencia feminicida en la Ciudad de M\u00e9xico que\nse vive hoy fue permitido por la falta de su atenci\u00f3n, por los obst\u00e1culos de\nacceso a la justicia para las v\u00edctimas. Las acciones adicionales deben estar\nconcentrados en un plan estrat\u00e9gico para saber qui\u00e9nes ser\u00e1n los responsables\nde coordinar y ejecutar esas acciones, indicadores y plazos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la acad\u00e9mica Marta Lamas est\u00e1 muy orgullosa\ndel gobierno de la CDMX que se tiene. M\u00e1s all\u00e1 de las cr\u00edticas, de los\nconflictos, dijo, tenemos una jefa de gobierno que da la cara, que quiere\ntrabajar con la sociedad civil, pues no toda la cuarta T quiere trabajar con\nella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, en redes sociales el evento fue\ncriticado, puesto que al Di\u00e1logo no convocaron abiertamente sino por\ninvitaci\u00f3n. En sus muros de Facebook, diversas activistas consideraron que no hab\u00eda\nrepresentatividad de las organizaciones feministas ni estaban las que llamaron a\nla marcha contra las agresiones policiacas. Se\u00f1alaron que las asistentes se\nprestaron a una simulaci\u00f3n. Un portal de noticias (<em>CDMX<\/em>) habl\u00f3 de las \u201cadulaciones\u201d y \u201cespaldarazo\u201d de feministas a\nSheinbaum.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/gl\/IL<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llama Sheinbaum a un acuerdo para avanzar hacia una ciudad que erradique la violencia de g\u00e9nero<\/p>\n","protected":false},"author":3,"featured_media":10814,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,51],"tags":[],"class_list":["post-10813","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/10813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=10813"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/10813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/10814"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=10813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=10813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=10813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}