{"id":10687,"date":"2019-08-12T16:52:04","date_gmt":"2019-08-12T16:52:04","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=10687"},"modified":"2023-07-21T14:52:32","modified_gmt":"2023-07-21T19:52:32","slug":"mujeres-extraordinarias-2","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/mujeres-extraordinarias-2\/","title":{"rendered":"Mar\u00eda Cano activista pol\u00edtica y sindical de Colombia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> <strong>Con su oratoria Mar\u00eda Cano atrajo multitudes, y conmovi\u00f3 a las masas como nunca antes una mujer lo hizo en Colombia. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/Hero\u00ednas.net. 12 de agosto 2019.-  Mar\u00eda Cano fue una mujer luchadora que naciendo en una familia con dinero fue capaz de hacerse escuchar para defender los derechos de la clase obrera, una mujer que como casi ninguna en su \u00e9poca fue capaz de dejar los oficios del hogar por ser una pol\u00edtica luchadora como ninguna otra para defender a la gente de clase baja, ella se preguntaba como iba a ser la vida de sus hijos si era que llegar\u00eda a tenerlos debido a que las clases altas se aprovechan de los de mas escasos recursos explot\u00e1ndolos laboralmente, esta mujer es de gran inspiraci\u00f3n para muchas otras mujeres que no quieren quedarse en casa teniendo hijos o familia si no que quieren ayudar a los demas. MARIA CANO MUJER VALIENTE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda de los \u00c1ngeles Cano M\u00e1rquez (Medell\u00edn, 1887 &#8211; abril 26 de 1967) La Flor del Trabajo, primera mujer l\u00edder pol\u00edtica en Colombia, dirigi\u00f3 la lucha por los derechos civiles fundamentales de la poblaci\u00f3n y por los derechos de los trabajadores asalariados; encabez\u00f3 la convocatoria y agitaci\u00f3n de las huelgas obreras, colabor\u00f3 en la difusi\u00f3n de las ideas socialistas y particip\u00f3 en forma decisiva en la fundaci\u00f3n del Partido Socialista Revolucionario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 1 de mayo de 1925 fue proclamada por obreros, artesanos, contratistas y maestros de obra, Flor del Trabajo. Como tal, con una \u00abjunta asesora\u00bb, analiz\u00f3 las condiciones laborales de f\u00e1bricas y trilladoras, las quejas presentadas por trabajadores acerca de su situaci\u00f3n y las comunicaciones enviadas a los empresarios y a las autoridades acerca de problemas que afectaban a la poblaci\u00f3n trabajadora; foment\u00f3 \u00abla uni\u00f3n del obrerismo\u00bb a trav\u00e9s de conferencias y ayud\u00f3 a reorganizar el peri\u00f3dico El Rebelde&#8217; y a recolectar fondos de solidaridad.<br>Inici\u00f3 su activismo pol\u00edtico y sindical directo en las minas de Segovia y Remedios, y a partir de ah\u00ed recorri\u00f3 pr\u00e1cticamente todo el pa\u00eds defendiendo los derechos de la clase trabajadora y los de las mujeres. Con motivo del traslado a la c\u00e1rcel de Medell\u00edn de un grupo de obreros de la Tropical Oil Company, presos desde hac\u00eda ocho meses por la huelga de Barrancabermeja, Mar\u00eda Cano pronunci\u00f3 una oraci\u00f3n p\u00fablica dirigida al juez de la causa:Cinco mil obreros de Barrancabermeja han querido que mi coraz\u00f3n traiga el eco de su clamor de justicia y el anhelo que ponen sus energ\u00edas en esta hora sagrada. No vengo a pediros un mendrugo, no vengo a pediros misericordia, sino justicia.<br>Junto con el ex presidente de la Rep\u00fablica Carlos E. Restrepo, llev\u00f3 la palabra en una multitudinaria movilizaci\u00f3n contra la pena de muerte y en defensa de las libertades p\u00fablicas; all\u00ed, con su aguerrida intervenci\u00f3n, Mar\u00eda Cano irrumpi\u00f3 ante la opini\u00f3n p\u00fablica nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1926 trabaj\u00f3 en la preparaci\u00f3n del III Congreso Nacional Obrero, para lo cual realiz\u00f3 una extensa gira desde Medell\u00edn hasta Ibagu\u00e9, en compa\u00f1\u00eda del dirigente socialista Tom\u00e1s Uribe M\u00e1rquez. En Bogot\u00e1, el Congreso Obrero, que sesion\u00f3 del 21 de noviembre al 4 de diciembre, la eligi\u00f3 en la directiva del mismo. En ese congreso fue fundado el Partido Socialista Revolucionario PSR, un partido amplio, de masas.<br>Durante 1927 y 1928, realiz\u00f3 una intensa actividad propagand\u00edstica por toda Colombia. Era recibida por multitudes que se agolpaban para saludarla y acompa\u00f1arla en las manifestaciones. En varias ocasiones fue detenida o fueron duramente reprimidos los manifestantes. Fund\u00f3 el Socorro Rojo entre los campesinos de Viot\u00e1, a quienes apoy\u00f3 en la lucha por la tierra.<br>Al regresar a Medell\u00edn, en marzo de 1928, particip\u00f3 activamente en las campa\u00f1as de solidaridad con Nicaragua, entonces invadida por tropas estadounidenses. Tambi\u00e9n hizo parte del Comit\u00e9 de Lucha por los Derechos Civiles contra la llamada \u00abLey heroica\u00bb, que suprim\u00eda las garant\u00edas individuales y autorizaba la represi\u00f3n y persecuci\u00f3n de los movimientos sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 6 de diciembre de 1928, una huelga de los trabajadores de la bananera United Friut Co. fue reprimida violentamente, produci\u00e9ndose una masacre en Ci\u00e9naga (Magdalena). La represi\u00f3n desatada posteriormente, llev\u00f3 a Mar\u00eda a prisi\u00f3n. Estos hechos y la recesi\u00f3n de 1930, provocaron la terminaci\u00f3n de las labores del Congreso Nacional Obrero y el fraccionamiento del PSR. Las confrontaciones internas en el socialismo y la creaci\u00f3n del Partido Comunista Colombiano, afectaron duramente a Mar\u00eda Cano y a sus compa\u00f1eros de lucha, uno de ellos fue su primo Tom\u00e1s Uribe M\u00e1rquez (dirigente socialista), pues fueron acusados deputchistas por haber dise\u00f1ado un plan para la toma del poder en 1928.<br>Mar\u00eda escribi\u00f3 en aquella \u00e9poca una carta a Guillermo Hern\u00e1ndez Rodr\u00edguez, por aquel entonces secretario general del Partido Comunista, en la que le dec\u00eda:Usted acusa de conspiradores a mis compa\u00f1eros del Partido Socialista Revolucionario y me quiere excluir a m\u00ed de tal responsabilidad, porque supuestamente estoy llevada y convencida por ellos, o sea, no me otorga la posibilidad de criterio personal. En este pa\u00eds, donde la mujer habla a trav\u00e9s del cura, del marido o del padre, hay esa costumbre. Pero ese debate yo no se lo voy a hacer, la gente sabe qui\u00e9n soy y cu\u00e1l es mi criterio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda se vincul\u00f3 entonces como obrera de la Imprenta Departamental de Antioquia, en 1930, y luego pas\u00f3 a trabajar a la Biblioteca Departamental, donde labor\u00f3 hasta 1947. En 1934 apoy\u00f3 activamente la huelga del Ferrocarril de Antioquia. En 1945, el movimiento de mujeres sufragistas le ofreci\u00f3 un homenaje en Medell\u00edn; reci\u00e9n derrotado el nazismo, dijo, en \u00e9sta que fue su \u00faltima intervenci\u00f3n p\u00fablica:Un mundo nuevo surge hoy de la epopeya de la libertad, nutrida con sangre y con llanto y con tortura. Es un deber responder al llamado de la historia. Tenemos que hacer que Colombia responda. Cada vez son m\u00e1s amplios los horizontes de libertad, de justicia y de paz. Hoy como ayer, soy un soldado del mundo.<br>Posteriormente se hundi\u00f3 en el m\u00e1s absoluto silencio, mientras en su ciudad natal se cuidaba con rigor a las hijas para que no acabaran convertidas en temidas mariacanos, t\u00e9rmino acu\u00f1ado para designar a las j\u00f3venes rebeldes.\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con su oratoria Mar\u00eda Cano atrajo multitudes, y conmovi\u00f3 a las masas como nunca antes una mujer lo hizo en Colombia.<\/p>\n","protected":false},"author":3,"featured_media":10688,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[690,66],"tags":[],"class_list":["post-10687","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-extraordinarias"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/10687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=10687"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/10687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/10688"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=10687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=10687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=10687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}