{"id":106337,"date":"2026-06-10T12:51:00","date_gmt":"2026-06-10T18:51:00","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=106337"},"modified":"2026-06-10T12:51:00","modified_gmt":"2026-06-10T18:51:00","slug":"impulsan-fortalecer-proteccion-de-ninas-ninos-y-adolescentes-de-entornos-digitales","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/impulsan-fortalecer-proteccion-de-ninas-ninos-y-adolescentes-de-entornos-digitales\/","title":{"rendered":"Impulsan fortalecer protecci\u00f3n de ni\u00f1as, ni\u00f1os y adolescentes de entornos digitales"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>Obligaci\u00f3n del Estado asegurar el ejercicio pleno de sus derechos<\/li>\n\n\n\n<li>Analizan en Am\u00e9rica Latina y Europa agenda de mejores pr\u00e1cticas<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Micaela M\u00e1rquez&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 10 de junio, 2026.- M\u00e9xico, junto con diversos pa\u00edses de Am\u00e9rica Latina, promueve una agenda regional orientada a fortalecer la protecci\u00f3n de ni\u00f1as, ni\u00f1os y adolescentes en los entornos digitales, colocando en el centro de las pol\u00edticas p\u00fablicas su bienestar, seguridad, salud mental y desarrollo integral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La secretaria ejecutiva del Sistema Nacional de Protecci\u00f3n de Ni\u00f1as, Ni\u00f1os y Adolescentes (SIPINNA), Lorena Villavicencio Ayala, destac\u00f3 que la protecci\u00f3n de ni\u00f1as, ni\u00f1os y adolescentes tambi\u00e9n debe garantizarse en los espacios digitales, lo que es una obligaci\u00f3n del Estado para asegurar el ejercicio pleno de sus derechos, as\u00ed como su desarrollo integral, salud mental y dignidad.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 que recientemente, durante una reuni\u00f3n celebrada en Tur\u00edn, Italia, la ministra de Juventud e Infancia de Espa\u00f1a, Sira Rego, propuso la creaci\u00f3n de un grupo de trabajo permanente en el marco de las Naciones Unidas para impulsar una regulaci\u00f3n internacional de los entornos digitales. La iniciativa busca fortalecer la cooperaci\u00f3n entre los pa\u00edses y establecer est\u00e1ndares m\u00e1s s\u00f3lidos para prevenir abusos y riesgos que afectan a ni\u00f1as, ni\u00f1os y adolescentes en internet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, M\u00e9xico participa en esta discusi\u00f3n internacional con una propuesta normativa que incorpora las mejores pr\u00e1cticas observadas en distintas experiencias internacionales y reconoce la autonom\u00eda progresiva de ni\u00f1as, ni\u00f1os y adolescentes, garantizando medidas de protecci\u00f3n acordes con cada etapa de desarrollo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con estas acciones, M\u00e9xico refrenda su compromiso de impulsar una gobernanza digital centrada en los derechos humanos y en el inter\u00e9s superior de la ni\u00f1ez, as\u00ed como de fortalecer la cooperaci\u00f3n regional e internacional para construir entornos digitales seguros, inclusivos y libres de violencia para todas las ni\u00f1as, ni\u00f1os y adolescentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, durante la XIII Reuni\u00f3n Ministerial Iberoamericana de Infancia y Adolescencia, celebrada los d\u00edas 28 y 29 de abril de 2026 en Zamora, Espa\u00f1a, los pa\u00edses participantes acordaron conformar una mesa de trabajo para ampliar el respaldo regional a estas propuestas y avanzar en la construcci\u00f3n de acuerdos internacionales que promuevan entornos digitales m\u00e1s seguros, transparentes y respetuosos de los derechos de ni\u00f1as, ni\u00f1os y adolescentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Frente a los riesgos que enfrentan ni\u00f1as, ni\u00f1os y adolescentes en internet, los pa\u00edses participantes han coincidido en la necesidad de establecer reglas m\u00e1s claras para que las plataformas digitales asuman una mayor responsabilidad en la protecci\u00f3n de sus derechos. Entre las medidas propuestas se encuentran mecanismos de dise\u00f1o seguro, sistemas de verificaci\u00f3n de edad que respeten la privacidad de las personas usuarias, herramientas gratuitas de supervisi\u00f3n parental y la regulaci\u00f3n de funciones que favorecen el uso excesivo de las plataformas, como la reproducci\u00f3n autom\u00e1tica de contenidos, el desplazamiento infinito y las notificaciones constantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La propuesta tambi\u00e9n plantea prohibir la publicidad personalizada dirigida a ni\u00f1as, ni\u00f1os y adolescentes, limitar el uso comercial de sus datos personales y garantizar la protecci\u00f3n de los ingresos que puedan generar mediante su participaci\u00f3n en plataformas digitales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se busca regular aquellas pr\u00e1cticas de dise\u00f1o y algoritmos que incentivan una permanencia prolongada en l\u00ednea, especialmente entre la ni\u00f1ez y la adolescencia, con el objetivo de reducir riesgos asociados al uso intensivo de las plataformas digitales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta iniciativa incorpora las opiniones, propuestas y preocupaciones expresadas por adolescentes de Am\u00e9rica Latina y cuenta con el impulso de la Secretar\u00eda Ejecutiva del SIPINNA Nacional. Como parte de este esfuerzo, se trabaja en una propuesta de reforma para fortalecer la protecci\u00f3n de los derechos de ni\u00f1as, ni\u00f1os y adolescentes en el entorno digital y establecer est\u00e1ndares comunes desde una perspectiva de derechos humanos, inter\u00e9s superior de la ni\u00f1ez y protecci\u00f3n integral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/mm\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Micaela M\u00e1rquez&nbsp; SemM\u00e9xico, Ciudad de M\u00e9xico, 10 de junio, 2026.- M\u00e9xico, junto con diversos pa\u00edses de Am\u00e9rica Latina, promueve una agenda regional orientada a fortalecer la protecci\u00f3n de ni\u00f1as, ni\u00f1os y adolescentes en los entornos digitales, colocando en el centro de las pol\u00edticas p\u00fablicas su bienestar, seguridad, salud mental y desarrollo integral. La secretaria ejecutiva [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":106341,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[903],"tags":[],"class_list":["post-106337","post","type-post","status-publish","format-standard","has-post-thumbnail","category-presidenta-y-mas"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/106337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=106337"}],"version-history":[{"count":1,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/106337\/revisions"}],"predecessor-version":[{"id":106342,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/106337\/revisions\/106342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/106341"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=106337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=106337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=106337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}