{"id":105850,"date":"2026-05-25T20:27:27","date_gmt":"2026-05-26T02:27:27","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=105850"},"modified":"2026-05-25T20:27:27","modified_gmt":"2026-05-26T02:27:27","slug":"una-ia-feminista-asistio-a-mas-de-2-300-victimas-de-violencia-de-genero-digital","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/una-ia-feminista-asistio-a-mas-de-2-300-victimas-de-violencia-de-genero-digital\/","title":{"rendered":"Una IA feminista asisti\u00f3 a m\u00e1s de 2.300 v\u00edctimas de violencia de g\u00e9nero digital"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Silvina Molina*<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 25 de mayo, 2026.- Ellas se encontraron al pie de una escalera. No era cualquier escalera, era la de un escenario del Woman Economic Forum, espec\u00edficamente, de un evento organizado por Forbes, en 2023, en M\u00e9xico. Se escucharon y dijeron: \u201cHag\u00e1moslo\u201d. Son esos encuentros esperados en lugares inesperados que cambian e impactan en la vida de cientos de mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La que bajaba la escalera luego de realizar su presentaci\u00f3n en ese escenario era Olimpia Coral Melo, sobreviviente de violencia de g\u00e9nero digital, una activista a la que cambi\u00f3 la vida desde entonces y que junto a otras que vivieron el mismo infierno, est\u00e1 cambiando leyes y generando conciencia para prevenir y acompa\u00f1ar situaciones similares. Ella no necesita mucha m\u00e1s presentaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al pie de la escalera la esperaba Edith Contla, mexicana y cofundadora de la reci\u00e9n iniciada startup tecnol\u00f3gica AuraChat.IA, una empresa de Estados Unidos con sede en Ciudad de M\u00e9xico, enfocada en el desarrollo de agentes de inteligencia artificial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Olimpia ten\u00eda 15 minutos \u201cpara convencer a personas que no les interesa nuestra causa\u201d de que invirtieran en un desarrollo tecnol\u00f3gico que las defensoras digitales ten\u00edan en mente; quer\u00edan aliviar la cantidad de consultas que recib\u00edan por d\u00eda de mujeres que eran violentadas a trav\u00e9s de entornos digitales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya sab\u00edan cu\u00e1nto dinero se necesitaba, pero no lo ten\u00edan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEntonces cont\u00e9 que ten\u00edamos la sistematizaci\u00f3n anal\u00f3gica, que necesit\u00e1bamos programarla\u201d. En el p\u00fablico estaba Edith, que junto a sus socios Enrique Partida y David Jafri, ya hab\u00edan pensado en trabajar junto a la Olimpia, y que ya ten\u00edan publicado un manifiesto de IA \u00e9tica y redactada una propuesta legislativa de m\u00e1s de 60 p\u00e1ginas para regular la inteligencia artificial en M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLe dije a mis socios que ten\u00eda a Olimpia frente a m\u00ed. Me dijeron que hable con ella y que le ofreciera un pro bono\u201d, recuerda Edith, en la charla que tenemos por videollamada. Olimpia resume ese encuentro: \u201cFue el faro de luz que necesit\u00e1bamos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este es el inicio de la historia que dio origen a OlimpIA una plataforma desarrollada por mujeres, que integra la metodolog\u00eda de Defensoras Digitales, la Ley Olimpia y la experiencia de v\u00edctimas y activistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta es una app que Edith define como \u201crobusta\u201d con 37 modelos de inteligencia artificial, y que reconoce como \u201cla m\u00e1s compleja creada por Aura Chat\u201d hasta la fecha (sus desarrollos comerciales tienen 28 modelos). Opera en una infraestructura privada y ofrece respuestas las 24 horas, los 7 d\u00edas de la semana de \u201cforma hiperpersonalizada, an\u00f3nima y confidencial\u201d en texto y voz, a trav\u00e9s de WhatsApp. Puede responder en m\u00e1s de 50 idiomas y adelanta que \u201cpronto incluir\u00e1 llamadas telef\u00f3nicas y enlaces en lengua de se\u00f1as mexicana\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">OlimpIA fue reconocido como uno de los 50 mejores proyectos de inteligencia artificial a nivel mundial en el Ai Action Summit, en el marco del Paris Peace Forum 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre febrero de 2025 y el mismo mes de 2026 recibi\u00f3 12.480 mensajes y asisti\u00f3 a 2.389 v\u00edctimas, que se contactaron sobre todo a la tarde y noche, principalmente en Ciudad de M\u00e9xico. Llegar al desarrollo implic\u00f3 muchos encuentros, mesas de trabajo con las v\u00edctimas donde \u201ccorr\u00edan l\u00e1grimas\u201d, reconoce la empresaria, y mucho compromiso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cFue un combate a la discriminaci\u00f3n tecnol\u00f3gica de g\u00e9nero. Nos sentimos muy orgullosas de hacer tecnolog\u00eda que no sali\u00f3 desde las grandes big tech\u201d, destaca Olimpia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ella, esa IA deb\u00eda contar con el sentimiento y el sentido pol\u00edtico de lo que significa para el movimiento la Ley Olimpia y para Defensores Digitales la causa de la atenci\u00f3n a v\u00edctimas. \u201cEstamos tratando con personas que est\u00e1n viviendo procesos de desigualdad, en contextos diferenciados e incluso de intentos de suicidio\u201d, agrega. Lograrlo ha sido un desaf\u00edo para el equipo de Aura Chat, que ha trabajado con gran responsabilidad y empat\u00eda e integrando la perspectiva de las v\u00edctimas en el dise\u00f1o del c\u00f3digo, seg\u00fan explica Edith.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El desarrollo se centr\u00f3 en cuatro ejes de apoyo: psicoemocional, legal, digital y comunitario, priorizando el psicoemocional, que es lo que el 80% de las v\u00edctimas solicita primero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay especificaciones que muestran c\u00f3mo esta es una IA creada por sobrevivientes de violencia: considera que muchas mujeres en peligros no pueden hablar o leer las respuestas, entonces ofrece diversas posibilidades e identifica situaciones de riesgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Olimpia resalta que se trata de una estructura \u201cde c\u00f3digo feminista aut\u00f3nomo, de territorio\u201d y de \u201cuna ense\u00f1anza de \u00e9tica feminista, poder saber que no necesariamente nos va a sanar de manera paternalista el Estado, sino que nos vamos a sanar entre nosotras\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSomos un movimiento pol\u00edtico de autosanaci\u00f3n, de autodeterminaci\u00f3n y de autoempoderamiento apoyado en herramientas digitales que hemos aportado, que las v\u00edctimas aportan\u201d, es la definici\u00f3n de &nbsp;Olimpia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay numerosas investigaciones sobre c\u00f3mo la violencia de g\u00e9nero digital impacta en la vida diaria de las mujeres, sobre c\u00f3mo se est\u00e1 utilizando IA como herramienta para violentar. A la par, se est\u00e1 subiendo una escalera, que es sinuosa, donde pelda\u00f1o a pelda\u00f1o muchas de ellas dise\u00f1an una IA feminista, y por lo tanto, situada, decolonial, que tiene en cuenta la diversidad de mujeres que somos en Am\u00e9rica Latina y Caribe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ese proceso en marcha se inicia con historias como esta, con mujeres que se encuentran y dicen: \u201cHag\u00e1moslo\u201d. Por ellas y por todas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente Semlac, paquete de comunicaci\u00f3n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Silvina Molina* SemM\u00e9xico, Cd. de M\u00e9xico, 25 de mayo, 2026.- Ellas se encontraron al pie de una escalera. No era cualquier escalera, era la de un escenario del Woman Economic Forum, espec\u00edficamente, de un evento organizado por Forbes, en 2023, en M\u00e9xico. Se escucharon y dijeron: \u201cHag\u00e1moslo\u201d. Son esos encuentros esperados en lugares inesperados que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":105851,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[748],"tags":[],"class_list":["post-105850","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura-feminista"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/105850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=105850"}],"version-history":[{"count":1,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/105850\/revisions"}],"predecessor-version":[{"id":105852,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/105850\/revisions\/105852"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/105851"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=105850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=105850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=105850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}