{"id":105547,"date":"2026-05-13T11:42:06","date_gmt":"2026-05-13T17:42:06","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=105547"},"modified":"2026-05-13T11:42:07","modified_gmt":"2026-05-13T17:42:07","slug":"opinion-la-secretaria-de-las-mujeres-y-las-madres-buscadoras","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/opinion-la-secretaria-de-las-mujeres-y-las-madres-buscadoras\/","title":{"rendered":"Opini\u00f3n | La Secretar\u00eda de las Mujeres y las madres buscadoras"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Elena Tapia Fonllem<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 13 de mayo, 2026.- Dos problemas, dos, entre muchos, ameritan ser comentados, uno tiene que ver con la falta de&nbsp;<strong>nombramiento de la nueva titular de la Secretar\u00eda de las Mujeres&nbsp;<\/strong>en el&nbsp;<strong>gobierno federal<\/strong>, ante la salida de la&nbsp;<strong>extitular<\/strong>&nbsp;<strong>Citlali Hernandez&nbsp;<\/strong>el 15 de abril, este hecho genera malestar e indigna pues el mensaje pareciera ser que las actividades de dicho espacio de gobierno no importan, no son esenciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El otro problema es la&nbsp;<strong>incapacidad del gobierno<\/strong>&nbsp;de reconocer a las&nbsp;<strong>madres buscadoras<\/strong>&nbsp;como lo que son,&nbsp;<strong>defensoras de los derechos humanos<\/strong>,&nbsp;<strong>luchadoras sociales<\/strong>&nbsp;que hacen lo que el&nbsp;<strong>Estado&nbsp;<\/strong>no ha podido hacer,&nbsp;<strong>buscar<\/strong>&nbsp;a las<strong>&nbsp;personas<\/strong>&nbsp;<strong>desaparecidas&nbsp;<\/strong>que suman ya los&nbsp;<strong>133 mil<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El paso de&nbsp;<strong>Instituto a Secretar\u00eda de las Mujeres<\/strong>, en octubre de<strong>&nbsp;2024<\/strong>,&nbsp;<strong>parec\u00eda<\/strong>&nbsp;representar un&nbsp;<strong>avance s\u00f3lido<\/strong>, un compromiso contundente para que la instancia administrativa y pol\u00edtica encargada de conducir y coordinar la pol\u00edtica nacional para la igualdad sustantiva tendr\u00eda no solo un&nbsp;<strong>status<\/strong>&nbsp;sino un trato y&nbsp;<strong>asignaci\u00f3n financiera suficiente<\/strong>&nbsp;para avanzar hacia la igualdad sustantiva de las mexicanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recordemos que de esta Secretar\u00eda depende garantizar la&nbsp;<strong>transversalidad de g\u00e9nero<\/strong>&nbsp;en toda la&nbsp;<strong>administraci\u00f3n p\u00fablica<\/strong>, impulsar las acciones&nbsp;<strong>contra la violencia hacia las mujeres&nbsp;<\/strong>y vigilar el cabal cumplimiento de las pol\u00edticas p\u00fablicas que atienden problemas de desigualdades e injusticias hacia mujeres y ni\u00f1as.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los&nbsp;<strong>a\u00f1os 90 del siglo XX<\/strong>&nbsp;varias expresiones del movimiento feminista ten\u00edan entre sus sus principales&nbsp;<strong>demandas<\/strong>&nbsp;la creaci\u00f3n de&nbsp;<strong>Instituto de las mujeres<\/strong>. Ser\u00eda en el 2001, durante el gobierno de&nbsp;<strong>Vicente Fox<\/strong>&nbsp;que se pudo aprobar la<strong>&nbsp;ley de creaci\u00f3n del Instituto de las Mujeres<\/strong>. Se inici\u00f3 entonces un&nbsp;<strong>largo camino<\/strong>&nbsp;para ir dise\u00f1ando&nbsp;<strong>pol\u00edticas y programas de \u00edndole p\u00fablico<\/strong>&nbsp;que atienden los problemas y necesidades de las mujeres en distintos \u00e1mbitos como la&nbsp;<strong>salud<\/strong>, la&nbsp;<strong>vivienda<\/strong>, la&nbsp;<strong>educaci\u00f3n<\/strong>, la&nbsp;<strong>prevenci\u00f3n de la violencia<\/strong>; se echaron a andar los institutos de las mujeres en las entidades federativas y en los municipios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Llegar a convertirse en Secretar\u00eda&nbsp;<strong>parec\u00eda una promesa de madurez<\/strong>&nbsp;en el abordaje de la desigualdad y la discriminaci\u00f3n que aqueja a las mujeres, lo que no se puede sin una titular, alguien que ejerza el liderazgo de corte feminista que se requiere.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>Secretaria de las Mujeres<\/strong>&nbsp;deber\u00eda tambi\u00e9n&nbsp;<strong>adoptar una clara defensa<\/strong>, un&nbsp;<strong>reconocimiento<\/strong>&nbsp;y&nbsp;<strong>acompa\u00f1amiento institucional a las mujeres<\/strong>&nbsp;que por todo el pa\u00eds llevan a cabo la b\u00fasqueda de sus familiares afectados por el fen\u00f3meno creciente de desapariciones forzosas. Para eso se pugnaba en los a\u00f1os 90, crear un Instituto, hoy secretar\u00eda que reconozca los m\u00faltiples problemas que enfrentan las mexicanas y desarrolle programas que apoyen sus necesidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las&nbsp;<strong>madres buscadoras son v\u00edctimas<\/strong>, pues personas cercanas a ellas han sido desaparecidas y\/ o asesinadas; las madres buscadoras son&nbsp;<strong>luchadoras sociales<\/strong>&nbsp;que defienden los derechos humanos y han sido&nbsp;<strong>reconocidas por instancias de la ONU<\/strong>, las madres buscadoras, son mujeres vulnerables a ser agredidas y a pesar de ello, el&nbsp;<strong>domingo 10 de mayo salieron nuevamente a las calles de la Ciudad de M\u00e9xico<\/strong>&nbsp;a protestar ante la indolencia del gobierno federal y de la Secretar\u00eda de las Mujeres que deber\u00eda defenderlas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elena Tapia Fonllem SemM\u00e9xico, Cd. de M\u00e9xico, 13 de mayo, 2026.- Dos problemas, dos, entre muchos, ameritan ser comentados, uno tiene que ver con la falta de&nbsp;nombramiento de la nueva titular de la Secretar\u00eda de las Mujeres&nbsp;en el&nbsp;gobierno federal, ante la salida de la&nbsp;extitular&nbsp;Citlali Hernandez&nbsp;el 15 de abril, este hecho genera malestar e indigna pues [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":98750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-105547","post","type-post","status-publish","format-standard","has-post-thumbnail","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/105547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=105547"}],"version-history":[{"count":1,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/105547\/revisions"}],"predecessor-version":[{"id":105548,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/105547\/revisions\/105548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/98750"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=105547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=105547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=105547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}