{"id":10519,"date":"2019-08-06T00:31:07","date_gmt":"2019-08-06T00:31:07","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=10519"},"modified":"2023-07-21T14:51:54","modified_gmt":"2023-07-21T19:51:54","slug":"opinion-27","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/opinion-27\/","title":{"rendered":"Palabra de Ant\u00edgona"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Los cambios a la AVGM que discuten las diputadas no ayudan<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Los\nmedios y el sistema educativo, pilares que sostienen la violencia feminicida<\/strong><\/li><li><strong>No\nse necesitan m\u00e1s parches a la LGAMVLV sino ir a fondo<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sara\nLovera<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> SemM\u00e9xico. Ciudad de M\u00e9xico. 5 de agosto de 2019.- Creo que la propuesta de la Comisi\u00f3n Nacional para Prevenir y Erradicar la Violencia contra las Mujeres (Conavim) para hacer cambios en la Alerta de Violencia de G\u00e9nero contra las Mujeres (AVGM) la burocratiza m\u00e1s de\u00a0 lo que ya exist\u00eda, al proponer nuevos mecanismos. Es un texto que confunde. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa, adem\u00e1s, es muy estricta atendiendo los\npendientes y la indiferencia de bur\u00f3cratas insensibles. La diputada federal Lorena\nVillavicencio hace tres propuestas punitivas contra los agentes del ministerio\np\u00fablico y los ayuntamientos, y propone se declare la AVGM en el pa\u00eds entero. La\niniciativa para crear un mecanismo especial en la Ciudad de M\u00e9xico es\nredundante. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como dice Rita Segato: la violencia y el feminicidio, m\u00e1s\nque un problema que s\u00f3lo se resuelve con leyes e instituciones, es un asunto\nque viene de un Estado patriarcal capitalista, donde los agentes que promueven\nla violencia contra las mujeres provienen de la forma jer\u00e1rquica de la sociedad.\nEs la explotaci\u00f3n y la desigualdad intr\u00ednseca del modo de producci\u00f3n. Tiene\nraz\u00f3n, pero hay que hacer algo mientras podamos modificar al sistema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Creo que las legisladoras deber\u00edan ir al fondo, ir a los\ndos de los pilares que sostienen y promueven la violencia feminicida. Ir a\nreformas serias que podr\u00edan incidir r\u00e1pido si se marcan l\u00edmites a los medios, sin\nmenoscabo de la libertad de expresi\u00f3n. Todav\u00eda en las entidades del pa\u00eds hay peri\u00f3dicos\nimpresos y digitales que publican \u00abencueradas\u00bb y tienen la desgracia\nde cosificar a las mujeres, por no hablar de la tendencia cada d\u00eda mayor de la\nvictimizaci\u00f3n de las mujeres y la reproducci\u00f3n de estereotipos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me canso que con la presi\u00f3n de las feministas podr\u00edan\nlograr di\u00e1logos con editores. \u00a1Claro que s\u00ed! Hay que explicarles, y si no le\nentran hay que reglamentar. Pero nadie lo ha hecho. Es tarea de Olga S\u00e1nchez\nCordero, la secretaria de Gobernaci\u00f3n, y su equipo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El otro pilar pernicioso es el sistema educativo. Sus maestras\ny maestros insensibles, ignorantes muchos y muchas y, lo peor, violentos y\nmachos. No hablo de abusadores, que los hay en los dos gremios de estos\npilares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es tiempo de pensar creativamente; ir por caminos nuevos.\nNo me sirve la denuncia cotidiana y a secas ni la conmiseraci\u00f3n hacia a las\nafectadas que viven la violencia en toda la gama perversa. Ellas, nosotras,\nnecesitamos cambios reales en el uso cotidiano del discurso patriarcal, empezando\npor dejar de hablar desde lo binario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo fomentar telenovelas cortas programadas sobre la experiencia\nde las mujeres y de muchos hombres que han dejado huellas centrales? Las que se\nhan hecho, como las del canal 11, por lo menos, est\u00e1n mal producidas y se\nquedan en el intento de que los conceptos comunican lo que no pueden las\npalabras. \u00a1Claro que las palabras pueden!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso no puede decir la ley violencia estructural ni\nigualdad sustantiva. Son dos conceptos, uno que explica hist\u00f3ricamente la\nviolencia; el otro es un concepto aspiracional. Ser\u00eda muy interesante que nuestras\nlegisladoras tomaran un curso de semi\u00f3tica y de literatura. Lo que no se\nconecta con las otras personas no comunica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yo creo que la AVGM debe ajustarse a lo que hoy dice la Ley\nGeneral de Acceso de las Mujeres a una Vida Libre de Violencia (LGAMVLV) o lo\nque dijo de origen. Creo que es menester hacer efectivos los sistemas de\nPrevenci\u00f3n, Atenci\u00f3n, Sanci\u00f3n y Erradicaci\u00f3n de la Violencia y los convenios de\nlos gobiernos federal y estatales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n ajustar a los medios a lo que dice la\nConstituci\u00f3n y que obligadamente informen o, de otro modo, cumplan con el\nderecho de las mexicanas a ser informadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Urge, por tanto \u2014y para eso es la paridad\u2014 que las mujeres\ndel poder tomen decisiones y empiecen a modificar conductas y, por supuesto,\nlogren el cese de la impunidad y que busquen se asegure una vida sin violencia\npara toda la poblaci\u00f3n mexicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfPor qu\u00e9 no un buen reglamento para las y los maestros?\nUn poquito de \u00e9tica en la locuci\u00f3n mexicana y buenas series en Netflix y todas\nlas redes sociales. Un diccionario de t\u00e9rminos no sexista; por favor, no una\ngu\u00eda sino un diccionario que traduzca las palabras usadas para denigrar o humillar.\nUn diccionario para las escuelas. Tambi\u00e9n he pensado en que se debe acordar con\nlas y los empresarios de todo tipo para que hablen del valor de las mujeres y\nel sentido filos\u00f3fico del buen vivir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed no tendr\u00edamos tantos parches en la ley que, por\ncierto, pocas personas conocen y m\u00e1s pocas respetan o se sit\u00faan en sus ejes. Ni\nlas ni los abogados saben. En fin, sue\u00f1os de una guajira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">saraloveralipez@gmail.com <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los cambios a la AVGM que discuten las diputadas no ayudan<\/p>\n","protected":false},"author":3,"featured_media":9290,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,95,69],"tags":[],"class_list":["post-10519","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-palabra-de-antigona","category-sara-lovera"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/10519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=10519"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/10519\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/9290"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=10519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=10519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=10519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}