{"id":104085,"date":"2026-03-27T15:48:57","date_gmt":"2026-03-27T21:48:57","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=104085"},"modified":"2026-03-27T16:01:21","modified_gmt":"2026-03-27T22:01:21","slug":"mas-de-16-mil-mujeres-en-prision-por-fallas-estructurales-del-estado-mexicano","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/mas-de-16-mil-mujeres-en-prision-por-fallas-estructurales-del-estado-mexicano\/","title":{"rendered":"M\u00e1s de 16 mil mujeres en prisi\u00f3n por fallas estructurales del Estado Mexicano"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>EQUIS Justicia presenta el informe De la ausencia a la criminalizaci\u00f3n<\/li>\n\n\n\n<li>Este no es un fen\u00f3meno aislado, sino el resultado de m\u00faltiples violencias y desigualdades<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Elda Montiel<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 27 de marzo, 2026.- En M\u00e9xico, 16 mil 172 mujeres se encuentran privadas de la libertad (SSPC, enero de 2026), muchas de ellas sin sentencia y en contextos marcados por la pobreza, los cuidados y las violencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n revela que se ha incrementado m\u00e1s del cinco por ciento el n\u00famero de mujeres en prisi\u00f3n, entre 2020 y 2024 con un repunte del 56 por ciento en 2023, un incremento mayor que el de los hombres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EQUIS Justicia para mujeres present\u00f3 dos documentos: El informe De la ausencia a la criminalizaci\u00f3n, y la agenda Duro contra el Mundo donde muestra un sistema que invisibiliza, abandona y termina criminalizando a las mujeres, al documentar c\u00f3mo opera la cadena de violaciones a derechos y, por otro, da voz a las mujeres que dentro y fuera de prisi\u00f3n, se organizan, nombran y enfrentan ese mismo sistema. La agenda recoge las demandas de mujeres privadas y exprivadas de la libertad que trazan una ruta clara de resistencia colectiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En Plural TV fue la presentaci\u00f3n de los documentos por EQUIS Justicia para las Mujeres<\/strong><strong>,<\/strong> en colaboraci\u00f3n con la <strong>Direcci\u00f3n General de Igualdad Sustantiva y No Discriminaci\u00f3n de la Suprema Corte de Justicia de la Naci\u00f3n.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los hallazgos del Informe muestran que la criminalizaci\u00f3n de las mujeres no es un fen\u00f3meno aislado, sino el resultado de m\u00faltiples violencias y desigualdades previas como la pobreza, antes de ser detenidas tres de cada 10 mujeres ganaban menos de tres mil pesos mensuales; cuatro de cada 10 mujeres realizaban trabajo dom\u00e9stico no remunerado, en mujeres ind\u00edgenas casi seis de cada 10, por lo que dejan de participar en el mercado laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al menos 17 por ciento reporta haber vivido violencia antes de su detenci\u00f3n, sin que estos contextos sean considerados por el sistema de justicia en los procesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El sistema penal como respuesta deja a nueve de 10 mujeres en prisi\u00f3n sin sentencia. De las que son sentenciadas uno de cada tres es por procedimiento abreviado y la mitad fue presionada para aceptarlo, lo que limita el acceso a una defensa adecuada y evita que un juez revise su caso con perspectiva de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gabriela Cruz, una mujer zapoteca que particip\u00f3 en la redacci\u00f3n de los documentos, &nbsp;relat\u00f3 que fue privada de la libertad por delito contra la salud, buscando un ingreso que le permitir\u00eda acceder a servicios de salud para su hijo con discapacidad. Realiz\u00f3 la entrega de la agenda, dise\u00f1ada desde las experiencias y vivencias de mujeres que como ella estuvieron en prisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la Agenda \u201cDuro contra el muro\u201d plantea como rutas concretas de acci\u00f3n:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Prevenir el encarcelamiento de mujeres deteniendo mecanismos de justicia autom\u00e1tica como la prisi\u00f3n preventiva de oficio o el procedimiento abreviado<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Garantizar condiciones dignas en prisi\u00f3n incluyendo el respeto a la autonom\u00eda corporal y el fortalecimiento de sus v\u00ednculos familiares y comunitarios<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Facilitar el acceso a mecanismos efectivos de excarcelaci\u00f3n y reinserci\u00f3n social<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">EQUIS Justicia detalla que ambos documentos fueron construidos a lo largo de tres a\u00f1os con la participaci\u00f3n de mujeres que enfrentaron procesos de criminalizaci\u00f3n, quienes contribuyeron en el dise\u00f1o metodol\u00f3gico, el trabajo de campo \u2014incluyendo entrevistas en centros penitenciarios de Ciudad de M\u00e9xico, Oaxaca y Campeche\u2014, el an\u00e1lisis de sentencias y la formulaci\u00f3n de propuestas. Como parte de la investigaci\u00f3n, se analizaron 60 sentencias penales, se realizaron 36 solicitudes de acceso a la informaci\u00f3n, se revisaron instrumentos de pol\u00edtica p\u00fablica y se incorporaron datos de la Encuesta Nacional de Poblaci\u00f3n Privada de la Libertad (ENPOL) 2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Durante la presentaci\u00f3n participaron, <\/strong><strong>&nbsp;<\/strong><strong>Cristina Solano<\/strong><strong>,<\/strong> Directora General de Igualdad Sustantiva y No Discriminaci\u00f3n de la Suprema Corte de Justicia de la Naci\u00f3n, el magistrado&nbsp;<strong>Benjam\u00edn Rubio<\/strong><strong>, <\/strong>titular del Instituto Federal de Defensor\u00eda P\u00fablica;&nbsp;<strong>Ingrid G\u00f3mez<\/strong><strong>, <\/strong>subsecretaria del Derecho a una Vida Libre de Violencias de la Secretar\u00eda de las Mujeres;&nbsp;<strong>Nestora Salgado<\/strong><strong>,<\/strong> tercera visitadora de la Comisi\u00f3n Nacional de los Derechos Humanos;&nbsp;<strong>Simey Olvera<\/strong><strong>,<\/strong> senadora y secretaria de la Mesa Directiva del Senado; y &nbsp;<strong>Ma\u00efssa Hubert<\/strong>, subdirectora ejecutiva de EQUIS Justicia para las Mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/em\/sj<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion-.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"723\" height=\"1024\" data-id=\"104089\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion--723x1024.jpg\" alt=\"\" class=\"wp-image-104089\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion--723x1024.jpg 723w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion--212x300.jpg 212w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion--768x1088.jpg 768w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion--150x213.jpg 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion--300x425.jpg 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion--696x986.jpg 696w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion-.jpg 847w\" sizes=\"auto, (max-width: 723px) 100vw, 723px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"723\" height=\"1024\" data-id=\"104091\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion-2-723x1024.jpg\" alt=\"\" class=\"wp-image-104091\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion-2-723x1024.jpg 723w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion-2-212x300.jpg 212w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion-2-768x1088.jpg 768w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion-2-150x213.jpg 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion-2-300x425.jpg 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion-2-696x986.jpg 696w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/criminalizacion-2.jpg 847w\" sizes=\"auto, (max-width: 723px) 100vw, 723px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Elda Montiel SemM\u00e9xico, Ciudad de M\u00e9xico, 27 de marzo, 2026.- En M\u00e9xico, 16 mil 172 mujeres se encuentran privadas de la libertad (SSPC, enero de 2026), muchas de ellas sin sentencia y en contextos marcados por la pobreza, los cuidados y las violencias. Tambi\u00e9n revela que se ha incrementado m\u00e1s del cinco por ciento el [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":104086,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[694],"tags":[],"class_list":["post-104085","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacadas"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/104085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=104085"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/104085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/104086"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=104085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=104085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=104085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}