{"id":104067,"date":"2026-03-25T15:26:35","date_gmt":"2026-03-25T21:26:35","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=104067"},"modified":"2026-03-25T15:26:36","modified_gmt":"2026-03-25T21:26:36","slug":"palabra-de-antigona-una-nueva-ley-general-de-feminicidio","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/palabra-de-antigona-una-nueva-ley-general-de-feminicidio\/","title":{"rendered":"Palabra de Ant\u00edgona | Una Nueva Ley General de Feminicidio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sara Lovera<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 25 de marzo, 2026,-&nbsp; Ayer amanecimos con el anuncio de una&nbsp;<strong>nueva Ley sobre Feminicidio<\/strong>, que&nbsp;sin duda es la expresi\u00f3n de la&nbsp;<strong>voluntad pol\u00edtica presidencial&nbsp;<\/strong>para&nbsp;atender esta<strong>&nbsp;tragedia&nbsp;<\/strong>cotidiana que&nbsp;se devel\u00f3 en 1998 en Ciudad Ju\u00e1rez, Chihuahua, y que ha cobrado la vida de m\u00e1s de mil mujeres cada a\u00f1o, que no se resolver\u00e1 mientras no se invierta en ello y&nbsp;<strong>de nada sirve aumentar sanciones o reglas<\/strong>&nbsp;que ya est\u00e1n en nuestra legislaci\u00f3n pero que no se cumplen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la ma\u00f1anera del pueblo vimos un esquema de la&nbsp;<strong>iniciativa<\/strong>&nbsp;que llegar\u00e1 de un momento a otro al&nbsp;<strong>Senado<\/strong>, cuyos ejes son&nbsp;una repetici\u00f3n&nbsp;de las recomendaciones hechas en&nbsp;2009 por la<strong>&nbsp;Corte Interamericana de Derechos Humanos<\/strong>&nbsp;-caso Campo Algodonero-&nbsp;y de la sentencia Mariana Lima Buen D\u00eda,&nbsp;del 25 de marzo de 2015, que b\u00e1sicamente recomiendan al Estado Mexicano hacer las<strong>&nbsp;investigaciones con visi\u00f3n de g\u00e9nero<\/strong>, investigar&nbsp;<strong>cada muerte violenta de mujeres como feminicidio<\/strong>,&nbsp;<strong>homologar el tipo penal<\/strong>,&nbsp;reglas para obligar&nbsp;a la autoridad judicial a conducirse con prontitud y diligencia&nbsp;y crear protocolos de prevenci\u00f3n, as\u00ed como investigar y procurar justicia respetando el debido proceso y cuidar la cadena de custodia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero lo m\u00e1s importante es que se&nbsp;trabaje un&nbsp;<strong>presupuesto suficiente y&nbsp;adecuado<\/strong>, en mecanismos para que las normas se cumplan y en la transformaci\u00f3n del pensamiento del funcionariado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo digo por nuestra&nbsp;<strong>desmemoria infinita<\/strong>.&nbsp;Lo&nbsp;que&nbsp;se propone est\u00e1 mandatado, pero desairado en el d\u00eda a d\u00eda. Tal es el problema de fondo. La iniciativa denominada Ley General para Prevenir, Investigar, Sancionar y Reparar el Da\u00f1o por el Delito de Feminicidio no&nbsp;<strong>s\u00f3lo repite todo lo vigente<\/strong>, sino que se nos presenta como nuevo y profundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace al menos ocho a\u00f1os las&nbsp;<strong>diputadas y senadoras perredistas<\/strong>&nbsp;insistieron en&nbsp;<strong>homologar el delito de feminicidio<\/strong>, definido por cada entidad de manera distinta, cosa que la&nbsp;iniciativa no resuelve al presentarse como<strong>&nbsp;ley general y no federal<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo de&nbsp;<strong>fiscal\u00edas especializadas<\/strong>, recordamos&nbsp;que fueron creadas desde 1989, que con reformas legales y reglamentos se fueron ampliando; pr\u00e1cticamente&nbsp;<strong>en todo el pa\u00eds existen, otra cosa es que mal funcionan<\/strong>. Entonces m\u00e1s que una ley&nbsp;<strong>habr\u00eda que hacer efectivas las instituciones ya creadas<\/strong>, cumplir los mandatos y las varias sentencias de la Corte que&nbsp;<strong>hoy&nbsp;son letra muerta<\/strong>.&nbsp;<strong>\u00bfPara qu\u00e9 una nueva ley? No lo entiendo<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No se trata de menospreciar el inter\u00e9s&nbsp;de la&nbsp;<strong>presidenta Claudia Sheinbaum Pardo<\/strong>, pero&nbsp;como me dijo la&nbsp;<strong>abogada Andrea Medina Rosas<\/strong>,<strong>&nbsp;<\/strong>las expertas feministas desde hace 17 a\u00f1os han&nbsp;insistido que el&nbsp;<strong>feminicidio debe atenderse en forma integral<\/strong>, resolver&nbsp;la falta de personal que debiera estar capacitado; hacer que&nbsp;los&nbsp;<strong>servicios periciales<\/strong>&nbsp;\u2013que son una tragedia-&nbsp;est\u00e9n&nbsp;<strong>especializados y sean&nbsp;diligentes<\/strong>. Nada&nbsp;de ello ser\u00e1 posible sin recursos, los que&nbsp;<strong>desde hace&nbsp;siete a\u00f1os&nbsp;se disminuyen<\/strong>&nbsp;sistem\u00e1ticamente, sobre todo en capacitaci\u00f3n y sensibilizaci\u00f3n del funcionariado. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>No tuvo l\u00f3gica&nbsp;desaparecer la CONAVIM<\/strong>, creada en el a\u00f1o 2004, o la fiscal\u00eda para los delitos contra las mujeres, tambi\u00e9n creada en 2005; trasladar&nbsp;los Centros de justicia a la Secretar\u00eda de las Mujeres, m\u00e1s ocupada en trabajo territorial que en pol\u00edticas p\u00fablicas,&nbsp;<strong>es un desprop\u00f3sito<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La acci\u00f3n pol\u00edtica de la presidenta de la Rep\u00fablica es eso. Ya tenemos una Ley General de Acceso de las Mujeres a una Vida Libre de Violencia desde 2007 con una docena de reformas. De esa Ley General se han desprendido 32 estatales&nbsp;en toda la Rep\u00fablica,&nbsp;de ah\u00ed eman\u00f3 la creaci\u00f3n del&nbsp;<strong>delito de feminicidio, no homologado todav\u00eda&nbsp;y que esta iniciativa no resuelve<\/strong>. Adem\u00e1s no sirve aumentar las sanciones -que en realidad tambi\u00e9n existen-&nbsp;cuando la atenci\u00f3n no es integral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De lo que le\u00ed&nbsp;<strong>en el esquema hay dos asuntos \u201cnuevos\u201d&nbsp;<\/strong>de pol\u00edtica discursiva o para una definici\u00f3n de ley, es que se dice que se trata de&nbsp;<strong>reforzar la investigaci\u00f3n con perspectiva de g\u00e9nero<\/strong>; aplicar protocolos especializados; analizar antecedentes de violencia aunque no haya denuncias previas; orientar las indagaciones con \u201cla determinaci\u00f3n de la verdad y reparaci\u00f3n integral del da\u00f1o\u201d. Lo que podr\u00eda ser un decreto presidencial, por ejemplo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n incorpora&nbsp;<strong>considerar como delito la tentativa de feminicidio&nbsp;<\/strong>que&nbsp;<strong>Carolina Ram\u00edrez<\/strong>, como l\u00edder de las v\u00edctimas de esa tentativa, propuso desde 2022, y me dijo que reconocer la tentativa de feminicidio es un avance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;O sea,&nbsp;<strong>nada nuevo bajo el sol en este discurso de preocupaci\u00f3n con una iniciativa \u201cnueva\u201d<\/strong>.&nbsp;Tambi\u00e9n se ponen en primer plano el programa los&nbsp;<strong>Centros Libres<\/strong>, antes puntos naranja o centros para mujeres que nacieron durante el gobierno de&nbsp;<strong>Cuauht\u00e9moc C\u00e1rdenas<\/strong>&nbsp;en la ciudad de M\u00e9xico en 1997.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yo creo que este esfuerzo pol\u00edtico nace de lo que en el&nbsp;<strong>podcast de La Lovera<\/strong>,&nbsp;<strong>Citlalli Hern\u00e1ndez Mora, secretaria de las Mujeres,<\/strong>&nbsp;me dijo -30 de enero 2026-: en realidad la Presidenta no ha encontrado la forma de c\u00f3mo atender y disminuir el feminicidio y no lo pudo hacer cuando era jefa de gobierno. Ahora la Presidenta nos dijo que la iniciativa&nbsp;surge de su experiencia y&nbsp;la de Ernestina Godoy Ramos, hoy Fiscal General de la Rep\u00fablica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La propuesta, que se seguir\u00e1 analizando,&nbsp;entra\u00f1a un discurso&nbsp;pol\u00edtico, que s\u00f3lo agrega a todo lo reglamentado&nbsp;adoptar la \u201cigualdad&nbsp;sustantiva\u201d, esa que se introdujo en la Constituci\u00f3n, y habla de \u201creforzar\u201d; de una&nbsp;Comisi\u00f3n Especial, porque el Programa Integral&nbsp;para Prevenir, Atender, Sancionar y Erradicar las Violencias Contra las Mujeres, ya fue publicado. Y de pol\u00edticas integrales, no dice nada. Veremos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*Periodista, editora de g\u00e9nero en la OEM y directora del portal informativo semmexico.mx<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/oem.com.mx\/elsoldemexico\/tags\/temas\/leyes\/app.json\">Leyes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/oem.com.mx\/elsoldemexico\/tags\/temas\/feminicidios\/app.json\">Feminicidios<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Sara Lovera SemM\u00e9xico, Cd. de M\u00e9xico, 25 de marzo, 2026,-&nbsp; Ayer amanecimos con el anuncio de una&nbsp;nueva Ley sobre Feminicidio, que&nbsp;sin duda es la expresi\u00f3n de la&nbsp;voluntad pol\u00edtica presidencial&nbsp;para&nbsp;atender esta&nbsp;tragedia&nbsp;cotidiana que&nbsp;se devel\u00f3 en 1998 en Ciudad Ju\u00e1rez, Chihuahua, y que ha cobrado la vida de m\u00e1s de mil mujeres cada a\u00f1o, que no se resolver\u00e1 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":70950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[35,69],"tags":[],"class_list":["post-104067","post","type-post","status-publish","format-standard","has-post-thumbnail","category-opinion","category-sara-lovera"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/104067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=104067"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/104067\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/70950"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=104067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=104067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=104067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}