{"id":103418,"date":"2026-03-07T14:06:09","date_gmt":"2026-03-07T20:06:09","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=103418"},"modified":"2026-03-07T14:06:10","modified_gmt":"2026-03-07T20:06:10","slug":"mujer-triqui-la-mirada-de-bety-perez-sobre-una-guerra-ignorada","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/mujer-triqui-la-mirada-de-bety-perez-sobre-una-guerra-ignorada\/","title":{"rendered":"Mujer Triqui, la mirada de Bety P\u00e9rez sobre una guerra ignorada"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>Es la versi\u00f3n de las mujeres sobre un conflicto de medio siglo<\/li>\n\n\n\n<li>Una generaci\u00f3n que tiene el compromiso de construir la paz<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Soledad Jarqu\u00edn Edgar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Oaxaca, 6 de febrero, 2026.- Beatriz P\u00e9rez L\u00f3pez es una mujer que vivi\u00f3 desde ni\u00f1a el \u201cconflicto\u201d de la naci\u00f3n triqui, su libro Mujer Triqui, una vida construyendo la paz (Grijabo, 2025) es la versi\u00f3n de la historia contada por una mujer, que vivi\u00f3 en carne propia la violencia feminicida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su pap\u00e1 Juan Dom\u00edngo P\u00e9rez como su mam\u00e1 Sof\u00eda L\u00f3pez Castro quer\u00edan que naciera en San Juan Copala, la cuna de la naci\u00f3n Triqui, pero el parto ocurri\u00f3 inesperadamente unos d\u00edas antes de lo previsto cuando se encontraban en Huajuapan de Le\u00f3n, la cabecera distrital, en la regi\u00f3n de la Mixteca oaxaque\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Beatriz P\u00e9rez L\u00f3pez ha desarrollado una carrera pol\u00edtica, que tras dos intentos logr\u00f3 en 2018 ser diputada federal por Morena. Es abogada y junto con Naomi, Joshua y Astrid, j\u00f3venes comunicadores y especialistas en medios digitales, produjo el documental <em>Ra\u00edces de Justicia. El legado de Juan Domingo <\/em>en 2024, y a trav\u00e9s del Podcast Nosotras en Ruta, amplifica las voces de las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mujer Triqui es una historia personal, una historia de familia, que se deb\u00eda escribir porque nac\u00ed dentro de un conflicto armado, donde su protecci\u00f3n fue su familia y las amistades que fue tejiendo desde el primer internado donde estudi\u00f3 su primaria y donde conoci\u00f3 a otras ni\u00f1as que como ella viv\u00edan el mismo conflicto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera vez que lleg\u00f3 al internado de \u201cmonjitas\u201d que hab\u00eda en San Juan Copala, fue tambi\u00e9n la primera vez que se separaba de su madre. Entr\u00f3 a la habitaci\u00f3n donde hab\u00eda otras ni\u00f1as, ella era la nueva. Se sent\u00f3 sobre la cama y se puso a llorar. Adriana Ortiz Garc\u00eda fue la \u00fanica ni\u00f1a que se acerc\u00f3 para consolarla, mientras era observada por su hermana Emelia. Esa amistad termin\u00f3 el 5 de noviembre del 2024, cuando Adriana y su hermana Virginia fueron asesinadas en la capital oaxaque\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todas somos ra\u00edces, venas y estamos entrelazadas por alguna raz\u00f3n, se\u00f1ala Bety P\u00e9rez, cuando habla de las hermanas Ortiz Garc\u00eda -Emelia, Adriana y Virginia- una al lado de la otras, todas pertenecen a esa generaci\u00f3n que ha vivido el conflicto armado desde chiquitas y siendo adultas emprendieron la tarea de sembrar la paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso, aunque el libro habla de su experiencia personal, Bety P\u00e9rez L\u00f3pez dice que Mujer Triqui es un homenaje a todas las mujeres, ni\u00f1as y adultas, que vivieron aquellos dif\u00edciles a\u00f1os de los setenta, ochenta y noventa, cuando el conflicto armado atraves\u00f3 sus vidas, como hoy a\u00fan las toca y lastima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mujeres a las que la autora de Mujer Triqui llama protectoras, porque siempre estuvieron a su lado, desde su abuela, su madre, una t\u00eda y las amigas que caminaron con ella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDesde que estaba en el internado me di cuenta de que el conflicto armado no s\u00f3lo afectaba a mi familia, porque mi pap\u00e1 Juan Domingo, hab\u00eda fundado el Movimiento de Unificaci\u00f3n de Lucha Triqui (MULT) cuyo nombre afirma fue sugerido por la antrop\u00f3loga Carolina Verduzgo, quien siendo muy joven lleg\u00f3 a la zona triqui para integrarse al proyecto del R\u00edo Balsas, que impuls\u00f3 el general L\u00e1zaro C\u00e1rdenas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juan Domingo y otros j\u00f3venes de los a\u00f1os setenta alzaron la voz y se organizaron, all\u00e1 donde nadie los pod\u00eda escuchar, en los cerros, \u00abya no queremos m\u00e1s saqueos, no queremos que se sigan llevando nuestros recursos, no queremos seguir endeud\u00e1ndonos\u201d, por eso decidieron hacer frente a los cacicazgos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, explica Bety P\u00e9rez, hubo una respuesta por parte del Estado mexicano quien envi\u00f3 a soldados a combatirlos, el nombre de su padre encabezaba la lista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La naci\u00f3n Triqui tiene muchos a\u00f1os inmersa en un conflicto que fue provocado desde afuera, desde el Estado, nos despojaron del territorio, a veces la comunidad se enteraba cuando la tierra ya ten\u00eda otros propietarios, que se adue\u00f1aban de los recursos naturales, como la madera para entregarla a la industria papelera, algo que la comunidad ni siquiera sab\u00eda, tambi\u00e9n hicieron lo mismo con el \u201coro verde\u201d el caf\u00e9 que se produc\u00eda en San Juan Copala y que compraban, a un bajo precio, en Putla Villa de Guerrero, donde como en los tiempos del porfiriato los triquis eran obligados a endeudarse en las tiendas de raya en pleno siglo XX.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caciques y un rancio priismo se aprovechaban del pueblo triqui en lo econ\u00f3mico y en lo pol\u00edtico, no s\u00f3lo les robaban, tambi\u00e9n impon\u00edan a quien deb\u00eda ser la autoridad y \u00e9ste a su vez deb\u00eda responder a los caciques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La intromisi\u00f3n y la pretensi\u00f3n de mantener al pueblo sometido afect\u00f3 a muchas familias, incluso lleg\u00f3 a dividirlos. Conocimos la violencia que se hab\u00eda entreverado, era cotidiana, y lo entendimos cuando entre nosotras cont\u00e1bamos las historias que hab\u00edamos visto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hombres amarrados y golpeados, que los hac\u00edan caminar para exhibidos, para que el pueblo entendiera lo que les pod\u00eda pasar; colgados, asesinados\u2026 es como dice la contraportada del libro: \u201cEn las monta\u00f1as de Oaxaca hay una guerra de medio siglo, ignorada por millones\u2026justo ah\u00ed naci\u00f3 una historia de resistencia y dignidad inquebrantable\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo otro que las ni\u00f1as de primaria y despu\u00e9s en secundaria aprendieron es que la violencia contra las mujeres no era igual que en el caso de los hombres. Si a una mujer la deten\u00edan era muy probable que sufriera una violaci\u00f3n sexual. Est\u00e1bamos aterradas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi vida feliz en el huerto de la casa, los d\u00edas de jugar en el agua del r\u00edo se hab\u00edan terminado cuando el pueblo decidi\u00f3 no permitir m\u00e1s el sometimiento, la explotaci\u00f3n, la violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por a\u00f1os Bety P\u00e9rez L\u00f3pez bloque\u00f3 de su memoria un episodio que la marc\u00f3 siendo una ni\u00f1a y que volvi\u00f3 cuando tuvo que escribir el libro, al que ahora dedica tiempo para promocionarlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando termin\u00f3, sinti\u00f3 un desahogo. La peque\u00f1a familia iba a ver a Juan Dom\u00edngo que se encontraba entre trabajando y escondido en Yosoyuxi. Antes de salir, Sof\u00eda, su madre, le dijo a Bety que ten\u00eda nueve o diez a\u00f1os, que en el camino hab\u00eda un ret\u00e9n de soldados, le explic\u00f3 que si la deten\u00edan deb\u00eda hacerse cargo de su hermita Emma de tres a\u00f1os y del nene que ten\u00eda apenas unos meses. La ni\u00f1a apenas entendi\u00f3. A mitad del camino encontraron el ret\u00e9n, su madre le pas\u00f3 al peque\u00f1o y se lo amarr\u00f3 con el rebozo a la espalda. Ya sabes lo que tienes que hacer, le agreg\u00f3 la maestra Sof\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bety, adem\u00e1s, deb\u00eda estar atenta a la se\u00f1al que le har\u00eda su mam\u00e1. Si ten\u00eda que salir corriendo de regreso a Copala para avisarle a la abuelita que su mam\u00e1 se hab\u00eda quedado en el ret\u00e9n y que los soldados y enemigos de su padre, lo estaban buscando para matarlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi mam\u00e1, dice Bety me estaba diciendo \u201cno quiero que mis hijos presencien un acto de violencia contra mi y nos estaba ordenando \u00a1v\u00e1yanse, salven su vida!\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La peque\u00f1ita entendi\u00f3 que su madre y su padre estaban en peligro real. \u201cAhora lo tengo m\u00e1s claro, no quer\u00edamos encontrarnos ning\u00fan ret\u00e9n, aprendimos que pod\u00edan desaparecer a tu familia, torturar, asesinar o violar a las mujeres\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el fondo sab\u00eda que algo pod\u00eda pasarle a mi mam\u00e1 y quiz\u00e1 tambi\u00e9n a mi pap\u00e1 y yo en medio de todo, me voy a quedar sola con mi hermanito y mi hermana, ten\u00eda que avisar. En ese momento me acord\u00e9 de que mi pap\u00e1 siempre me dec\u00eda, \u201ccuando yo no est\u00e9, va a estar t\u00fa mam\u00e1, pero cuando no est\u00e9 ni ella ni yo, tendr\u00e1s que hacerte cargo t\u00fa, pero nunca estar\u00e1s sola, tienes familia y hasta hoy nunca me he sentido sola, me han protegido las otras mujeres, mi familia\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por suerte, la ni\u00f1a que hab\u00eda empezado a correr jalando a la peque\u00f1a Emma y cargado en su espalada a su hermanito Juan, pero algo, dice, se lo imped\u00eda, no quer\u00eda dejar sola a su mam\u00e1 con todos los soldados, pero quer\u00eda salvar a su pap\u00e1, pero fue alcanzada por su madre quien hab\u00eda librado a los soldados tras un interrogatorio. Juntos caminaron entre el monte, casi al amanecer se encontraron con su pap\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la Triqui aplicaron aquello de \u201cdivide y vencer\u00e1s\u201d, crearon diferencias internas que hasta el d\u00eda hoy tenemos y que ha originado muchas tragedias desde el desplazamiento forzado hasta los asesinatos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchas veces est\u00e1s j\u00f3venes ya adolescentes se organizaron para aprender a curar heridos porque en Copala no hab\u00eda Centro de Salud, hab\u00eda que enviar a las personas hasta el hospital de Putla o Oaxaca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La paz un anhelo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Somos una generaci\u00f3n que desde muy j\u00f3venes empezamos a hablar sobre lo que nos une como pueblo y nos une la comida, nuestra fiesta, por eso decidimos aprovechar la fiesta de Tatach\u00fa, pap\u00e1 Jes\u00fas, es nuestro Santo, como la Virgen de Guadalupe es a todo el pa\u00eds. Igual Tatach\u00fa es muy milagroso y hoy est\u00e1 en otros lugares como Guerrero, Michoac\u00e1n, Puebla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su fiesta re\u00fane a todo el pueblo, en el atrio nuestros sanadores y sanadoras hacen limpias para que toda la energ\u00eda mala se vaya, as\u00ed que hace a\u00f1os decidimos aprovechar ese momento, porque entonces nadie ataca a nadie, era un momento de aprovechar las tradiciones y que nuestra cultura fuera una semilla de paz, as\u00ed naci\u00f3 el primer encuentro de la cultura triqui en San Juan Copala. Bety recuerda el activismo de Emelia y Adriana en esta tarea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin duda, lograrlo fue un primer acuerdo, por primera vez las organizaciones se sentaron a dialogar y el sacerdote fue el mediador, fuimos quienes nacimos y crecimos en medio del conflicto quienes buscamos la paz, hemos planteado que debemos tener una forma diferente de vivir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed, dice Bety P\u00e9rez L\u00f3pez, autora de Mujer Triqui, estamos hablando de esa guerra de medio siglo que ha sido ignorada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHasta el d\u00eda de hoy, el conflicto armado de Copala no se ha resuelto\u201d, escribe Bety al final del libro, donde reafirma el compromiso de su generaci\u00f3n de construir la paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/sj<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/MUJER-TRIQUI-.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"1280\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/MUJER-TRIQUI-.jpeg\" alt=\"\" class=\"wp-image-103419\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/MUJER-TRIQUI-.jpeg 720w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/MUJER-TRIQUI--169x300.jpeg 169w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/MUJER-TRIQUI--576x1024.jpeg 576w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/MUJER-TRIQUI--150x267.jpeg 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/MUJER-TRIQUI--300x533.jpeg 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/03\/MUJER-TRIQUI--696x1237.jpeg 696w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Soledad Jarqu\u00edn Edgar SemM\u00e9xico, Oaxaca, 6 de febrero, 2026.- Beatriz P\u00e9rez L\u00f3pez es una mujer que vivi\u00f3 desde ni\u00f1a el \u201cconflicto\u201d de la naci\u00f3n triqui, su libro Mujer Triqui, una vida construyendo la paz (Grijabo, 2025) es la versi\u00f3n de la historia contada por una mujer, que vivi\u00f3 en carne propia la violencia feminicida. Su [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":103421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[748],"tags":[],"class_list":["post-103418","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura-feminista"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/103418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=103418"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/103418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/103421"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=103418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=103418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=103418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}