{"id":103363,"date":"2026-03-06T17:04:28","date_gmt":"2026-03-06T23:04:28","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=103363"},"modified":"2026-03-06T17:04:45","modified_gmt":"2026-03-06T23:04:45","slug":"esos-restos-no-los-colocamos-estaban-ahi-hubo-muerte-dolor-y-silencio","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/esos-restos-no-los-colocamos-estaban-ahi-hubo-muerte-dolor-y-silencio\/","title":{"rendered":"Esos restos no los colocamos, estaban ah\u00ed; hubo muerte, dolor y silencio"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>Hace un a\u00f1o descubri\u00f3 el rancho Izaguirre, de\u00a0Teuchitl\u00e1n<\/li>\n\n\n\n<li>Muestran un video que revela un escenario escalofriante<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Elizabeth Ibal<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/El Sol de M\u00e9xico, Guadalajara, 6 de marzo, 2026.- El colectivo Guerreros Buscadores de Jalisco&nbsp;que hace un a\u00f1o descubri\u00f3 el rancho Izaguirre, de&nbsp;Teuchitl\u00e1n, revel\u00f3 un video de aquel 3 de marzo, en el que llegaron y encontraron un escenario escalofriante al descubrir que el lugar era usado para el reclutamiento de&nbsp;sicarios&nbsp;para el cartel&nbsp;Jalisco Nueva Generaci\u00f3n,&nbsp;adem\u00e1s que hab\u00eda cientos de prendas que despu\u00e9s fueron reconocidas por familiares de personas desaparecidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las im\u00e1genes de hace un a\u00f1o se observa que llegaron y en principio hicieron oraci\u00f3n con la intenci\u00f3n de poder dar con el paradero de alg\u00fan desaparecido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Encontraron tierra removida, por horas estuvieron cerniendo la tierra hasta que encontraron lo que la autoridad fue incapaz:&nbsp;segmentos \u00f3seos inhumados&nbsp;de forma&nbsp;clandestina&nbsp;y hasta carbonizados, al igual que casquillos de armas de grueso calibre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n implementos bajo el sol para el&nbsp;adiestramiento, se\u00f1alamientos tapizados de orificios causados por proyectiles de&nbsp;arma de fuego.&nbsp;Todo pone en evidencia el tipo de actividades que se desarrollaban en el interior de ese rancho ubicado a 52 kil\u00f3metros al Poniente del Centro de Guadalajara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cumplirse el primer a\u00f1o de ese hallazgo en el colectivo acompa\u00f1\u00f3 el video por un texto en el que se\u00f1al\u00f3 que jam\u00e1s lo van a olvidar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abHace un a\u00f1o entramos a un lugar que jam\u00e1s vamos a olvidar.&nbsp;Hoy compartimos un video que no hab\u00edamos publicado antes. En \u00e9l se ve el momento en que ingresamos al&nbsp;Rancho Izaguirre&nbsp;y c\u00f3mo comenzamos a encontrar lo que nadie deber\u00eda encontrar: huesos calcinados y restos humanos entre la tierra. Esos restos no los colocamos nosotros. Estaban ah\u00ed, ocultos bajo el suelo.&nbsp;A\u00fan se nos eriza la piel al recordar ese momento\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n exigi\u00f3 una&nbsp;investigaci\u00f3n&nbsp;que revele lo que realmente sucedi\u00f3 en ese rancho descubierto de manera inicial por la guardia nacional el 18 de septiembre de 2024 por la Guardia Nacional tras un enfrentamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese lugar muchas personas perdieron la vida. No fue solamente un sitio de adiestramiento o reclutamiento. En ese rancho hubo muerte, dolor y silencio. A un a\u00f1o de ese hallazgo, seguimos exigiendo lo mismo que desde el primer d\u00eda: verdad, investigaci\u00f3n y justicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El colectivo que reci\u00e9n cumpli\u00f3&nbsp;dos a\u00f1os&nbsp;de existencia explic\u00f3 que las familias merecen saber qu\u00e9 pas\u00f3 porque detr\u00e1s de cada resto encontrado hay una historia, una familia y una ausencia que sigue esperando respuestas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De la misma manera exigieron informaci\u00f3n de qu\u00e9 es lo que se ha recabado como parte de la carpeta de investigaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEl&nbsp;Rancho Izaguirre&nbsp;no se olvida. Fiscal\u00eda General de la Rep\u00fablica,&nbsp;Claudia Sheinbaum Pardo; Fiscal\u00eda del Estado de Jalisco, Pablo Lemus Navarro, exigimos tambi\u00e9n la informaci\u00f3n de lo recabado en la investigaci\u00f3n que hicieron ustedes, Comisi\u00f3n Nacional de los Derechos Humanos (CNDH) d\u00f3nde qued\u00f3 lo que sus peritos y visitadores recabaron de informaci\u00f3n en esa carpeta\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta ahora no hay ninguna postura por parte de las autoridades respecto del posicionamiento, ni a un a\u00f1o del hallazgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM-El Sol de M\u00e9xico\/ei<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elizabeth Ibal SemM\u00e9xico\/El Sol de M\u00e9xico, Guadalajara, 6 de marzo, 2026.- El colectivo Guerreros Buscadores de Jalisco&nbsp;que hace un a\u00f1o descubri\u00f3 el rancho Izaguirre, de&nbsp;Teuchitl\u00e1n, revel\u00f3 un video de aquel 3 de marzo, en el que llegaron y encontraron un escenario escalofriante al descubrir que el lugar era usado para el reclutamiento de&nbsp;sicarios&nbsp;para el cartel&nbsp;Jalisco [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":103364,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[48],"tags":[],"class_list":["post-103363","post","type-post","status-publish","format-standard","has-post-thumbnail","category-no-mas-impunidad-no-mas-impunidad"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/103363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=103363"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/103363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/103364"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=103363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=103363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=103363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}