{"id":102929,"date":"2026-02-23T19:33:56","date_gmt":"2026-02-24T01:33:56","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=102929"},"modified":"2026-02-23T19:52:02","modified_gmt":"2026-02-24T01:52:02","slug":"cita-de-el-mencho-con-su-pareja-fue-clave-para-operativo","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/cita-de-el-mencho-con-su-pareja-fue-clave-para-operativo\/","title":{"rendered":"Cita de El Mencho con su pareja fue clave para operativo"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>As\u00ed fue la operaci\u00f3n militar contra el l\u00edder del CJNG<\/li>\n\n\n\n<li>El secretario de la Defensa explic\u00f3 c\u00f3mo fue el operativo<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alejandro Su\u00e1rez<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/El Sol de M\u00e9xico, Ciudad de M\u00e9xico, 23 de febrero, 2026.-&nbsp; La ubicaci\u00f3n y seguimiento de<strong>&nbsp;uno de los hombres de confianza de la pareja sentimental de Nemesio Oseguera<\/strong>&nbsp;fue lo que deton\u00f3 el operativo en el que muri\u00f3<a href=\"https:\/\/oem.com.mx\/elsoldemexico\/mexico\/de-policia-a-lider-del-cjng-nemesio-oseguera-el-mencho-construyo-el-cartel-mas-sanguinario-de-mexico-28605551.app.json\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;<strong>El Mencho<\/strong><\/a>, explic\u00f3 el general Ricardo Trevilla, secretario de la Defensa Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la conferencia de prensa de Palacio Nacional, Trevilla coment\u00f3 que el 20 de febrero, personal de<a href=\"https:\/\/oem.com.mx\/elsoldemexico\/mexico\/nuevo-grupo-liderado-por-militares-de-eu-ayudo-en-la-busqueda-de-el-mencho-28610765.app.json\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;<strong>inteligencia militar<\/strong><\/a>&nbsp;ubic\u00f3 a esta persona cerca del poblado de Tapalpa, Jalisco, por lo que se dio seguimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 21 de febrero, se confirm\u00f3 que esta persona se reunir\u00eda con El Mencho en una caba\u00f1a de Tapalpa, por lo que comenz\u00f3 la planeaci\u00f3n del&nbsp;<a href=\"https:\/\/oem.com.mx\/elsoldemexico\/mexico\/fuerzas-federales-abaten-a-el-mencho-lider-del-cjng-en-jalisco-28604485\" target=\"_blank\" rel=\"noreferrer noopener\">operativo<\/a>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El secretario dijo que lo primero fue organizar grupos, uno de<strong>&nbsp;Fuerzas Especiales del Ej\u00e9rcito,<\/strong>&nbsp;otro de la&nbsp;<strong>Guardia Nacional<\/strong>&nbsp;y un tercero de la&nbsp;<strong>Fuerza A\u00e9rea<\/strong>. Todo este personal no lleg\u00f3 de inmediato a Jalisco, sino a entidades vecinas, para evitar poner en alerta al grupo delictivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La madrugada del domingo 22 de febrero, cuando se tuvo la certeza de que El Mencho se encontraba en esta caba\u00f1a, inici\u00f3 el operativo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al percatarse de la presencia de los militares, los<strong>&nbsp;escoltas del l\u00edder del&nbsp;<\/strong><a href=\"https:\/\/oem.com.mx\/elsoldemexico\/mexico\/de-el-03-a-el-jardinero-quienes-son-los-cinco-posibles-sucesores-de-el-mencho-dentro-del-cjng-28609110.app.json\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>C\u00e1rtel Jalisco Nueva Generaci\u00f3n<\/strong><\/a><strong>&nbsp;comenzaron a dispararles<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAbre fuego el personal de seguridad El Mencho contra el personal militar, El Mencho sale, dejan a un grupo con una gran cantidad de armas, realmente fue un&nbsp;<a href=\"https:\/\/oem.com.mx\/elsoldemexico\/mexico\/operativo-contra-el-mencho-dejo-mas-de-60-muertos-25-fueron-elementos-de-la-guardia-nacional-28620541.app.json\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>ataque muy violento<\/strong><\/a>&nbsp;el que realiz\u00f3 el personal de la delincuencia organizada, y el personal militar de Fuerzas Especiales repele la acci\u00f3n.&nbsp;<strong>Fallecen ah\u00ed ocho delincuentes<\/strong>\u201d, dijo Trevilla al actualizar el n\u00famero de fallecidos en el operativo del domingo, ya que en primera instancia se reportaron cuatro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras ocurr\u00eda este primer enfrentamiento,&nbsp;<strong>El Mencho y su c\u00edrculo cercano escapan a una zona boscosa<\/strong>, pero el personal militar despleg\u00f3 un&nbsp;<strong>cerco para evitar su huida.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al ver que se acercaban los elementos militares,&nbsp;<strong>los delincuentes volvieron a disparar contra los militares<\/strong>, y lograron impactar un helic\u00f3ptero del Ej\u00e9rcito que tuvo que&nbsp;<strong>aterrizar de emergencia en una base en Sayula, Jalisco<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c(Fuerzas Especiales) lo ubican en la maleza (a El Mencho), ellos hacen fuego contra las Fuerzas Especiales, llevaban&nbsp;<strong>lanzacohetes<\/strong>, debido a la presi\u00f3n no los usaron afortunadamente; sin embargo, s\u00ed impactaron a una fuerza aerom\u00f3vil. Este helic\u00f3ptero se vio obligado a realizar un aterrizaje de emergencia en una instalaci\u00f3n militar cercana, en Sayula, Jalisco, ah\u00ed es donde aterriza, afortunadamente&nbsp;<strong>no hubo personal militar herido<\/strong>\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante este intercambio de balazos,&nbsp;<strong>Nemesio Oseguera y dos de sus escoltas resultan heridos,<\/strong>&nbsp;y otros dos delincuentes fueron detenidos, coment\u00f3 el secretario de la Defensa. quien a\u00f1adi\u00f3 que&nbsp;<strong>tres militares resultaron heridos en el operativo<\/strong>, dos en la caba\u00f1a y otro en el ataque de los escoltas de El Mencho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cUna vez que se control\u00f3 la situaci\u00f3n el personal de sanidad militar acude al lugar donde se encontraba El Mencho y sus dos escoltas heridos, determina que era necesario evacuarlos,<strong>&nbsp;estaban muy graves<\/strong>, se pide el apoyo de un helic\u00f3ptero para que sean trasladados a una instituci\u00f3n m\u00e9dica en Jalisco, y<strong>&nbsp;se traslada a El Mencho, sus dos escoltas y el oficial herido<\/strong>, desafortunadamente fallece (Oseguera) en el trayecto\u201d, coment\u00f3 Trevilla en la conferencia de prensa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de la muerte de El Mencho, a\u00f1adi\u00f3 el general, se decide que el cuerpo no llegue a ninguna ciudad de Jalisco, sino a otro estado por cuestiones de seguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn ese momento se decide que&nbsp;<strong>el helic\u00f3ptero se traslade al aeropuerto de Morelia, en donde estaba un avi\u00f3n caza de la Fuerza A\u00e9rea.<\/strong>&nbsp;Llegan ah\u00ed, lo trasladan al avi\u00f3n caza y&nbsp;<strong>ese avi\u00f3n caza se traslada a la Ciudad de M\u00e9xico<\/strong>. Esto se decidi\u00f3 porque&nbsp;<strong>no era conveniente llegar a Guadalajara por el riesgo<\/strong>&nbsp;de que este grupo delictivo hiciera acciones m\u00e1s violentas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s tarde, en la conferencia de prensa, el secretario de Seguridad y Protecci\u00f3n Ciudadana, Omar Garc\u00eda Harfuch, inform\u00f3 que la Fiscal\u00eda General de la Rep\u00fablica ya<strong>&nbsp;confirm\u00f3 la identidad del cuerpo&nbsp;<\/strong>de Nemesio Oseguera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, el general Trevilla dijo que en otro operativo<strong>&nbsp;se abati\u00f3 a Hugo N, alias El Tuli, uno de los hombres de confianza de El Mencho<\/strong>, y quien ayer estaba&nbsp;<strong>organizando<\/strong><a href=\"https:\/\/oem.com.mx\/elsoldemexico\/mexico\/caida-de-el-mencho-provoco-252-bloqueos-en-mas-del-60-del-pais-28615726.app.json\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>&nbsp;bloqueos carreteros y ataques<\/strong><\/a><strong>&nbsp;contra miembros de las fuerzas armadas.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM-El Sol de M\u00e9xico\/as<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/EL-MENCHO-2.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/EL-MENCHO-2-1024x576.webp\" alt=\"\" class=\"wp-image-102931\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/EL-MENCHO-2-1024x576.webp 1024w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/EL-MENCHO-2-300x169.webp 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/EL-MENCHO-2-768x432.webp 768w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/EL-MENCHO-2-150x84.webp 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/EL-MENCHO-2-696x392.webp 696w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/EL-MENCHO-2-1068x601.webp 1068w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/EL-MENCHO-2.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Alejandro Su\u00e1rez SemM\u00e9xico\/El Sol de M\u00e9xico, Ciudad de M\u00e9xico, 23 de febrero, 2026.-&nbsp; La ubicaci\u00f3n y seguimiento de&nbsp;uno de los hombres de confianza de la pareja sentimental de Nemesio Oseguera&nbsp;fue lo que deton\u00f3 el operativo en el que muri\u00f3&nbsp;El Mencho, explic\u00f3 el general Ricardo Trevilla, secretario de la Defensa Nacional. Durante la conferencia de prensa [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":102930,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[682],"tags":[],"class_list":["post-102929","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/102929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=102929"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/102929\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/102930"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=102929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=102929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=102929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}