{"id":10288,"date":"2019-07-30T01:22:25","date_gmt":"2019-07-30T01:22:25","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=10288"},"modified":"2023-07-21T14:51:16","modified_gmt":"2023-07-21T19:51:16","slug":"guerrero-4","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/guerrero-4\/","title":{"rendered":"Exigen que el Congreso de Guerrero apruebe la Ley Olimpia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">* <strong>Protestan por exhibici\u00f3n de videos \u00edntimos de una servidora p\u00fablica<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">* <strong>En esa entidad hay 97 mercados de explotaci\u00f3n digital<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Josefina Aguilar Pastor <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Chilpancingo,\nGro., 29 julio 2019.- Mujeres que militan en Morena- Acapulco, exigieron al\nCongreso del Estado agilizar la aprobaci\u00f3n de la \u201cLey Olimpia\u201d para frenar la\nviolencia digital en Guerrero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yolox\u00f3chitl \u00c1vila\nAlcaraz, presidenta de Acci\u00f3n Femenil de la Asociaci\u00f3n&nbsp; \u201cAcapulco nos Necesita\u201d, acompa\u00f1ada de otras\nmilitantes de Morena, salieron a manifestar su total apoyo a Tania S\u00e1mano, directora de Catastro\nMunicipal, de quien en d\u00edas pasados, circul\u00f3\nun video con contenido \u00edntimo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Olimpia\nCoral Melo Cruz, impulsora de la llamada \u201cLey Olimpia\u201d, ha se\u00f1alado que en\nGuerrero, existen 97 mercados de\nexplotaci\u00f3n digital, que difunden sin consentimiento, ocho mil videos de\nmujeres y no son solo videos sexuales de pareja, sino incuso de madres\namantando. De cada 100 mujeres y ni\u00f1as, 87 sufren acoso a graves de las redes\nsociales, document\u00f3 Yolox\u00f3chitl \u00c1vila, al expresar su indignaci\u00f3n ante la\nexhibici\u00f3n de la funcionaria p\u00fablica municipal, militante tambi\u00e9n de su\npartido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNosotras,\nmujeres como ella queremos que sepa que no est\u00e1 sola que, si tocan a una, nos\ntocan a todas, y hoy estamos aqu\u00ed para manifestarle a ella nuestro apoyo y para\nexigir al Congreso del estado que apruebe a ley Olimpia\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las\nmujeres de Morena, indic\u00f3, exigen la inmediata aprobaci\u00f3n de la ley Olimpia,\nque comprende la tipificaci\u00f3n del ciberacoso, castig\u00f3 a la difusi\u00f3n de\ncontenidos \u00edntimos y violencia digital, as\u00ed como la reforma al c\u00f3digo penal,\ncon penas de cinco a 12 a\u00f1os de c\u00e1rcel a quienes realicen estas pr\u00e1cticas. La\niniciativa es impulsada en Guerrero por las diputadas Norma Otilia Hern\u00e1ndez\nMart\u00ednez, Mariana Itallitzin Garc\u00eda Guillen y Erika Valencia Cardona, desde\nhace ya varios meses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La\niniciativa se encuentra detenida en la Comisi\u00f3n de Justicia que preside el\ndiputado local priista, Omar Jalil Flores Majul, \u201cy no entendemos la raz\u00f3n por\nla cual a\u00fan no ha sido aprobada esta ley\u201d, recalc\u00f3 la conferencista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c1vila Alcaraz\nexigi\u00f3 tambi\u00e9n la reparaci\u00f3n completa para la funcionaria municipal, dijo que\nlas mujeres no son propiedad de nadie, sus acciones son solo propiedad de ellas\nmismas, su vida profesional y salud mental no deben ser ultrajadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cExigimos que\nnuestro espacio digital ya no sea violentado y que Guerrero sea de inmediato,\nel sexto estado capaz de castigar, este tipo de violencia contra las mujeres\u201d,\nexpuso Yolox\u00f3chitl \u00c1vila, quien destac\u00f3 que esta ley no solo beneficiar\u00e1 a las\nmujeres, sino a todas las personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La \u201cLey Olimpia\u201d,\nya ha sido aprobada en Puebla (diciembre de 2018); Coahuila (junio de 2019),\nChiapas (marzo 2019), y en este mes de julio en Oaxaca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/jap\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Protestan por exhibici\u00f3n de videos \u00edntimos de una servidora p\u00fablica<\/p>\n","protected":false},"author":3,"featured_media":10289,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,54],"tags":[],"class_list":["post-10288","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-mujeres"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/10288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=10288"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/10288\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/10289"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=10288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=10288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=10288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}