{"id":102803,"date":"2026-02-18T14:22:21","date_gmt":"2026-02-18T20:22:21","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=102803"},"modified":"2026-02-18T14:22:22","modified_gmt":"2026-02-18T20:22:22","slug":"opinion-sin-corbata","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/opinion-sin-corbata\/","title":{"rendered":"Opini\u00f3n | Sin Corbata"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&nbsp;David Mart\u00edn del Campo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cuernavaca, Morelos, 18 de febrero, 2024.-La idea fue de Jaime Torres Bodet, luego de conversar con el candidato electo, Adolfo L\u00f3pez Mateos. Hacer libros para todos los ni\u00f1os y ni\u00f1as&nbsp; de M\u00e9xico, atractivos, gratuitos, instructivos. As\u00ed en 1959, luego de creada la Comisi\u00f3n Nacional del Libro de Texto Gratuito, fue publicado el inaugural de ellos: \u201cMi libro de Primer A\u00f1o\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La leyenda cuenta que don Adolfo, cuando ni\u00f1o, no ten\u00eda libro escolar y era la burla (como siempre) de sus compa\u00f1eritos del sal\u00f3n de clases. Despu\u00e9s de su aciaga participaci\u00f3n como orador en la campa\u00f1a presidencial de Jos\u00e9 Vasconcelos, despu\u00e9s de su trashumante peregrinaje hasta la hacienda en Chiapas donde viv\u00eda su verdadero padre \u2013don Gonzalo de Murga\u2013, despu\u00e9s de sobresalir como senador y como ministro de Trabajo, L\u00f3pez Mateos fue electo presidente de la Rep\u00fablica. Cuentan que se emocion\u00f3 hasta la l\u00e1grimas al tener en las manos aquel primer ejemplar, en cuya portada luc\u00eda el retrato de La Patria, \u00f3leo de Jorge Gonz\u00e1lez Camarena.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy el retrato de Carlos Marx luce en el escritorio de su hom\u00f3nimo, Marx Arriaga, ex director de Producci\u00f3n Editorial en la SEP. Es cosa de revisar las fotograf\u00edas de prensa. De ese modo, el capit\u00e1n de los libros gratuitos que reciben los ni\u00f1os en M\u00e9xico, se precia de ser coautor de la Nueva Escuela Mexicana, que se ha impuesto desde diciembre de 2018.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quien revise los libros de texto hoy vigentes, comparados con los editados en d\u00e9cadas anteriores, se podr\u00eda ir de espaldas. El \u00e1nimo por la formaci\u00f3n y el aprendizaje (cient\u00edfico) se ha puesto de lado en beneficio de la instrumentaci\u00f3n ideol\u00f3gica. En el libro de Cuarto A\u00f1o, por ejemplo, asoma el dibujo de un caballero elegante, trajeado, sobre el cual hay una voluta de rayones, elimin\u00e1ndolo, sobre una leyenda que dice: \u201cLas personas que llevan corbata son desconfiables\u201d. As\u00ed nom\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora que don Marx Arriaga ha sido despedido de su puesto, sin embargo, se asegura que no habr\u00e1 cambios en el contenido de los libros producidos por la Conaliteg, si acaso ser\u00e1n incorporados temas de las mujeres y las comunidades ind\u00edgenas del pa\u00eds. Y como don Marx Arriaga no se quiere ir de su trinchera\u2026 perd\u00f3n, de su oficina, ha emprendido una campa\u00f1a para salvar el puesto, aduciendo que las fuerzas neoliberales, en connivencia con el titular de la SEP, Mario Delgado, est\u00e1n confabuladas contra \u00e9l y la \u201crevoluci\u00f3n educativa\u201d que encabezaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para quienes hayan le\u00eddo el Manifiesto Comunista, recordar\u00e1n que tesis fundamental del volumen es aquella donde se afirma que \u201cLa historia del mundo es la historia de la lucha de clases\u201d. En ese volumen, escrito emparejadamente por Federico Engels y Carlos Marx (el verdadero), asoma la primera frase de terror c\u00edvico: \u201cUn fantasma recorre Europa, es el fantasma del comunismo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed ahora, en la cr\u00f3nica que podr\u00eda escribirse desde el sexto piso de la SEP (donde el licenciado Arriaga permanece atrincherado), asomar\u00eda la sentencia: \u201cUn fantasma recorre la SEP, es el mismo que vaga por Palacio Nacional\u201d. Cosa de esperar c\u00f3mo se desenvuelve el desaguisado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los precedentes pol\u00edticos que confluyeron en la integraci\u00f3n del PRD \u2013luego Morena\u2013, fueron partidos de apellido hist\u00f3rico: Popular Socialista, Socialista Unificado (antes PCM), Mexicano de los Trabajadores, \u201cTendencia democr\u00e1tica\u201d del PRI. Todos tildados de izquierda, asumiendo el marxismo como principio motor de su lucha, que era (y es) la de los desheredados del mundo. Recu\u00e9rdense las pueriles pancartas asomando en las dos campa\u00f1as electorales de Cuauht\u00e9moc C\u00e1rdenas\u2026 Carlos Marx, Federico Engels, Joseph Stalin, junto a las im\u00e1genes de la Virgen de Guadalupe. O sea, el que se daba en llamar \u201cmarxismo guadalupano\u201d, del que hoy disfrutamos sus consecuencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La revoluci\u00f3n proletaria requiere de conciencia, militancia, adoctrinamiento. As\u00ed fue en la Rusia zarista de 1917, as\u00ed fue en Cuba despu\u00e9s del 16 de abril de 1961, cuando la Declaraci\u00f3n de La Habana. No es ning\u00fan secreto, en esa visi\u00f3n del mundo lo primordial es azuzar la \u201clucha de clases\u201d\u2026 esclavos vs. patricios, siervos vs. hacendados, proletarios vs. capitalistas, y ahora \u201cel pueblo bueno\u201d vs. neoliberales. En ese sentido es como deben ser entendidos los nuevos libros de texto, bendecidos por don Marx Arriaga, para concientizar a las masas. Al fin que los encorbatados \u2013del Banco de M\u00e9xico y del Grupo Monterrey\u2013 son del todo desconfiables, y merecen ser tachonados a golpes de cray\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada quien se llama como quiere (o como puede). Las Guadalupes son adeptas a la Virgen que apareci\u00f3 en el Tepeyac, los Benitos son disc\u00edpulos del Benem\u00e9rito, los Brandon del mundo son pros\u00e9litos del tosco Marlon de las pel\u00edculas. As\u00ed nuestro (Carlos) Marx defendiendo la barricada del sexto piso\u2026 \u00bfpor qu\u00e9 ese nombre tan hist\u00f3rico? \u00bfDe qu\u00e9 se hablaba en la sobremesa familiar? \u00bfDe princesas y castillos, del canto de Filippa Giordano? Me parece que no mucho, aunque s\u00ed de incendiar corbatas, tan inc\u00f3modas por cierto.&nbsp; &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;David Mart\u00edn del Campo SemM\u00e9xico, Cuernavaca, Morelos, 18 de febrero, 2024.-La idea fue de Jaime Torres Bodet, luego de conversar con el candidato electo, Adolfo L\u00f3pez Mateos. Hacer libros para todos los ni\u00f1os y ni\u00f1as&nbsp; de M\u00e9xico, atractivos, gratuitos, instructivos. As\u00ed en 1959, luego de creada la Comisi\u00f3n Nacional del Libro de Texto Gratuito, fue [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":84026,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-102803","post","type-post","status-publish","format-standard","has-post-thumbnail","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/102803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=102803"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/102803\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/84026"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=102803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=102803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=102803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}