{"id":102779,"date":"2026-02-18T10:29:18","date_gmt":"2026-02-18T16:29:18","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=102779"},"modified":"2026-02-18T10:29:19","modified_gmt":"2026-02-18T16:29:19","slug":"comision-avala-dictamen-para-designar-a-cecilia-lopez-perez-como-acreedora-al-reconocimiento-elvia-carrillo-puerto","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/comision-avala-dictamen-para-designar-a-cecilia-lopez-perez-como-acreedora-al-reconocimiento-elvia-carrillo-puerto\/","title":{"rendered":"Comisi\u00f3n avala dictamen para designar a Cecilia L\u00f3pez P\u00e9rez como acreedora al Reconocimiento \u201cElvia Carrillo Puerto\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">De origen tzotzil, L\u00f3pez P\u00e9rez cuenta con m\u00e1s de tres d\u00e9cadas de trayectoria en la defensa de los derechos de las ind\u00edgenas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se entregar\u00e1 el pr\u00f3ximo 8 de marzo en el Senado<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redacci\u00f3n&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 18 de febrero, 2026.-La Comisi\u00f3n para la Igualdad de G\u00e9nero, que preside la senadora Martha Luc\u00eda Micher Camarena, aprob\u00f3 el dictamen por el que se designa a la ciudadana Cecilia L\u00f3pez P\u00e9rez como acreedora al Reconocimiento \u201cElvia Carrillo Puerto\u201d, correspondiente a 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cecilia L\u00f3pez P\u00e9rez es una mujer de la etnia tzotzil, originaria de San Andr\u00e9s Larr\u00e1inzar, Chiapas, con m\u00e1s de tres d\u00e9cadas de trayectoria en la defensa de los derechos de las ind\u00edgenas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre 2011 y 2025 apoy\u00f3 a m\u00e1s de 330 mujeres v\u00edctimas de violencia familiar, sexual, comunitaria e institucional, a trav\u00e9s de la traducci\u00f3n en su lengua natal, seguimiento legal y articulaci\u00f3n interinstitucional, para garantizarles acceso a la justicia con enfoque intercultural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Senado de la Rep\u00fablica entrega el reconocimiento \u201cElvia Carrillo Puerto\u201d en el Marco del D\u00eda Internacional de la Mujer, para reconocer y premiar a mujeres que hayan incidido y destacado en la lucha social, cultural, pol\u00edtica y econ\u00f3mica en favor de los derechos humanos de las mujeres y de la igualdad de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La senadora&nbsp; Micher Camarena reconoci\u00f3 a Cecilia L\u00f3pez P\u00e9rez por su trabajo de m\u00e1s de 30 a\u00f1os en defensa de las mujeres ind\u00edgenas, adem\u00e1s de subrayar que ella, al igual que las otras dos integrantes de la terna, destacan por su trabajo en favor de las mexicanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alejandra Berenice Arias Trevilla, senadora de Morena, destac\u00f3 el origen tzotzil de L\u00f3pez P\u00e9rez, quien, a\u00f1adi\u00f3, ha dejado en alto el nombre de las mujeres ind\u00edgenas, ha combatido las injusticias que enfrentan y le ha dado dignidad a su pueblo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/image-16.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/image-16-1024x683.jpeg\" alt=\"\" class=\"wp-image-102782\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/image-16-1024x683.jpeg 1024w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/image-16-300x200.jpeg 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/image-16-768x512.jpeg 768w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/image-16-150x100.jpeg 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/image-16-696x464.jpeg 696w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/image-16-1068x712.jpeg 1068w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2026\/02\/image-16.jpeg 1447w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El decreto por el que se crea el Reconocimiento \u201cElvia Carrillo Puerto\u201d, publicado en el Diario Oficial de la Federaci\u00f3n, precisa que este galard\u00f3n ser\u00e1 entregado en Ceremonia Solemne en el Senado de la Rep\u00fablica, en conmemoraci\u00f3n del 8 de marzo, D\u00eda Internacional de la Mujer.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Comisi\u00f3n para la Igualdad de G\u00e9nero tambi\u00e9n aprob\u00f3 publicar los nombres y curr\u00edculos de las otras dos integrantes de la terna, a partir de la cual se eligi\u00f3 a la ganadora del Reconocimiento \u00abElvia Carrillo Puerto\u201d, para dar transparencia al procedimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, la senadora Micher Camarena inform\u00f3 que se solicitar\u00e1 a la Mesa Directiva del Senado de la Rep\u00fablica que se programe la entrega del galard\u00f3n en la fecha exacta del D\u00eda Internacional de la Mujer, el 8 de marzo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De origen tzotzil, L\u00f3pez P\u00e9rez cuenta con m\u00e1s de tres d\u00e9cadas de trayectoria en la defensa de los derechos de las ind\u00edgenas Se entregar\u00e1 el pr\u00f3ximo 8 de marzo en el Senado Redacci\u00f3n&nbsp; SemM\u00e9xico, Cd. de M\u00e9xico, 18 de febrero, 2026.-La Comisi\u00f3n para la Igualdad de G\u00e9nero, que preside la senadora Martha Luc\u00eda Micher Camarena, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":102783,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[748],"tags":[],"class_list":["post-102779","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura-feminista"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/102779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=102779"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/102779\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/102783"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=102779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=102779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=102779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}