{"id":102442,"date":"2026-02-02T20:05:49","date_gmt":"2026-02-03T02:05:49","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=102442"},"modified":"2026-02-02T20:05:49","modified_gmt":"2026-02-03T02:05:49","slug":"inicia-este-martes-juicio-final-contra-probable-feminicida-de-estudiante-de-la-umar","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/inicia-este-martes-juicio-final-contra-probable-feminicida-de-estudiante-de-la-umar\/","title":{"rendered":"Inicia este martes juicio final contra probable feminicida de estudiante de la UMAR"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>El delito se cometi\u00f3 en octubre de 2024<\/li>\n\n\n\n<li>El presunto responsable habr\u00eda sido su novio<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Lorena Vaniezcot<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Oaxaca, 2 de febrero, 2026.- Este martes inicia la audiencia de juicio final en contra de Mois\u00e9s N, quien presuntamente cometi\u00f3 el delito de feminicidio agravado en contra de Hiromi D.C., estudiante de la Universidad del Mar, en la costa oaxaque\u00f1a en octubre de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mois\u00e9s N, quien habr\u00eda sido novio de la estudiante de Biolog\u00eda Marina, fue detenido por elementos de la Fiscal\u00eda General del Estado de Oaxaca cuando se encontraba en la ciudad de Oaxaca, en la regi\u00f3n de Valles Centrales, luego de huir desde Puerto \u00c1ngel donde cometi\u00f3 el feminicidio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La joven fue encontrada con signos de estrangulamiento por la propietaria de la casa donde Hiromi D.C. hab\u00eda rentado una habitaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La audiencia final se prev\u00e9 realizar en el Centro de Justicia Manuel Sabino Crespo de Ejutla de Crespo, donde se constituir\u00e1 el tribunal de enjuiciamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/lv\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorena Vaniezcot SemM\u00e9xico, Oaxaca, 2 de febrero, 2026.- Este martes inicia la audiencia de juicio final en contra de Mois\u00e9s N, quien presuntamente cometi\u00f3 el delito de feminicidio agravado en contra de Hiromi D.C., estudiante de la Universidad del Mar, en la costa oaxaque\u00f1a en octubre de 2024. Mois\u00e9s N, quien habr\u00eda sido novio de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":102443,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[48],"tags":[],"class_list":["post-102442","post","type-post","status-publish","format-standard","has-post-thumbnail","category-no-mas-impunidad-no-mas-impunidad"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/102442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=102442"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/102442\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/102443"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=102442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=102442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=102442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}