{"id":102322,"date":"2026-01-30T19:20:06","date_gmt":"2026-01-31T01:20:06","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=102322"},"modified":"2026-01-30T19:20:07","modified_gmt":"2026-01-31T01:20:07","slug":"mas-de-la-mitad-de-los-responsables-de-feminicidios-en-la-cdmx-no-han-sido-detenidos","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/mas-de-la-mitad-de-los-responsables-de-feminicidios-en-la-cdmx-no-han-sido-detenidos\/","title":{"rendered":"M\u00e1s de la mitad de los responsables de feminicidios en la CDMX no han sido detenidos"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>El 93% de los feminicidas son hombres de entre 18 a 93 a\u00f1os de edad<\/li>\n\n\n\n<li>725 de los procesos contin\u00faan abiertos\u00a0sin ning\u00fan responsable detenido<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Dana Estrada<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/El Sol de M\u00e9xico, Ciudad de M\u00e9xico, 30 de enero, 2026.- En los \u00faltimos seis a\u00f1os, de cada 10&nbsp;<a href=\"https:\/\/www.oem.com.mx\/elsoldemexico\/mexico\/secretaria-de-las-mujeres-pide-que-las-muertes-violentas-de-mujeres-sean-investigadas-como-feminicidio-27861271\" target=\"_blank\" rel=\"noreferrer noopener\">feminicidios<\/a>&nbsp;ocurridos en la&nbsp;Ciudad de M\u00e9xico,&nbsp;en seis el responsable de este delito no ha sido detenido, de acuerdo con datos obtenidos a trav\u00e9s de la&nbsp;Plataforma Nacional de Transparencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;Tribunal Superior de Justicia&nbsp;capitalino registr\u00f3 entre 2020 y 2025 un total de mil 290&nbsp;procesos penales&nbsp;por feminicidio. De ellos, 565 casos cuentan con&nbsp;un detenido&nbsp;y 725 contin\u00faan abiertos&nbsp;sin capturar&nbsp;a alg\u00fan responsable, pese a tenerlo&nbsp;identificado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con estos datos, el&nbsp;93 por ciento&nbsp;de los responsables por el&nbsp;<a href=\"https:\/\/oem.com.mx\/elsoldemexico\/mexico\/violencia-familiar-feminicidio-y-violacion-los-principales-delitos-contra-mujeres-27133961\" target=\"_blank\" rel=\"noreferrer noopener\">delito de feminicidio<\/a>&nbsp;en la ciudad han sido&nbsp;hombres&nbsp;de entre 18 y 93 a\u00f1os de edad. Adem\u00e1s, al menos 86 mujeres tambi\u00e9n han sido identificadas como responsables de este delito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/oem.com.mx\/elsoldemexico\/mexico\/secretaria-de-las-mujeres-y-fgr-compartiran-informacion-para-identificar-agresores-27993977\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El feminicida&nbsp;m\u00e1s longevo&nbsp;con el que cuenta el sistema penal de la ciudad es un hombre de&nbsp;93 a\u00f1os&nbsp;de edad quien en julio de 2024 fue detenido por tentativa de homicidio en la alcald\u00eda Iztapalapa, de acuerdo con reportes policiacos, luego de que&nbsp;intent\u00f3 prender fuego&nbsp;a su&nbsp;nieta&nbsp;de 28 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los casos por este&nbsp;delito&nbsp;que se castiga hasta con&nbsp;70 a\u00f1os de prisi\u00f3n&nbsp;han crecido a\u00f1o con a\u00f1o ante el&nbsp;Tribunal de la CDMX.&nbsp;En 2020, este n\u00famero era de 156 investigaciones; para 2021 aument\u00f3 a 200 procesos; en 2022 hubo 265 procesos; un a\u00f1o despu\u00e9s se tuvo una reducci\u00f3n a 258 investigaciones, y en 2024 nuevamente creci\u00f3 a 325 expedientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las alcald\u00edas con&nbsp;mayor incidencia&nbsp;en el periodo de 2020 a 2025 fueron Iztapalapa con 113 casos;&nbsp;Cuauht\u00e9moc&nbsp;con 76;&nbsp;Tlalpan&nbsp;con 64 feminicidios;&nbsp;\u00c1lvaro Obreg\u00f3n&nbsp;con 60 investigaciones;&nbsp;Gustavo A. Madero&nbsp;con 58;&nbsp;Tl\u00e1huac&nbsp;con 40;&nbsp;Venustiano Carranza&nbsp;con 31;&nbsp;Milpa Alta&nbsp;con 28 feminicidios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Coyoac\u00e1n, Azcapotzalco, Benito Ju\u00e1rez, Iztacalco, Miguel Hidalgo, Magdalena Contreras, Xochimilco, y Cuajimalpa reportaron de 24 a 11 feminicidios, por cada alcald\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Tribunal reconoci\u00f3 que&nbsp;663 investigaciones&nbsp;de feminicidio no cuentan con un lugar claro del crimen, es decir el 51 por ciento de los casos registrados en estos \u00faltimos a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n de los&nbsp;mil 290 feminicidios, el 52 por ciento han sido investigados y juzgados como tentativa, es decir, que no se complet\u00f3 el crimen; y el resto de los casos s\u00ed se consumaron, dejando&nbsp;523 asesinatos de mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con la&nbsp;Subsecretar\u00eda del Sistema Penitenciario de la CDMX, el n\u00famero de&nbsp;personas recluidas&nbsp;actualmente en las distintas&nbsp;<a href=\"https:\/\/www.oem.com.mx\/elsoldemexico\/metropoli\/aumenta-poblacion-extranjera-en-carceles-de-la-ciudad-de-mexico-27348905\" target=\"_blank\" rel=\"noreferrer noopener\">c\u00e1rceles<\/a>&nbsp;de la CDMX por este&nbsp;<a href=\"https:\/\/www.oem.com.mx\/elsoldemexico\/mexico\/diciembre-de-2025-registra-la-cifra-de-homicidios-dolosos-mas-baja-desde-2016-27568954\" target=\"_blank\" rel=\"noreferrer noopener\">delito<\/a>&nbsp;es de&nbsp;494 personas. Siendo el n\u00famero m\u00e1s alto en los \u00faltimos cinco a\u00f1os, pues en el 2021 hab\u00eda 211 feminicidas recluidos, de acuerdo con&nbsp;datos obtenidos v\u00eda transparencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM-El Sol de M\u00e9xico\/de<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dana Estrada SemM\u00e9xico\/El Sol de M\u00e9xico, Ciudad de M\u00e9xico, 30 de enero, 2026.- En los \u00faltimos seis a\u00f1os, de cada 10&nbsp;feminicidios&nbsp;ocurridos en la&nbsp;Ciudad de M\u00e9xico,&nbsp;en seis el responsable de este delito no ha sido detenido, de acuerdo con datos obtenidos a trav\u00e9s de la&nbsp;Plataforma Nacional de Transparencia. El&nbsp;Tribunal Superior de Justicia&nbsp;capitalino registr\u00f3 entre 2020 y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":102323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[48],"tags":[],"class_list":["post-102322","post","type-post","status-publish","format-standard","has-post-thumbnail","category-no-mas-impunidad-no-mas-impunidad"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/102322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=102322"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/102322\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/102323"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=102322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=102322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=102322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}