{"id":101892,"date":"2026-01-14T10:30:55","date_gmt":"2026-01-14T16:30:55","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=101892"},"modified":"2026-01-14T10:30:56","modified_gmt":"2026-01-14T16:30:56","slug":"bellas-y-airosas-yo-no-creo-en-lo-hombres-caridad-bravo-adams","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/bellas-y-airosas-yo-no-creo-en-lo-hombres-caridad-bravo-adams\/","title":{"rendered":"Bellas y airosas |Yo no creo en lo hombres: Caridad Bravo Adams"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elvira Hern\u00e1ndez Carballido<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>SemM\u00e9xico, Pachuca, Hidalgo, 14 de enero, 2024.- \u201cHablo en defensa de mis compa\u00f1eras de trabajo, mujeres que nacen y viven humilladas, sufriendo todas las privaciones y que, a diario, tropiezan con esos se\u00f1ores que nos deslumbran con su dinero, posici\u00f3n, influencia y que nos prometen con mentira, una espiral, un mundo de maravillas, para luego hundirnos en el deshonor y la verg\u00fcenza: matan nuestros sue\u00f1os, nuestras ilusiones, y nos dejan vac\u00edas de esperanza dentro de un cuerpo ya sin vida. Es un crimen mil veces peor que los otros y no hay ley que lo persiga\u2026 \u00a1Al matar, no s\u00f3lo lo hice en leg\u00edtima defensa!, sino por algo que vale m\u00e1s que la vida misma: la dignidad, el respeto de los sentimientos de la fe, que no se pueden comprar ni con la violencia, ni con el dinero\u2026\u201d<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Caridad Robledo es la protagonista de \u201cYo no creo en los hombres\u201d, novela escrita en 1951 por la tabasque\u00f1a Caridad Bravo Adams, texto que despu\u00e9s se convirti\u00f3 en radionovela, ha tenido una versi\u00f3n en cine y tres en telenovelas. A juicio del cr\u00edtico de televisi\u00f3n, \u00c1lvaro Cueva, el argumento quiso representar un acto de justicia para miles de mujeres oprimidas. Se dice que la autora escribi\u00f3 esta historia bas\u00e1ndose en los casos de mujeres presas, luego de cada charla con varias reclusas se dio cuenta que hab\u00eda un eje com\u00fan en los relato: todas estaban encarceladas por haber cre\u00eddo en un hombre que las enga\u00f1\u00f3, us\u00f3 o abus\u00f3 de ellas. Aunque en una entrevista ella declar\u00f3 otro motivo para escribirla: \u201cConoc\u00ed a una muchacha que estaba condenada a la pena de muerte. La chica me cont\u00f3 su historia que me conmovi\u00f3 a tal grado que me lanc\u00e9 a escribir Yo no creo en los hombres, claro que a mi hero\u00edna yo s\u00ed la saco de la c\u00e1rcel\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A 118 a\u00f1os de su nacimiento, 14 de enero de 1908 (aunque algunas semblanzas se\u00f1alan que fue en 1904), recorrer su obra representa la oportunidad de redescubrirla o de admirar a una mexicana que fue escritora, poeta, dramaturga, actriz y periodista en una \u00e9poca donde no resultaba sencillo para una mujer estar visible en estos escenarios.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1920 public\u00f3 su primer libro, \u201c<em>P\u00e9talos Sueltos\u201d<\/em>, lleno de poemas inspiradores, y en la d\u00e9cada siguiente fue periodista en <em>Revista de Revistas, Exc\u00e9lsior y El Universal.<\/em> Es una l\u00e1stima que todav\u00eda no se recuperen sus textos period\u00edsticos, pero resulta curioso que en las semblanzas que circulan en redes solamente se haga referencia a una entrevista que le hizo a Carmen Serd\u00e1n, pero nadia aporta un poco m\u00e1s de las term\u00e1ticas y g\u00e9neros que domin\u00f3.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a que su padre y madre se dedicaban a la actuaci\u00f3n, se entusiasmo con el teatro y escribi\u00f3 -en 1962- la obra titulada Agustina Ram\u00edrez, que trata sobre una mexicana cuyo marido y 12 hijos murieron durante la intervenci\u00f3n francesa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bravo Adams escribi\u00f3 otras historias que se hicieron muy populares en los medios de comunicaci\u00f3n, entre ellas Coraz\u00f3n Salvaje, La Mentira, Bodas de Odio y Lo Imperdonable. En cada una de ellas destacan perfiles femeninos fuertes, mujeres decididas y que pese a estar dentro de un contexto de amor rom\u00e1ntico, siempre trataban de quererse m\u00e1s a s\u00ed mismas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es interesante que Caridad Brazo Adams le comentara a mi querida tocaya Elvira Garc\u00eda: &nbsp;\u201cEn realidad no escribo para que me den el Premio Nobel -pobre de m\u00ed-; yo escribo para llegar al pueblo, a la gran masa humana, a tanta gente que necesita una hora de distracci\u00f3n\u2026 Me niegan el pan y la sal porque escribo para la radio y televisi\u00f3n, pero yo tengo cuatro libros de versos, treinta y ocho novelas y dos obras de teatro; si soy buena o mala no me toca a m\u00ed discutirlo, pero desde luego que soy escritora\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nunca se cas\u00f3 ni tuvo hijos, existen muy pocos trabajos que recuperan su trayectoria, entre ellos una tesis de la UNAM donde el autor clasifica las obras de Caridad como literatura kitsch, sin bien la asignaci\u00f3n puede parecer de menosprecio, el an\u00e1lisis simplemente reconoce la existencia de este tipo de escritura se caracteriza por su emotividad y sentimentalismo basados \u201cen la piedad y el temor del melodrama cl\u00e1sico. El lector siente temor por las vicisitudes del h\u00e9roe, y, al mismo tiempo, piedad: autocompasi\u00f3n por temer que las maldades que el h\u00e9roe sufre, tambi\u00e9n las sufra\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, recurriendo a la IA es divertido poner en el buscador Caridad Bravo Adams y feminismo y que te respondan: \u201cCaridad Bravo Adams&nbsp;no fue una feminista en el sentido militante moderno, pero sus obras reflejaron y desafiaron las normas de g\u00e9nero de su \u00e9poca, creando protagonistas femeninas fuertes que luchaban contra la opresi\u00f3n, la injusticia y el machismo, como en&nbsp;<em>Yo no creo en los hombres<\/em>, y abordando temas de mujer trabajadora y de autoafirmaci\u00f3n, a pesar de escribir dentro del melodrama popular, siendo una figura relevante dentro del Ateneo Mexicano de Mujeres\u2026 Aunque algunos la etiquetaron como \u00abpatrona del drama cursi\u00bb, su trabajo reflej\u00f3 la vida de las mujeres y sus luchas en un contexto popular, y sus obras fueron adaptadas numerosas veces, consolidando su impacto cultural y el de sus hero\u00ednas.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso, yo la sigo disfrutando con cari\u00f1o y agradecimiento. Marc\u00f3 mi infancia con personajes como M\u00f3nica y Aim\u00e9e de Altamira, en Coraz\u00f3n Salvaje; Ver\u00f3nica Vastelo Blanco, en La Mentira; y, Mar\u00eda Caridad en Yo no creo en los hombres interpretada por Sarita Montiel en el cine. Todav\u00eda suspiro por ese personaje masculino llamado Juan del Diablo que fue interpretado maravillosamente por Enrique Lizalde, Julio Alem\u00e1n y Eduardo Palomo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Do\u00f1a Caridad Bravo Adams, fue pionera y vanguardista, ojal\u00e1 que este evocaci\u00f3n de su obra provoque explorar m\u00e1s sus creaciones literarias y period\u00edsticas.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elvira Hern\u00e1ndez Carballido SemM\u00e9xico, Pachuca, Hidalgo, 14 de enero, 2024.- \u201cHablo en defensa de mis compa\u00f1eras de trabajo, mujeres que nacen y viven humilladas, sufriendo todas las privaciones y que, a diario, tropiezan con esos se\u00f1ores que nos deslumbran con su dinero, posici\u00f3n, influencia y que nos prometen con mentira, una espiral, un mundo de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":70197,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[202,35],"tags":[],"class_list":["post-101892","post","type-post","status-publish","format-standard","has-post-thumbnail","category-elvira-hernandez-carballido","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/101892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=101892"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/101892\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/70197"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=101892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=101892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=101892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}