{"id":101872,"date":"2026-01-14T10:06:34","date_gmt":"2026-01-14T16:06:34","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=101872"},"modified":"2026-01-14T10:06:35","modified_gmt":"2026-01-14T16:06:35","slug":"debemos-apostar-por-una-sociedad-del-cuidado-edith-ortiz-romero","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/debemos-apostar-por-una-sociedad-del-cuidado-edith-ortiz-romero\/","title":{"rendered":"Debemos apostar por una sociedad del cuidado: Edith Ortiz Romero"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hay que crear una cultura al respecto a partir de las infancias, conferencia magistral&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reflexi\u00f3n organizada por la Comisi\u00f3n Interna para la Igualdad de G\u00e9nero del Programa Universitario de Bio\u00e9tica<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redacci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 14 de enero, 2026.- Hoy se busca el reconocimiento del cuidado como derecho humano, aunque es necesario tomar medidas para que adem\u00e1s esa tarea, asignada a las mujeres, se redistribuya, se brinde en los hogares, se haga part\u00edcipe a la sociedad, y que el Estado regule acciones para quitarle a ellas esa carga, afirm\u00f3 la especialista del Centro de Investigaciones en Estudios de G\u00e9nero de la UNAM, Edith Ortiz Romero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 que todas las personas podemos brindar atenciones y tambi\u00e9n recibirlas. Se requiere considerar el valor de este trabajo, asegurar el derecho de quienes los necesitan y de aquellos que los proveen, adem\u00e1s del ejercicio del autocuidado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto \u00faltimo es importante porque est\u00e1 vinculado a la salud f\u00edsica y emocional de quienes los brindan, prosigui\u00f3 la experta al impartir la conferencia magistral \u00c9tica del cuidado en tiempos de crisis: horizontes bio\u00e9ticos para una sociedad que sostiene, organizada por la Comisi\u00f3n Interna para la Igualdad de G\u00e9nero del Programa Universitario de Bio\u00e9tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La universitaria resalt\u00f3 que asistir a otros compete a las mujeres y a las dem\u00e1s personas del n\u00facleo familiar, red social y entorno. \u201cEn agosto pasado la Corte Interamericana de Derechos Humanos reconoci\u00f3 los cuidados como un derecho humano aut\u00f3nomo y estableci\u00f3 que esta facultad tiene tres dimensiones b\u00e1sicas: ser cuidado, cuidar y el autocuidado\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todas y todos los requerimos, en mayor o menor medida, a lo largo de nuestra vida. El problema es qui\u00e9n cuida, desde esa perspectiva nos preguntamos qui\u00e9n lo ha hecho y qui\u00e9n lo seguir\u00e1 haciendo, y qu\u00e9 implica para las personas cuidadoras, destac\u00f3 Ortiz Romero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Participaci\u00f3n inequitativa<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mencion\u00f3 que con base en datos de 2022 del Instituto Nacional de Estad\u00edstica y Geograf\u00eda (INEGI), 78 por ciento de los hogares ten\u00eda al menos un integrante que los necesitaba; hab\u00eda 58.3 millones de personas con necesidades de cuidados, lo que representaba 45.2 por ciento de la poblaci\u00f3n total; y 42 por ciento requer\u00eda alg\u00fan tipo de espec\u00edfico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, recalc\u00f3 que del total de las personas de 15 a\u00f1os y m\u00e1s, 31.7 millones (32 por ciento) los brindaron en su propio hogar o en otros, 75 por ciento de ese porcentaje fueron mujeres y 24 por ciento hombres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Edith Ortiz Romero expuso que las cuidadoras de personas con discapacidad son, en su mayor\u00eda, las hijas o madres; de las infancias, 86 por ciento se hacen cargo las mam\u00e1s y abuelas; quienes principalmente atienden a personas de seis a 17 a\u00f1os son las madres (81 por ciento), y los padres (seis por ciento), as\u00ed como las abuelas (seis por ciento).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De los adultos mayores de 60 a\u00f1os y m\u00e1s, son hijas, nietas, pareja o c\u00f3nyuge, hijos, nietos y algunas personas con otro parentesco. \u201cEsa es la realidad que vamos viendo y en donde las mujeres est\u00e1n presentes\u201d, alert\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque en esos procesos hay intervenci\u00f3n de hombres y mujeres, no es equitativa. A partir de una perspectiva de g\u00e9nero tiene que ver con roles y espacios asignados hist\u00f3ricamente, lo que implica mayor carga de labor hacia ellas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Plante\u00f3 que el sector femenino dedica, en promedio, 28.2 horas a la semana al trabajo dom\u00e9stico, en tanto que los varones 11.5. La diferencia es casi de 16 horas. Al cuidado de personas ellas ocupan 13.6 horas y ellos 8.7 horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hecho de que dediquen m\u00e1s tiempo a estas actividades que los hombres tiene implicaciones o afectaciones a la salud f\u00edsica y emocional de ellas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Plante\u00f3 que, para cumplir con el derecho al cuidado, en M\u00e9xico debe establecerse un sistema nacional progresivo en el cual el Estado participe a trav\u00e9s de sus instituciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para que funcione hay que proveer servicios p\u00fablicos de mayor calidad, eficientes y suficientes; empleos, educaci\u00f3n e infraestructura especializada como estancias infantiles, as\u00ed como hospitales, apunt\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se apuesta por aquellas personas que requieren de atenciones y por las cuidadoras. M\u00e1s que una carga, precis\u00f3, los cuidados deben verse como una vivencia del d\u00eda a d\u00eda, es decir, que no se perciba como un asistencialismo en el que el Estado y las familias deben proveerlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La apuesta ser\u00eda hacia una sociedad del cuidado y para ello debe haber una educaci\u00f3n a partir de las infancias para que empecemos a tener esa responsabilidad, resalt\u00f3 Ortiz Romero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hay que crear una cultura al respecto a partir de las infancias, conferencia magistral&nbsp; Reflexi\u00f3n organizada por la Comisi\u00f3n Interna para la Igualdad de G\u00e9nero del Programa Universitario de Bio\u00e9tica Redacci\u00f3n SemM\u00e9xico, Cd. de M\u00e9xico, 14 de enero, 2026.- Hoy se busca el reconocimiento del cuidado como derecho humano, aunque es necesario tomar medidas para [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":101873,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[748],"tags":[],"class_list":["post-101872","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura-feminista"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/101872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=101872"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/101872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/101873"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=101872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=101872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=101872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}