{"id":101748,"date":"2026-01-09T18:45:32","date_gmt":"2026-01-10T00:45:32","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=101748"},"modified":"2026-01-09T18:45:37","modified_gmt":"2026-01-10T00:45:37","slug":"los-capitales-mexico-sigue-como-el-principal-proveedor-de-bienes-a-eu","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/los-capitales-mexico-sigue-como-el-principal-proveedor-de-bienes-a-eu\/","title":{"rendered":"Los Capitales| M\u00e9xico sigue como el principal proveedor de bienes a EU."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Edgar Gonz\u00e1lez Mart\u00ednez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 9 de diciembre 2026.- Mientras el presidente Donald Trump no pierde oportunidad para amenazar \u201cde que luego de lo de Venezuela, se debe hacer algo con M\u00e9xico\u201d, los empresarios de EU siguen contratando mano de obra de mexicanos y la sociedad estadunidense sigue comprando bienes exportados por M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con cifras del Citibanamex, M\u00e9xico contin\u00faa como el principal proveedor de bienes importados de EU. En octubre -ultima de las cifras oficiales, las importaciones de bienes provenientes de M\u00e9xico totalizaron 48.5 mil millones de d\u00f3lares (m\u00e1ximo hist\u00f3rico), tras los 44.6 mmd del mes previo, y representaron 17.7 por ciento del total (m\u00e1xima proporci\u00f3n hist\u00f3rica), mientras que la participaci\u00f3n en las importaciones estadounidenses desde Canad\u00e1 fue de 11.3 por ciento, seguida por China, con 8.7 por ciento. As\u00ed, durante los primeros 10 meses de 2025 las importaciones desde M\u00e9xico ascendieron a 448.0 mmd, 5.6 por ciento por arriba de las registradas en el mismo periodo de 2024 (el total de importaciones de bienes de EU creci\u00f3 6.1%).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con ello, la participaci\u00f3n de M\u00e9xico promedi\u00f3 15.6 por ciento en dicho periodo, 0.1 puntos porcentuales (pp) por debajo de la participaci\u00f3n en enero-octubre de 2024, mientras que para China y Canad\u00e1 fue de 9.3 y 11.2 por ciento, respectivamente (4.2 pp y 1.4 pp menos que en 2024, en ese orden). Y sigue recuperando terreno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Considerando el promedio m\u00f3vil a 12 meses de la participaci\u00f3n en las importaciones totales, los aumentos abruptos registrados en marzo de Irlanda (farmac\u00e9uticos) y Suiza (oro) parecen mantenerse. Por su parte, Vietnam y Taiw\u00e1n siguen ganando participaci\u00f3n a costa de China y Canad\u00e1, pues M\u00e9xico ha revertido la tendencia decreciente que hab\u00eda exhibido los primeros meses de 2025, gracias en buena medida al beneficio que otorga el cumplimiento con las reglas del TMEC para la importaci\u00f3n libre de arancel. M\u00e9xico aument\u00f3 su ventaja arancelaria frente al resto del mundo. La ca\u00edda mensual de 4.3 por ciento en las importaciones totales de bienes de EU durante octubre, tras el avance de 1 por ciento en septiembre y la disminuci\u00f3n de 6.6 por ciento en agosto, refleja un mayor efecto de todos los aranceles anunciados por la administraci\u00f3n Trump en los primeros meses del a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, el arancel promedio efectivamente pagado durante octubre fue de 11 por ciento, 0.3 pp m\u00e1s que en septiembre, o bien 8.7 pp m\u00e1s que antes de la imposici\u00f3n de los aranceles. Para M\u00e9xico, el arancel efectivamente pagado en octubre fue de 4.6 por ciento, 0.1 pp menor al 4.7 por ciento exhibido en los tres meses previos. Por su parte, China exhibi\u00f3 un arancel promedio de 37 por ciento en octubre, 0.1 pp menos que en septiembre, pero 26.1 pp superior al previo a los aranceles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En fin, M\u00e9xico export\u00f3 a EU libre de arancel 81.6 por ciento de sus exportaciones, durante octubre. Esto representa aproximadamente 7.2 pp menos que antes de la imposici\u00f3n de aranceles. As\u00ed, durante el mes de referencia, 15.7 por ciento de las exportaciones mexicanas con destino a EU pagaron un arancel, 7.5 pp m\u00e1s que un a\u00f1o antes. Por su parte, el uso de almacenes y\/o zonas de libre comercio (2.8 % del total) fue 0.4 pp menos que en octubre de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La verdad es que EU requiere de la mano de obra mexicana, y en su comercio, procedente del exterior, M\u00e9xico es el principal abastecedor. \u00bfLo sabr\u00e1 el presidente Donald Trump y sus asesores?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:loscapitales@yahoo.com.mx\" target=\"_blank\" rel=\"noreferrer noopener\">loscapitales@yahoo.com.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Twiter: @Edgar4712<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Edgar Gonz\u00e1lez Mart\u00ednez SemM\u00e9xico, Ciudad de M\u00e9xico, 9 de diciembre 2026.- Mientras el presidente Donald Trump no pierde oportunidad para amenazar \u201cde que luego de lo de Venezuela, se debe hacer algo con M\u00e9xico\u201d, los empresarios de EU siguen contratando mano de obra de mexicanos y la sociedad estadunidense sigue comprando bienes exportados por M\u00e9xico. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":75979,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[750,110,35],"tags":[],"class_list":["post-101748","post","type-post","status-publish","format-standard","has-post-thumbnail","category-edgar-gonzalez-martinez","category-la-opinion-columnas","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/101748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=101748"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/101748\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/75979"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=101748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=101748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=101748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}