{"id":101291,"date":"2025-12-12T12:44:58","date_gmt":"2025-12-12T18:44:58","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=101291"},"modified":"2025-12-12T12:44:59","modified_gmt":"2025-12-12T18:44:59","slug":"tras-la-puerta-del-poder-mexico-no-va-al-populismo-monreal","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/tras-la-puerta-del-poder-mexico-no-va-al-populismo-monreal\/","title":{"rendered":"Tras la puerta del poder| M\u00e9xico no va al populismo: Monreal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Roberto Vizca\u00edno&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 12 de diciembre, 2025.- Es muy distinto ser un gobierno con base popular, afirm\u00f3, al reconocer que \u00e9l, como coordinador primero de los senadores -de 2018 a 2024- y ahora de los diputados de Morena haya -junto con sus bancadas- impulsado reformas a m\u00e1s de 40 art\u00edculos constitucionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ricardo Monreal, coordinador de la mayor\u00eda de Morena en San L\u00e1zaro y presidente de la Junta de Coordinaci\u00f3n pol\u00edtica, dijo que las fracciones mayoritarias de la 4T han aprobado cambios profundos a la Constituci\u00f3n de 1917, pero sin llegarla a modificar de tal forma que se pueda hablar de una Constituci\u00f3n distinta, subray\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al hacer un r\u00e1pido balance de fin per\u00edodo y a\u00f1o, indic\u00f3 que tan s\u00f3lo en estos \u00faltimos 4 meses legislativos, se presentaron m\u00e1s de mil iniciativas entre las que se tramitaron temas tan importantes como la nueva Ley del Agua, la Reforma de Econom\u00eda Circular, una Reforma a la Organizaci\u00f3n de la Armada sin contar con que se tuvo que debatir y aprobar el Presupuesto de Ingresos y el de la Ley de Egresos que son fundamentales para la operaci\u00f3n del Gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstas iniciativas son, adem\u00e1s, expresiones de una visi\u00f3n compartida entre poderes que, en su interacci\u00f3n, est\u00e1n dando forma a una reforma profunda del pacto social. Cada decisi\u00f3n legislativa refleja la voluntad de acompa\u00f1ar al Ejecutivo en la construcci\u00f3n de un nuevo modelo de Estado, m\u00e1s activo, m\u00e1s protector y cercano a la ciudadan\u00eda. La manera en que los tramitamos, la apertura al debate, las m\u00faltiples reservas y foros que abrieron este espacio a un gran n\u00famero de actores, es muestra de la madurez democr\u00e1tica del pa\u00eds. La mayor\u00eda actu\u00f3 con responsabilidad y con apego a su mandato constitucional\u201d, precis\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y agreg\u00f3:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCon este conjunto de reformas, hoy el Estado se vuelve garante de derechos; se afirma sobre instituciones, t\u00e9cnica y justicia social. El presupuesto p\u00fablico, por su parte, se orienta como instrumento de redistribuci\u00f3n y de bienestar colectivo. Donde antes el presupuesto operaba como incentivo para quienes m\u00e1s ten\u00edan, hoy se orienta como instrumento de redistribuci\u00f3n y de bienestar colectivo. Donde la igualdad y la protecci\u00f3n del entorno eran temas secundarios, hoy est\u00e1n en el centro del proyecto p\u00fablico, como condici\u00f3n de futuro. Prueba de ello es el Presupuesto de Egresos de la Federaci\u00f3n de 2026. Ah\u00ed est\u00e1 plasmado, con toda claridad, el compromiso de este Congreso con el pueblo de M\u00e9xico, ya que para el pr\u00f3ximo ejercicio fiscal se aprob\u00f3 una inversi\u00f3n p\u00fablica por m\u00e1s de un bill\u00f3n doscientos sesenta mil millones de pesos, equivalente al 3.2 por ciento del producto interno bruto, con un crecimiento real de m\u00e1s del 21 por ciento respecto al a\u00f1o anterior.&nbsp;Esto no es un ajuste marginal. Es una definici\u00f3n pol\u00edtica de rumbo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quedan en espera, indic\u00f3, la Reforma Electoral de la cual hay debate sin que todav\u00eda exista un proyecto presentado por la Comisi\u00f3n Presidencial encabezada por&nbsp;Pablo G\u00f3mez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;El Senado ha cumplido: Laura Itzel<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su vez la senadora de Morena&nbsp;Laura Itzel Castillo,&nbsp;presidenta del Senado declar\u00f3 concluidos ayer los trabajos del Primer Periodo Ordinario de Sesiones del Segundo A\u00f1o de la LXVI Legislatura, un per\u00edodo lleno de conflictos y encontronazos entre fracciones, pero a la vez de grandes aprobaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su mensaje final, la senadora refrendo su convicci\u00f3n democr\u00e1tica&nbsp;y reiter\u00f3 que todas las voces son necesarias para la edificaci\u00f3n de un mejor pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afirm\u00f3 que con ella en la&nbsp;presidencia de la Mesa Directiva del Senado, esta parte del Congreso \u201ces un espacio plural donde se dialoga, delibera, se discute de manera fuerte, pero donde tambi\u00e9n se trabaja con responsabilidad por el bienestar del pueblo de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHa sido un periodo intenso de trabajo compartido, donde todas y todos hemos contribuido a consolidar el papel hist\u00f3rico de esta C\u00e1mara de Senadores y Senadoras\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este Periodo de Sesiones, record\u00f3, se tom\u00f3 protesta de 877 juzgadoras y juzgadores del nuevo Poder Judicial de la Federaci\u00f3n, incluida la totalidad de las ministras y ministros de la nueva Suprema Corte de Justicia de la Naci\u00f3n surgida del voto&nbsp;popular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEste hecho hist\u00f3rico, consider\u00f3, marc\u00f3 un momento decisivo para fortalecer la impartici\u00f3n de justicia en nuestro pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn este lapso igual se aprobaron reformas de una enorme importancia para la construcci\u00f3n de un Estado de bienestar social y de derecho como los cambios a las leyes de Amparo, la ley contra la extorsi\u00f3n, instrumentos claves para cerrar la pinza en el combate a la corrupci\u00f3n y, sobre todo a la impunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAdem\u00e1s, se aval\u00f3 el Paquete Econ\u00f3mico, la reforma la Ley de Aguas Nacionales y la nueva Ley General de Aguas, proyectos que garantizan el acceso a derechos esenciales como la salud, la educaci\u00f3n, los cuidados de la poblaci\u00f3n vulnerable y el derecho y el acceso al agua y a la vida digna\u201d, subray\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro hecho sobresaliente, agreg\u00f3, fue el nombramiento de la Fiscal General de la Rep\u00fablica,&nbsp;Ernestina Godoy, de quien se espera que, afirm\u00f3, en coordinaci\u00f3n con el Gabinete de Seguridad ayudar\u00e1 en la construcci\u00f3n de una sociedad m\u00e1s segura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo puedo dejar de destacar un hecho hist\u00f3rico que marc\u00f3 nuestra vida parlamentaria: por primera vez abrimos este Pleno a la voz de los pueblos y comunidades ind\u00edgenas, para que, desde aqu\u00ed, desde esta alta tribuna de la naci\u00f3n, puedan dirigir sus mensajes de lucha y esperanza en su lengua originaria\u201d, destac\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEste acto, subray\u00f3, simboliza el compromiso de esta C\u00e1mara de Senadoras y Senadores con la inclusi\u00f3n, el reconocimiento y el respeto a la diversidad cultural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cConcluimos as\u00ed este periodo intenso y trascendente con las reformas en materia de salud y de pol\u00edtica arancelaria\u201d, cerr\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Twitter: @_Vizcaino \/ Facebook<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\/&nbsp;<a href=\"https:\/\/www.facebook.com\/rvizcainoa\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/rvizcainoa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roberto Vizca\u00edno&nbsp; SemM\u00e9xico, Ciudad de M\u00e9xico, 12 de diciembre, 2025.- Es muy distinto ser un gobierno con base popular, afirm\u00f3, al reconocer que \u00e9l, como coordinador primero de los senadores -de 2018 a 2024- y ahora de los diputados de Morena haya -junto con sus bancadas- impulsado reformas a m\u00e1s de 40 art\u00edculos constitucionales. Ricardo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":39589,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[35,623,622],"tags":[],"class_list":["post-101291","post","type-post","status-publish","format-standard","has-post-thumbnail","category-opinion","category-roberto-vizcaino","category-tras-la-puerta-del-poder"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/101291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=101291"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/101291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/39589"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=101291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=101291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=101291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}