{"id":100941,"date":"2025-12-01T18:09:58","date_gmt":"2025-12-02T00:09:58","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=100941"},"modified":"2025-12-01T18:09:58","modified_gmt":"2025-12-02T00:09:58","slug":"violeta-del-anahuac-parenlas-a-como-de-lugar","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/violeta-del-anahuac-parenlas-a-como-de-lugar\/","title":{"rendered":"Violeta del An\u00e1huac| P\u00e1renlas \u00bfa c\u00f3mo d\u00e9 lugar?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Isabel Ortega Morales<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Chilpancingo, 1 de diciembre, 2025.- Es el inicio del \u00faltimo mes del a\u00f1o 2025. La oposici\u00f3n al partido en el poder parec\u00eda no tener un referente que le quitara el sue\u00f1o al partidazo para ir a una elecci\u00f3n intermedia con lo que se llamaba carro completo y ahora es\u2026 lo mismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Levant\u00f3 la mano el empresario Ricardo Salinas Pliego y no solo deber\u00e1 estar a la altura de la instrucci\u00f3n presidencial \u201ctoma chocolate, paga lo que debes\u201d, sino que ahora, pende sobre \u00e9l la amenaza de la ruina que deber\u00e1 sortear con mucha inteligencia para mantener a flote su liderazgo empresarial como tambi\u00e9n su pretensi\u00f3n presidencial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero en ese camino de la elecci\u00f3n intermedia, el partidazo no est\u00e1 dispuesto a dejar a nadie, y nadie es nadie, o ning\u00fan estado seg\u00fan sea el caso, a otro partido que no sea el que est\u00e1 en el poder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso, parece que ha surgido la orden \u201cp\u00e1renlas, a como de lugar\u201d. Y no los ha detenido ni el duelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para parar a Grecia Quiroz, viuda de Carlos Manzo, se ha acudido a la descalificaci\u00f3n convocando a la sociedad conservadora de la moral social a presentarla con el uso de la IA, Inteligencia Artificial, como de romance con el legislador que se atrevi\u00f3 a levantar la voz para defenderla y que aparece con el cuadro del alcalde privado de la vida en la toma de protesta de Grecia que levanta el s\u00edmbolo de lucha que ahora representa el sombrero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para parar a la alcaldesa de la Delegaci\u00f3n Cuauht\u00e9moc, Alessandra Rojo de la Vega, est\u00e1n acudiendo a la amenaza de quitarle el poder v\u00eda Congreso de la Ciudad de M\u00e9xico con mayor\u00eda de miembros del partidazo adem\u00e1s de investigar tanto a ella como a su familia de las empresas que tienen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las dos mujeres han crecido en liderazgo social, se han convertido en un referente de lucha con causa, han recibido solidaridad colectiva y han sido vistas bien para encabezar cualquier proyecto pol\u00edtico, incluso sin propon\u00e9rselo en este momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quienes revisan a la clase pol\u00edtica han detectado ello y han visto eclipsarse figuras a pesar de tener un control de la sociedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Saben que pueden ser las dos mujeres una alianza que pueda crecer no solo de forma regional sino nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Saben que pueden ser opositoras reales al sistema que se est\u00e1 envejeciendo en pr\u00e1cticas que detesta la sociedad: la mentira, la corrupci\u00f3n, la omisi\u00f3n, la violencia, el crimen, y hasta la falta de poder real del ejercicio constitucional que eman\u00f3 de un voto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfPor qu\u00e9 empezar a sembrar en la sociedad la idea de un romance de la viuda de Carlos Manzo con el Legislador Independiente? Porque quieren obligarla a seguir un rol de viuda y buscan descalificarla entre mujeres que busquen conservar ese estatus y que no se salga del molde que, seg\u00fan la moral social, debe cumplir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfPor qu\u00e9 parar a Alessandra? Porque se ha expresado con una fuerza pol\u00edtica atribuida al sector masculino que est\u00e1 acostumbrado a someter y ser sometido para conservar un estatus pol\u00edtico y se ha atrevido a usar su voz para el ejercicio del mandato que le dio esa Alcald\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una frase de Simone de Beauvoir es \u201cUna no nace, sino que se convierte en mujer\u201d, adem\u00e1s de que implica todo un esquema a revalorarnos y revisar lo que en nuestro contexto ocurre, tambi\u00e9n nos indica que ser mujer es no ajustarse al cumplimiento de roles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que van a existir mandatos con los que intentar\u00e1n someternos, que habr\u00e1 a quienes se les perdonen por ser parte de la estructura y que habr\u00e1 a quienes se les excluya por no seguirlos y cumplirlos, incluso hasta inventarlos ya que a ellas no les aplican el amparo de la violencia pol\u00edtica en raz\u00f3n de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta parece ser una lecci\u00f3n de lo que se espera de la mujer en la nueva narrativa pol\u00edtica mexicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Isabel Ortega Morales SemM\u00e9xico, Chilpancingo, 1 de diciembre, 2025.- Es el inicio del \u00faltimo mes del a\u00f1o 2025. La oposici\u00f3n al partido en el poder parec\u00eda no tener un referente que le quitara el sue\u00f1o al partidazo para ir a una elecci\u00f3n intermedia con lo que se llamaba carro completo y ahora es\u2026 lo mismo. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":38576,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[198,35,197],"tags":[],"class_list":["post-100941","post","type-post","status-publish","format-standard","has-post-thumbnail","category-isabel-ortega-morales","category-opinion","category-violeta-del-anahuac"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/100941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=100941"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/100941\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/38576"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=100941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=100941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=100941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}