{"id":100757,"date":"2025-11-25T13:36:31","date_gmt":"2025-11-25T19:36:31","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=100757"},"modified":"2025-11-25T13:36:32","modified_gmt":"2025-11-25T19:36:32","slug":"machismo-esta-detras-de-60-de-asesinatos-de-mujeres-en-el-mundo-alerta-onu","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/machismo-esta-detras-de-60-de-asesinatos-de-mujeres-en-el-mundo-alerta-onu\/","title":{"rendered":"Machismo est\u00e1 detr\u00e1s de 60% de asesinatos de mujeres en el mundo, alerta ONU"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Solo en 2024, casi 50 mil mujeres y ni\u00f1as fueron asesinadas por personas cercanas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el an\u00e1lisis global de la ONU &nbsp;difundido en el marco del D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Magdalena Valdez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/Radio del Sur, Cd. de M\u00e9xico, 25 de noviembre, 2025.- Un nuevo informe de ONU Mujeres y la Oficina de la ONU contra la Droga y el Delito revela que el machismo y las normas sociales que subordinan a las mujeres explican al menos el 60% de los homicidios de mujeres registrados en el mundo, la mayor\u00eda perpetrados por parejas o familiares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Solo en 2024, casi 50 mil mujeres y ni\u00f1as fueron asesinadas por personas cercanas, seg\u00fan el an\u00e1lisis global difundido en el marco del&nbsp;D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El documento subraya que el hogar es el lugar m\u00e1s peligroso para ellas: de los cerca de 80 mil homicidios de mujeres registrados ese a\u00f1o, seis de cada diez ocurrieron en el entorno \u00edntimo. En contraste, solo 11% de los hombres asesinados murieron a manos de parejas o familiares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La violencia que termina en feminicidio, advierte el informe, suele formar parte de patrones previos de control, amenazas o acoso, incluso mediante tecnolog\u00edas digitales. La directora de Pol\u00edticas de ONU Mujeres, Sarah Hendriks, record\u00f3 que una de cada cuatro mujeres entre 15 y 49 a\u00f1os ha sufrido violencia f\u00edsica o sexual por parte de su pareja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ONU alert\u00f3 adem\u00e1s que las nuevas tecnolog\u00edas han amplificado las agresiones, desde el ciberacoso hasta la difusi\u00f3n no consentida de im\u00e1genes o el uso de videos manipulados, pr\u00e1cticas que en muchos casos preceden a agresiones f\u00edsicas y asesinatos. Un an\u00e1lisis citado en Reino Unido mostr\u00f3 que en casi 60% de los feminicidios revisados se emple\u00f3 tecnolog\u00eda para ejercer control coercitivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El organismo se\u00f1ala que las ra\u00edces de estos cr\u00edmenes est\u00e1n en estereotipos, discriminaci\u00f3n y relaciones de poder desiguales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A escala regional, \u00c1frica registra la tasa m\u00e1s alta de feminicidios \u00edntimos, seguida por Am\u00e9rica, Ocean\u00eda, Asia y Europa. En este \u00faltimo continente, la tasa ha disminuido lentamente, especialmente en el norte y el sur, indica el informe de ONU.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.laradiodelsur.com.ve\/cepal-revela-que-en-2024-se-cometieron-casi-4-000-feminicidios\/\"><strong>Cepal revela que en 2024 se cometieron casi 4.000 feminicidios<\/strong><\/a><strong><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Solo en 2024, casi 50 mil mujeres y ni\u00f1as fueron asesinadas por personas cercanas Seg\u00fan el an\u00e1lisis global de la ONU &nbsp;difundido en el marco del D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer Magdalena Valdez SemM\u00e9xico\/Radio del Sur, Cd. de M\u00e9xico, 25 de noviembre, 2025.- Un nuevo informe de ONU Mujeres [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":100759,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[1148,27],"tags":[],"class_list":["post-100757","post","type-post","status-publish","format-standard","has-post-thumbnail","category-25n-2025","category-cobertura-especial"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/100757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=100757"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/100757\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/100759"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=100757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=100757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=100757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}