{"id":100419,"date":"2025-11-14T15:06:59","date_gmt":"2025-11-14T21:06:59","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=100419"},"modified":"2025-11-14T15:07:00","modified_gmt":"2025-11-14T21:07:00","slug":"los-capitales-buena-senal-empresas-demandan-creditos-para-aumentar-produccion-bbva","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/los-capitales-buena-senal-empresas-demandan-creditos-para-aumentar-produccion-bbva\/","title":{"rendered":"Los capitales| Buena se\u00f1al: empresas demandan cr\u00e9ditos para aumentar producci\u00f3n: BBVA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Edgar Gonz\u00e1lez Mart\u00ednez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 14 de noviembre, 2025.-La instituci\u00f3n crediticia confirm\u00f3 que el cr\u00e9dito bancario a las empresas repunta de modo generalizado entre sectores. En efecto, la cartera de cr\u00e9dito vigente al Sector Privado No Financiero (SPNF) cerr\u00f3 el 3T25 con un crecimiento de 5.8% anual, tras descontar la inflaci\u00f3n y el efecto cambiario. El saldo del cr\u00e9dito a las empresas ya es superior a lo observado antes de la pandemia en pr\u00e1cticamente todos los sectores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y esto ocurre en el actual contexto de desaceleraci\u00f3n de la actividad econ\u00f3mica y del empleo formal que se ha visto influido por la incertidumbre sobre la pol\u00edtica arancelaria de los EU y por los cambios institucionales dom\u00e9sticos. As\u00ed, el financiamiento en M\u00e9xico se ha distinguido por tres principales tendencias hacia el tercer trimestre de 2025:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera, el incremento de los recursos destinados a financiar a las empresas, lo que permiti\u00f3 que la desaceleraci\u00f3n del cr\u00e9dito total fuera menor a la anticipada a inicios del a\u00f1o. La elevada incertidumbre sobre el nivel y el momento de la entrada en vigor de los aranceles en EU motiv\u00f3 un adelanto de compras con la finalidad de eludir, por alg\u00fan tiempo, la medida. Esto se reflej\u00f3 en un alza de 9.7% trimestral de las exportaciones mexicanas a EU durante los primeros tres meses del a\u00f1o, lo que a su vez impuls\u00f3 la demanda de cr\u00e9dito en M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esta manera, el cr\u00e9dito a empresas creci\u00f3 a una tasa anual real de 11.2% al cierre de marzo, su mayor nivel desde junio de 2018, principalmente por el impulso adicional en el crecimiento de los sectores de manufactura y construcci\u00f3n y de las regiones norte y centro-norte, que agrupan el 78.0% del valor de las exportaciones totales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El an\u00e1lisis realizado por BBVA Research M\u00e9xico destaca que este mayor crecimiento del cr\u00e9dito a empresas se present\u00f3 a la par de una desaceleraci\u00f3n del cr\u00e9dito al consumo y a la vivienda, explicada, en buena medida, por la menor creaci\u00f3n de empleo formal y el poco dinamismo de la actividad econ\u00f3mica. Entre diciembre de 2024 y septiembre de 2025 la tasa de crecimiento anual de los empleos registrados en el IMSS pas\u00f3 de 1.0 a 0.4%, luego de registrar un crecimiento nulo en junio. Asimismo, de acuerdo con el INEGI, durante el tercer trimestre la econom\u00eda creci\u00f3 -0.3% a tasa anual, derivado de un crecimiento promedio nulo a tasa anual del consumo privado y de -6.8% de la inversi\u00f3n entre enero y agosto de 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La segunda tendencia del financiamiento a lo largo del 2025 ha sido la diluci\u00f3n e incluso la reversi\u00f3n del efecto contable del tipo cambio sobre los saldos de las carteras de cr\u00e9dito y dep\u00f3sitos. La depreciaci\u00f3n cambiaria desde niveles de 16.5 pesos por d\u00f3lar (ppd), registrada desde junio del 2024, gener\u00f3 un efecto contable positivo para las carteras de cr\u00e9dito, particularmente a inicios del a\u00f1o en que el tipo de cambio se ubic\u00f3 cerca de los 21.0 ppd.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, el informe se\u00f1ala que la tercera tendencia a lo largo del 2025 ha sido el fortalecimiento del ahorro para el retiro como la principal fuente de ahorro interno. Como resultado de la reforma al sistema de pensiones de 2020, las entradas netas de recursos a las SIEFORES se han incrementado m\u00e1s de 110% en promedio mensual en los \u00faltimos cinco a\u00f1os. Esto ha llevado a que los activos netos de las SIEFORES superen los ocho billones de pesos, alrededor del 21.0% del PIB, y representen el 20.0% de los activos financieros internos del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En suma, el sistema financiero ha atravesado el complejo entorno econ\u00f3mico apoyado en fuentes de financiamiento internas robustecidas por el ahorro para el retiro y dedicando una mayor cantidad de recursos financieros a las empresas. Cabe se\u00f1alar que, a\u00fan con esta alza, el uso de recursos por parte de las empresas se mantiene rezagado respecto a lo observado antes de la pandemia y muy por debajo del uso de recursos del sector p\u00fablico, el cual se mantiene claramente como el principal usuario de los recursos financieros de la econom\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y nadie debe dudarlo: hasta el momento, la intermediaci\u00f3n bancaria ha mantenido una din\u00e1mica favorable, dada la magnitud de la desaceleraci\u00f3n econ\u00f3mica. No obstante, de mantenerse las condiciones de debilidad en el empleo y la actividad, no puede descartarse que la provisi\u00f3n de cr\u00e9dito a hogares y empresas pueda verse reducida adicionalmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:loscapitales@yahoo.com.mx\" target=\"_blank\" rel=\"noreferrer noopener\">loscapitales@yahoo.com.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Twiter: @ Edgar4712&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Edgar Gonz\u00e1lez Mart\u00ednez SemM\u00e9xico, Cd. de M\u00e9xico, 14 de noviembre, 2025.-La instituci\u00f3n crediticia confirm\u00f3 que el cr\u00e9dito bancario a las empresas repunta de modo generalizado entre sectores. En efecto, la cartera de cr\u00e9dito vigente al Sector Privado No Financiero (SPNF) cerr\u00f3 el 3T25 con un crecimiento de 5.8% anual, tras descontar la inflaci\u00f3n y el [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":75979,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[750,110,35],"tags":[],"class_list":["post-100419","post","type-post","status-publish","format-standard","has-post-thumbnail","category-edgar-gonzalez-martinez","category-la-opinion-columnas","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/100419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=100419"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/100419\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/75979"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=100419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=100419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=100419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}