{"id":100277,"date":"2025-11-09T19:12:50","date_gmt":"2025-11-10T01:12:50","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=100277"},"modified":"2025-11-09T19:12:51","modified_gmt":"2025-11-10T01:12:51","slug":"swiftynomics-el-lazo-entre-taylor-swift-y-la-ultima-bruja-noruega-quemada-en-una-hoguera","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/swiftynomics-el-lazo-entre-taylor-swift-y-la-ultima-bruja-noruega-quemada-en-una-hoguera\/","title":{"rendered":"Swiftynomics: El lazo entre Taylor Swift y la \u00faltima bruja noruega quemada en una hoguera"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">M\u00e1s de 355 a\u00f1os distancian a Lisbeth Nypan, acusada de brujer\u00eda y llevada a la hoguera&nbsp;en 1670, de Taylor Swift. Pero ambas encarnan la misma herej\u00eda: la de una mujer que&nbsp;cobra por su arte. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Swiftynomics: C\u00f3mo las mujeres dirigen y redefinen nuestra econom\u00eda, Misty&nbsp;Heggeness explora el hilo invisible que une a las mujeres que han desafiado las reglas del&nbsp;dinero y la sociedad<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juan Luis Ramos &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/ El Sol de M\u00e9xico, Cd. de M\u00e9xico, 9 de noviembre, 2025.- Misty&nbsp;Heggeness ten\u00eda 16 a\u00f1os cuando supo que&nbsp;<strong>en 1670, Lisbeth Nypan fue quemada en la&nbsp;<\/strong><strong>hoguera<\/strong>&nbsp;y se convirti\u00f3 en&nbsp;<strong>la \u00faltima bruja<\/strong>&nbsp;<strong>de Noruega<\/strong>. Era su&nbsp;<strong>tatarabuela<\/strong>. Hoy, una&nbsp;placa en el centro de la&nbsp;<strong>ciudad de Trondheim<\/strong>, a unos 500 kil\u00f3metros al norte de Oslo, la&nbsp;recuerda a ella y&nbsp;<strong>a todas las mujeres ind\u00f3mitas<\/strong>. Tambi\u00e9n hay un libro de Rossell Hope&nbsp;Robbins,&nbsp;<em>Enciclopedia de Brujer\u00eda y Demonolog\u00eda<\/em>, que cuenta su juicio. \u201cEra&nbsp;<strong>curandera&nbsp;<\/strong><strong>en la comunidad y le\u00eda la sal<\/strong>. Ese conocimiento sin duda influy\u00f3 en qui\u00e9n soy hoy\u201d, dice. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue 27 a\u00f1os despu\u00e9s, en&nbsp;<strong>2019,&nbsp;<\/strong>cuando trabajaba como economista principal y asesora&nbsp;senior en la Oficina del Censo de Estados Unidos<strong>,&nbsp;<\/strong>que&nbsp;<strong>la descendiente de la \u00faltima bruja&nbsp;<\/strong><strong>noruega sinti\u00f3 una nueva fascinaci\u00f3n<\/strong>, similar a la que le produjo enterarse de la historia&nbsp;de su tatarabuela y que marcar\u00eda un nuevo rumbo en su carrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante una cena familiar,&nbsp;<strong>Misty Heggeness&nbsp;<\/strong>vio el video de&nbsp;<strong>la canci\u00f3n&nbsp;<\/strong><strong><em>The Man<\/em><\/strong>, cuarto&nbsp;sencillo del disco&nbsp;<em>Lover<\/em>, lanzado por&nbsp;<strong>Taylor Swift&nbsp;<\/strong>ese mismo a\u00f1o. La canci\u00f3n, una cr\u00edtica&nbsp;abierta sobre la&nbsp;<strong>desigualdad laboral&nbsp;<\/strong>entre&nbsp;<strong>hombres<\/strong>&nbsp;y<strong>&nbsp;mujeres,<\/strong>&nbsp;la impact\u00f3 tanto que al&nbsp;d\u00eda siguiente se plant\u00f3 en la oficina de su jefe para hablar del asunto que le daba vueltas.&nbsp;\u201cI would be complex \/ I would be cool \/ They\u2019d say I played the field before I found someone&nbsp;to commit to \/ And that would be okay \/ For me to do (<em>Yo ser\u00eda compleja \/ Yo ser\u00eda cool \/&nbsp;<\/em><em>Dir\u00edan que \u2018jugu\u00e9 el campo\u2019 antes de encontrar a alguien con quien comprometerme \/ Y&nbsp;<\/em><em>estar\u00eda bien \/ Que yo lo hiciera<\/em>)\u201d, inicia la canci\u00f3n que, en tres minutos y 10 segundos,&nbsp;se\u00f1ala c\u00f3mo Taylor Swift cree que ser\u00eda<strong>&nbsp;tratada de manera diferente si fuera un&nbsp;<\/strong><strong>hombre.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una entrevista con&nbsp;<strong><em>Billboard<\/em><\/strong><strong>,&nbsp;<\/strong>previa al evento&nbsp;<em>Women In Music 2019<\/em>, la cantante&nbsp;originaria de<strong>&nbsp;Pensilvania&nbsp;<\/strong>explic\u00f3 que compuso esa canci\u00f3n basada en su experiencia y&nbsp;la de otras mujeres en la industria, quienes coinciden que&nbsp;<strong>muchas cosas que hacen los&nbsp;<\/strong><strong>hombres se hacen con facilidad<\/strong>. \u201cPero nosotras no\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En&nbsp;<em>The Man<\/em>, la tambi\u00e9n actriz que durante a\u00f1os fue cuestionada por el n\u00famero de parejas&nbsp;que hab\u00eda tenido, hace referencia a&nbsp;<strong>Leonardo DiCaprio,<\/strong>&nbsp;el actor hollywoodense famoso&nbsp;no s\u00f3lo por sus pel\u00edculas, sino por la&nbsp;<strong>larga lista de novias&nbsp;<\/strong>que coinciden en una cosa:&nbsp;todas son menores de 25 a\u00f1os. \u201cAnd they would toast to me, oh \/ Let the players play \/ I\u2019d&nbsp;be just like Leo \/ In Saint Tropez (<em>Y brindar\u00edan por m\u00ed, oh \/ Que los playboys sigan jugando&nbsp;<\/em><em>\/ Yo ser\u00eda como Leo \/ en Saint-Tropez<\/em>)\u201d, canta Swift.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tonada de la pieza, \u201cpegadiza\u201d como la describi\u00f3 la misma&nbsp;<strong>Swift,<\/strong>&nbsp;tiene la intenci\u00f3n de&nbsp;dejar grabada en la cabeza de quien la escuche \u2013principalmente sus fans\u2013 una canci\u00f3n&nbsp;sobre la&nbsp;<strong>desigualdad de g\u00e9nero.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La intenci\u00f3n de la cantante tuvo eco en&nbsp;<strong>Misty Heggeness,&nbsp;<\/strong>cuya&nbsp;<strong>oficina estaba llena&nbsp;<\/strong><strong>entonces de estadistas hombres<\/strong>, en una proporci\u00f3n de ocho a dos respecto a las&nbsp;mujeres. \u201cMe sent\u00ed muy identificada con esa canci\u00f3n\u201d.<\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">The Eras Tour, de Taylor Swift, fue una de las giras m\u00e1s exitosas de la historia \/ Foto:&nbsp;Reuters<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La autora record\u00f3 las sensaciones que le dejaron la&nbsp;<strong>historia de su tatarabuela<\/strong>&nbsp;y&nbsp;la&nbsp;<strong>canci\u00f3n de Taylor Swift&nbsp;<\/strong>y c\u00f3mo la marcaron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDescubrir la&nbsp;<strong>historia de mi tatarabuela&nbsp;<\/strong>me dej\u00f3 con una sensaci\u00f3n de asombro y&nbsp;curiosidad. Ver el video de<strong>&nbsp;<\/strong><strong><em>The Man<\/em><\/strong>&nbsp;me dej\u00f3 con la&nbsp;<strong>sensaci\u00f3n de ser vista en lo m\u00e1s&nbsp;<\/strong><strong>profundo de mi ser<\/strong>\u201d, cuenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A seis a\u00f1os de ese episodio musical, la&nbsp;<strong>profesora e investigadora de la Universidad de&nbsp;<\/strong><strong>Kansas&nbsp;<\/strong>usa el t\u00e9rmino \u201c<strong>swiftynomics\u201d<\/strong>&nbsp;como el&nbsp;<strong>poder de utilizar las experiencias y&nbsp;<\/strong><strong>voces de las mujeres&nbsp;<\/strong>para avanzar en el crecimiento econ\u00f3mico, el desarrollo y&nbsp;la&nbsp;<strong>equidad.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el libro, publicado por la&nbsp;<strong>Universidad de California&nbsp;<\/strong>y que podr\u00eda traducirse al espa\u00f1ol&nbsp;en un a\u00f1o, Heggeness utiliza a Taylor Swift como su \u201cmusa perfecta\u201d para hablar&nbsp;del<strong>&nbsp;impacto econ\u00f3mico&nbsp;<\/strong>de la cantante y de otras mujeres conocidas mundialmente,&nbsp;como&nbsp;<strong>Beyonc\u00e9, Rihanna, Madonna, Dolly Parton<\/strong>&nbsp;y la chilena&nbsp;<strong>Mon Laferte;<\/strong>&nbsp;pero&nbsp;tambi\u00e9n de las disparidades de g\u00e9nero en la econom\u00eda y la importancia del&nbsp;<strong>trabajo de&nbsp;<\/strong><strong>cuidados no remunerado,<\/strong>&nbsp;as\u00ed como del&nbsp;<strong>empoderamiento econ\u00f3mico femenino&nbsp;<\/strong>a&nbsp;trav\u00e9s de hitos como los&nbsp;<strong>derechos reproductivos<\/strong>&nbsp;y el aumento de la participaci\u00f3n en&nbsp;el&nbsp;<strong>mercado laboral.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Taylor Swift es una de las artistas m\u00e1s prol\u00edficas de&nbsp;<\/em><\/strong><strong><em>nuestra \u00e9poca. Merece ser estudiada. Estoy segura de&nbsp;<\/em><\/strong><strong><em>que perdurar\u00e1 y posiblemente se extienda a aulas de&nbsp;<\/em><\/strong><strong><em>todo el mundo<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Misty Heggeness, profesora en la Universidad de Kansas<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lisbeth Nypan,<\/strong>&nbsp;la tatarabuela de la autora acusada de&nbsp;<strong>brujer\u00eda,&nbsp;<\/strong>se ganaba la vida a&nbsp;trav\u00e9s de su&nbsp;<strong>talento<\/strong>&nbsp;y&nbsp;<strong>habilidades<\/strong>&nbsp;en un&nbsp;<strong>mundo que no estaba dise\u00f1ado para ella,<\/strong>&nbsp;tal&nbsp;como las artistas que refiere el libro. El primer cap\u00edtulo del libro titulado&nbsp;<em>Reinvention&nbsp;<\/em><em>(Taylor\u2019s Version)<\/em>, se refiere a la estrategia de la cantante de regrabar su&nbsp;m\u00fasica para&nbsp;<strong>reclamar la autonom\u00eda de su arte<\/strong>&nbsp;como una met\u00e1fora central de&nbsp;la&nbsp;<strong>reinvenci\u00f3n femenina.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La acad\u00e9mica recuerda que en 2019 el sello discogr\u00e1fico de&nbsp;<strong>Taylor Swift&nbsp;<\/strong>fue adquirido y&nbsp;las grabaciones originales de sus primeros seis \u00e1lbumes, incluyendo&nbsp;<em>Reputation<\/em>, fueron&nbsp;vendidas sin su consentimiento. La artista tom\u00f3 entonces la decisi\u00f3n de grabar esos discos&nbsp;nuevamente y lanzarlos con el subt\u00edtulo&nbsp;<em>Taylor\u2019s Version,&nbsp;<\/em>como una&nbsp;<strong>negativa a ser&nbsp;<\/strong><strong>intimidada o controlada.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La historia de&nbsp;<strong>reinvenci\u00f3n de Taylor,&nbsp;<\/strong>cuenta la autora, ha sido impulsada por una&nbsp;creencia en su arte y una negativa a ser intimidada o controlada. Y esa reinvenci\u00f3n,&nbsp;contin\u00faa, saca a las&nbsp;<strong>mujeres&nbsp;<\/strong>del estancamiento y las mantiene&nbsp;<strong>avanzando&nbsp;<\/strong>cuando otros&nbsp;preferir\u00edan que se quedaran d\u00f3nde est\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Descubrir la historia de mi tatarabuela me dej\u00f3 con una&nbsp;<\/em><\/strong><strong><em>sensaci\u00f3n de asombro y curiosidad. Ver el video de The&nbsp;<\/em><\/strong><strong><em>Man me dej\u00f3 con la sensaci\u00f3n de ser vista en lo m\u00e1s&nbsp;<\/em><\/strong><strong><em>profundo de mi ser<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Misty Heggeness, autora del libro Swiftynomics: C\u00f3mo las mujeres dirigen y&nbsp;<\/em><em>redefinen nuestra econom\u00eda<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el tercer cap\u00edtulo del libro, llamado<em>&nbsp;Misogyny: You have the right to prove them wrong<\/em>,&nbsp;asevera que la misoginia ha intentado silenciar y controlar las historias y carreras de las&nbsp;mujeres. En este contexto, el texto abunda que&nbsp;<strong>Taylor Swift,&nbsp;<\/strong>al igual que las mujeres&nbsp;incomprendidas del pasado como&nbsp;<strong>Lisbeth Nypan,<\/strong>&nbsp;perseguida por sus conocimientos y&nbsp;autonom\u00eda, tuvo que&nbsp;<strong>reinventarse y planear estrat\u00e9gicamente c\u00f3mo recuperar la&nbsp;<\/strong><strong>propiedad de su arte.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para&nbsp;<strong>Misty Heggeness,&nbsp;<\/strong>todas las&nbsp;<strong>mujeres&nbsp;<\/strong>de las que se habla porque&nbsp;<strong>no se ajustan a&nbsp;<\/strong><strong>los roles<\/strong>&nbsp;y pensamientos tradicionales no son malas, simplemente&nbsp;son&nbsp;<strong>incomprendidas,&nbsp;<\/strong>eso incluye a su tatarabuela, a Taylor Swift y a un sinn\u00famero de&nbsp;estudiantes, amas de casa, trabajadoras, artistas y dem\u00e1s profesiones. \u201cQue su&nbsp;<strong>feroz&nbsp;<\/strong><strong>valent\u00eda,<\/strong>&nbsp;su&nbsp;<strong>independencia econ\u00f3mica<\/strong>&nbsp;y su capacidad para prosperar en un entorno&nbsp;que nunca fue creado para ellas perduren en el resto de nosotras\u201d, dice la dedicatoria del&nbsp;libro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A finales de octubre,\u00a0<em>The New York Times<\/em>\u00a0public\u00f3 una nota en la que refiri\u00f3 el \u201ctoque de\u00a0reina Midas\u201d de Swift, debido a que el\u00a0<strong>Museo de Wiesbaden, en Alemania,\u00a0<\/strong>ha recibido\u00a0en el \u00faltimo mes olas de fans de la cantante para admirar el cuadro\u00a0<em>Ofelia<\/em>, del artista\u00a0decimon\u00f3nico\u00a0<strong>Friedrich Heyser.<\/strong>\u00a0La obra, inspirada en una de las protagonistas de la\u00a0obra\u00a0<em>Hamlet<\/em>, de\u00a0<strong>William Shakespeare,\u00a0<\/strong>parece la inspiraci\u00f3n para una escena del videoclip de\u00a0<em>The Fate of Ophelia<\/em>, primer sencillo del nuevo \u00e1lbum de Taylor Swift,\u00a0<em>The Life\u00a0of a Showgirl<\/em>, lanzado el 3 de octubre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La publicaci\u00f3n del diario estadounidense recuerda que desde hace tiempo se sabe que&nbsp;la<strong>&nbsp;fama de Swift&nbsp;<\/strong>tiene un&nbsp;<strong>efecto econ\u00f3mico&nbsp;<\/strong>sobre todo lo que toca o menciona el cual,&nbsp;a\u00f1ade, queda demostrado en sus&nbsp;<strong>conciertos.<\/strong><\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">En su libro,<strong>&nbsp;Misty Heggeness<\/strong>&nbsp;sostiene quete&nbsp;<em>Eras Tour<\/em>&nbsp;condens\u00f3 como ninguna otra&nbsp;cosa el&nbsp;<strong>poder econ\u00f3mico femenino actual&nbsp;<\/strong>y que el verano de 2023 qued\u00f3 bautizado&nbsp;como \u201cel verano de la mujer\u201d: un auge de gasto detonado por Taylor Swift, el&nbsp;fen\u00f3meno&nbsp;<em>Barbie<\/em>&nbsp;y el&nbsp;<em>Renaissance Tour<\/em>&nbsp;de Beyonc\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los grupos de ni\u00f1as, j\u00f3venes y adultas que asistieron a estos conciertos y a las salas de&nbsp;cine para ver la pel\u00edcula protagonizada por&nbsp;<strong>Margot Robbie&nbsp;<\/strong>reiteraron la&nbsp;<strong>fuerza&nbsp;<\/strong><strong>econ\u00f3mica de las mujeres a trav\u00e9s del consumo,&nbsp;<\/strong>explica la autora en su libro.&nbsp;En&nbsp;<strong>M\u00e9xico,<\/strong>&nbsp;los&nbsp;<strong>cuatro conciertos&nbsp;<\/strong>de la cantante que inici\u00f3 en el&nbsp;<strong>country<\/strong>&nbsp;dio en agosto&nbsp;de ese a\u00f1o dejaron una derrama por m\u00e1s de&nbsp;<strong>mil millones de pesos&nbsp;<\/strong>y beneficiaron a&nbsp;comercios como&nbsp;<strong>Fantas\u00edas Miguel,<\/strong>&nbsp;que se populariz\u00f3 entonces en redes sociales con su&nbsp;campa\u00f1a \u201cBienvenidas&nbsp;<em>swifties<\/em>, consigue aqu\u00ed todo para el concierto\u201d, con la que&nbsp;promocion\u00f3 art\u00edculos para hacer&nbsp;<em>friendship bracelets<\/em>, las ic\u00f3nicas pulseras que las&nbsp;<strong>fans&nbsp;<\/strong><strong>de Taylor<\/strong>&nbsp;se intercambian en cada evento de la artista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Si Taylor Swift fuera una econom\u00eda, ser\u00eda m\u00e1s grande&nbsp;<\/em><\/strong><strong><em>que la de 50 pa\u00edsesDan Fleetwood, presidente de la&nbsp;<\/em><\/strong><strong><em>plataforma de investigaci\u00f3n de mercados &nbsp;<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>QuestionPro Research and Insights<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cameron Tucker, analista de Educaci\u00f3n Econ\u00f3mica en la Reserva Federal de San&nbsp;<\/strong><strong>Luis,&nbsp;<\/strong>dice que gracias a las&nbsp;<em>swifties<\/em>&nbsp;la&nbsp;<strong>influencia&nbsp;<\/strong>de esta&nbsp;<strong>estrella del pop&nbsp;<\/strong>no es&nbsp;s\u00f3lo&nbsp;<strong>cultural,&nbsp;<\/strong>sino tambi\u00e9n&nbsp;<strong>econ\u00f3mica.<\/strong>&nbsp;En materia de comercio, la experta destac\u00f3 en un&nbsp;an\u00e1lisis que la tradici\u00f3n de los fans de Taylor Swift de regalarse entre ellos&nbsp;<strong>pulseras de la&nbsp;<\/strong><strong>amistad<\/strong>&nbsp;en cada concierto es una tendencia que, dice, nunca pasar\u00e1 de moda, y gener\u00f3&nbsp;m\u00e1s de&nbsp;<strong>tres millones de d\u00f3lares&nbsp;<\/strong>en ventas en la tienda en&nbsp;<strong>l\u00ednea Etsy&nbsp;<\/strong>en 2023, seg\u00fan&nbsp;inform\u00f3 la revista&nbsp;<em>Time<\/em>, mismo a\u00f1o en que la publicaci\u00f3n nombr\u00f3 a la cantante&nbsp;como&nbsp;<strong>\u201cPersona del A\u00f1o\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El efecto que la cantante de&nbsp;<em>Love Story<\/em>&nbsp;ha tenido sobre el&nbsp;<strong>Museo de Wiesbaden<\/strong>&nbsp;y el sitio&nbsp;Etsy tambi\u00e9n impacta a instancias de mayor renombre, como la<strong>&nbsp;NFL,<\/strong>&nbsp;considerada la&nbsp;<strong>liga&nbsp;<\/strong><strong>deportiva m\u00e1s poderosa de Estados Unidos<\/strong>&nbsp;y una de las m\u00e1s influyentes en el mundo.&nbsp;En 2023 se hizo p\u00fablica la relaci\u00f3n entre&nbsp;<strong>Taylor Swift<\/strong>&nbsp;y el ala cerrada de los<strong>&nbsp;Kansas City&nbsp;<\/strong><strong>Chiefs, Travis Kelce.&nbsp;<\/strong>El hecho llev\u00f3 a la NFL a registrar picos de audiencia en los juegos&nbsp;de los cuatro veces ganadores del&nbsp;<strong>Super Bowl&nbsp;<\/strong>e increment\u00f3 en m\u00e1s de&nbsp;<strong>50 por&nbsp;<\/strong><strong>ciento<\/strong>&nbsp;la&nbsp;<strong>audiencia femenina&nbsp;<\/strong>de entre 12 y 17 a\u00f1os para la liga, seg\u00fan datos de Nielsen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/oem.com.mx\/elsoldemexico\/mexico\/no-juraras-el-nombre-de-dios-en-vano-para-dejar-de-beber-25417755\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pasado 26 de agosto la cantante y el jugador&nbsp;<strong>anunciaron su compromiso<\/strong>&nbsp;a trav\u00e9s de&nbsp;redes sociales. Un d\u00eda despu\u00e9s, el jersey de los Kansas City Chiefs con el&nbsp;<strong>dorsal&nbsp;<\/strong><strong>87,&nbsp;<\/strong>de<strong>&nbsp;Travis Kelce,&nbsp;<\/strong>registr\u00f3 un m\u00e1ximo de pedidos y durante esa semana increment\u00f3&nbsp;sus ventas en casi el triple respecto al&nbsp;<strong>Super Bowl LIX,&nbsp;<\/strong>seg\u00fan datos de&nbsp;<strong>Fanatics,<\/strong>&nbsp;el socio&nbsp;oficial de venta de&nbsp;<strong>NFLShop.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para&nbsp;<strong>Misty Heggeness,<\/strong>&nbsp;las&nbsp;<em>swifties<\/em>&nbsp;\u2013en su mayor\u00eda mujeres\u2013 son una fuerza de cambio&nbsp;y, seg\u00fan narra en el libro, son la verdadera fuerza econ\u00f3mica detr\u00e1s del fen\u00f3meno&nbsp;de<strong>&nbsp;Taylor Swift.<\/strong>&nbsp;Las adolescentes y mujeres fans de la cantante son descritas como&nbsp;aquellas que est\u00e1n&nbsp;<strong>impulsando<\/strong>&nbsp;los<strong>&nbsp;patrones&nbsp;<\/strong>de&nbsp;<strong>consumo,<\/strong>&nbsp;particularmente gastando en&nbsp;m\u00fasica y conciertos. \u201cSer&nbsp;<strong><em>swiftie<\/em><\/strong><strong>&nbsp;<\/strong>significa sentirte vista en un mundo que no fue creado&nbsp;para ti. Significa apoyar a otras personas que comparten tus experiencias y desear que&nbsp;las mujeres y su talento natural triunfen contra viento y marea\u201d, responde la autora a este&nbsp;diario sobre el significado de ser fan de la cantautora.<\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Taylor Swift y Travis Kelce se comprometieron en agosto de 2025 \/ Foto: Reuters<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la revista&nbsp;<em>Forbes<\/em>,&nbsp;<strong>Taylor Swift&nbsp;<\/strong>se convirti\u00f3 en&nbsp;<strong>multimillonaria&nbsp;<\/strong>en octubre de 2023,&nbsp;impulsada por los ingresos de&nbsp;<em>The Eras Tour<\/em>&nbsp;y el valor de su cat\u00e1logo. Su fortuna se&nbsp;desglosa en casi&nbsp;<strong>800 millones de d\u00f3lares de regal\u00edas y giras,<\/strong>&nbsp;un cat\u00e1logo estimado&nbsp;en<strong>&nbsp;600 millones de d\u00f3lares<\/strong>&nbsp;y unos&nbsp;<strong>110 millones de d\u00f3lares&nbsp;<\/strong>en<strong>&nbsp;bienes ra\u00edces.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Frida L\u00f3pez&nbsp;<\/strong>se convirti\u00f3 en&nbsp;<em>swiftie<\/em>&nbsp;a los 12 a\u00f1os casi por accidente. Estaba descargando&nbsp;m\u00fasica en&nbsp;<strong>Ares&nbsp;<\/strong>y encontr\u00f3&nbsp;<em>Our Song<\/em>, del primer \u00e1lbum de la int\u00e9rprete. La plataforma le&nbsp;dec\u00eda que la pieza era de&nbsp;<strong>Demi Lovato,&nbsp;<\/strong>pero ella indag\u00f3 m\u00e1s porque la letra, que habla&nbsp;de una pareja de j\u00f3venes que crea su propia canci\u00f3n utilizando los detalles y eventos&nbsp;cotidianos de su relaci\u00f3n, la atrap\u00f3. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Taylor Swift<\/strong>&nbsp;inici\u00f3 su carrera en el&nbsp;<strong>country,<\/strong>&nbsp;y aunque Frida no hab\u00eda escuchado este&nbsp;g\u00e9nero, esa primera canci\u00f3n de la cantautora la motiv\u00f3 a pedirle a su pap\u00e1 que le comprara&nbsp;el disco. Desde entonces, ha comprado cada \u00e1lbum de la artista por la experiencia que&nbsp;eso le significa. Los<strong>&nbsp;discos,&nbsp;<\/strong>no las<strong>&nbsp;descargas.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pasado 3 de octubre, Taylor Swift lanz\u00f3 su d\u00e9cimo segundo disco, The Life pf a&nbsp;Sjpwgirl, dos semanas despu\u00e9s, ya circulaban m\u00e1s de&nbsp;<strong>30 versiones alternativas,<\/strong>&nbsp;desde&nbsp;ediciones limitadas con portadas exclusivas hasta versiones ac\u00fasticas de los temas m\u00e1s&nbsp;populares, seg\u00fan destac\u00f3 el peri\u00f3dico brit\u00e1nico<em>&nbsp;The Independent<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La publicaci\u00f3n se\u00f1ala que algunos fans comenzaban a criticar que el&nbsp;<strong>capitalismo<\/strong>&nbsp;pas\u00f3 a&nbsp;ocupar el centro de la propuesta de la artista, desplazando a su m\u00fasica. Pero a\u00f1adi\u00f3 que&nbsp;hay un argumento que juega a favor de Swift, el que&nbsp;<strong>si fuera hombre, su estrategia&nbsp;<\/strong><strong>probablemente se ver\u00eda como inteligente.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para Misty Heggeness,&nbsp;<strong>Taylor Swift&nbsp;<\/strong>adem\u00e1s de ser inteligente y considerada, tiene&nbsp;una&nbsp;<strong>estrategia de marketing&nbsp;<\/strong>que le funciona y, adem\u00e1s, dice, hay artistas que tienen<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">muchas m\u00e1s versiones de sus discos que la cantante de Pensilvania. \u201cSi no te gustan sus&nbsp;estrategias, no compres los \u00e1lbumes\u201d, explica la autora.<\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Frida L\u00f3pez coincide: \u201cCompro sus discos, me gusta esa experiencia de sumergirme en&nbsp;su mundo\u201d, dice la joven que confiesa que no adquiere cada versi\u00f3n que la cantante&nbsp;publica de sus discos, porque tiene otros gastos como \u201cadulta independiente\u201d, pero&nbsp;tampoco critica a quienes deciden comprar todo lo que Swift saca porque est\u00e1 consciente&nbsp;de que hay quienes aprecian coleccionar, pero ella busca s\u00f3lo la historia y los mensajes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para la&nbsp;<em>swiftie<\/em>&nbsp;la estrategia de su cantante favorita va m\u00e1s all\u00e1 de ganar dinero s\u00f3lo por&nbsp;ganarlo, es un mensaje de que&nbsp;<strong>puedes hacer de tu pasi\u00f3n un arte que te genere&nbsp;<\/strong><strong>dinero<\/strong>&nbsp;y te permita vivir tranquila, y eso le ha dejado una ense\u00f1anza ya que, cuenta, a&nbsp;veces le da pena pedir cosas, pero recuerda que como mujer debe reclamar su valor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La fan ha visto crecer a Taylor Swift y tambi\u00e9n ha crecido con ella. El significado de sus&nbsp;canciones y lo que hace con su vida la ha marcado, por eso, cuando&nbsp;<strong><em>The Eras Tour<\/em><\/strong>&nbsp;lleg\u00f3&nbsp;a&nbsp;<strong>M\u00e9xico<\/strong>&nbsp;no dud\u00f3 en pagar&nbsp;<strong>10 mil pesos por un boleto en gradas.&nbsp;<\/strong>Era un momento que&nbsp;esperaba desde los 12 a\u00f1os y al que ten\u00eda que asistir costara lo que costara.&nbsp;<strong>Toby&nbsp;<\/strong><strong>Koenigsberg, profesor asociado y director del Departamento de M\u00fasica Popular de&nbsp;<\/strong><strong>la Escuela de M\u00fasica y Danza de la Universidad de Oregon,&nbsp;<\/strong>dijo en una entrevista&nbsp;publicada en el portal de la instituci\u00f3n que las habilidades empresariales de Taylor son&nbsp;prodigiosas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acad\u00e9mico destac\u00f3 desde la capacidad de la artista para crear su marca con maestr\u00eda&nbsp;hasta sus movimientos estrat\u00e9gicos como la decisi\u00f3n de producir una pel\u00edcula de su&nbsp;gira<em>&nbsp;The Eras Tour&nbsp;<\/em>y su&nbsp;<strong>estrategia de marketing en redes sociales&nbsp;<\/strong>para crear una marca&nbsp;cercana y aut\u00e9ntica para sus fans. \u201cHa demostrado ser una artista y empresaria de \u00e9xito\u201d. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el libro&nbsp;<strong><em><a href=\"https:\/\/www.swiftynomics.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Swiftynomics: C\u00f3mo las mujeres dirigen y redefinen nuestra econom\u00eda<\/a><\/em><\/strong><strong><a href=\"https:\/\/www.swiftynomics.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">,&nbsp;<\/a><\/strong><strong><a href=\"https:\/\/www.swiftynomics.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Misty Heggeness<\/a><\/strong><strong>&nbsp;<\/strong>refiere c\u00f3mo las mujeres de hoy en d\u00eda sobreviven y prosperan en un&nbsp;entorno dominado por el hombre, donde destaca el t\u00e9rmino&nbsp;<em>masterminding<\/em>, que se refiere&nbsp;a la planificaci\u00f3n estrat\u00e9gica y negociaci\u00f3n, como la clave para que las mujeres, a menudo&nbsp;subestimadas, persistan y prosperen.<\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Debido a su \u00e9xito comercial, Taylor Swift es conocida como la \u201cReina Midas del Siglo&nbsp;XXI\u201d \/ Foto: AFP<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La autora afirma que&nbsp;<strong>vivir en un mundo no dise\u00f1ado para la mujer es desafiante,<\/strong>&nbsp;pero&nbsp;que estas barreras han persistido a trav\u00e9s de la reinvenci\u00f3n y la planificaci\u00f3n estrat\u00e9gica,&nbsp;este&nbsp;<em>masterminding<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La disrupci\u00f3n de Taylor Swift&nbsp;<\/strong>no s\u00f3lo se queda en el \u00e1mbito art\u00edstico y econ\u00f3mico,&nbsp;es<strong>&nbsp;objeto de estudio<\/strong>&nbsp;en algunas de las universidades m\u00e1s renombradas a escala global,&nbsp;como&nbsp;<strong>Harvard, Duke, Berkeley, Stanford, la Universidad de Nueva York (NYU)&nbsp;<\/strong>e,&nbsp;incluso, instituciones europeas como las universidades de&nbsp;<strong>Gante, en B\u00e9lgica, y de Viena,&nbsp;<\/strong><strong>en Austria.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>He recibido ensayos en los que analizan la forma en que&nbsp;<\/em><\/strong><strong><em>Taylor resignifica sus experiencias amorosas y las&nbsp;<\/em><\/strong><strong><em>convierte en obras creativas<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Juana Mercado, acad\u00e9mica de la FES Acatl\u00e1n<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer curso sobre Taylor Swift data de 2022, por la\u00a0<strong>Universidad de Texas en\u00a0Austin,\u00a0<\/strong>desde entonces han surgido decenas de planes acad\u00e9micos que abordan\u00a0diversas ramas alrededor de la figura de Swift, desde su m\u00fasica, sus letras y sus influencias literarias, hasta su impacto econ\u00f3mico, pol\u00edtico, social y, por supuesto, las\u00a0perspectivas cultural y de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En M\u00e9xico, la&nbsp;<strong>Facultad de Estudios Superiores (FES) Acatl\u00e1n,<\/strong>&nbsp;de la&nbsp;<strong>UNAM,&nbsp;<\/strong>llev\u00f3 a&nbsp;cabo en octubre de 2023 un&nbsp;<strong>ciclo de conferencias y actividades para&nbsp;<\/strong><strong><em>swifties<\/em><\/strong><strong>,&nbsp;<\/strong>donde&nbsp;se realizaron talleres, conversatorios y ponencias desde distintas perspectivas&nbsp;acad\u00e9micas, pero todas con el eje tem\u00e1tico de Taylor Swift.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Juana Mercado, acad\u00e9mica de la FES Acatl\u00e1n,&nbsp;<\/strong>dice que el ciclo surgi\u00f3 a partir de las&nbsp;necesidades y de los gustos de la comunidad estudiantil. \u201cDetectamos que hab\u00eda un gran&nbsp;inter\u00e9s por artistas como Taylor Swift, BTS o Lana del Rey, y nos pareci\u00f3 importante&nbsp;aprovechar ese entusiasmo para crear<strong>&nbsp;espacios&nbsp;<\/strong>de<strong>&nbsp;encuentro<\/strong>&nbsp;y&nbsp;<strong>aprendizaje\u201d.<\/strong><\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">La acad\u00e9mica recuerda que el&nbsp;<strong>impacto<\/strong>&nbsp;de las actividades fue&nbsp;<strong>inmediato<\/strong>&nbsp;y se extendi\u00f3&nbsp;m\u00e1s all\u00e1 del campus, aunque algunas sesiones fueron virtuales, lo que permiti\u00f3 la&nbsp;participaci\u00f3n de estudiantes de distintos campus. Estudiantes de facultades y planteles de&nbsp;la&nbsp;<strong>UNAM,<\/strong>&nbsp;incluidos de educaci\u00f3n media superior como los&nbsp;<strong>Colegios de Ciencias y&nbsp;<\/strong><strong>Humanidades (CCH),&nbsp;<\/strong>escrib\u00edan al&nbsp;<strong>Departamento de Atenci\u00f3n a la Comunidad&nbsp;<\/strong><strong>Estudiantil&nbsp;<\/strong>de la&nbsp;<strong>FES Acatl\u00e1n&nbsp;<\/strong>preguntando cu\u00e1ndo habr\u00eda un nuevo ciclo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Te puede interesar:&nbsp;<\/strong><strong><a href=\"https:\/\/oem.com.mx\/elsoldemexico\/gossip\/taylor-swift-aviva-sospechas-de-nueva-musica-por-cuenta-regresiva-en-su-pagina-25180372\" target=\"_blank\" rel=\"noreferrer noopener\">Taylor Swift aviva sospechas de nueva m\u00fasica por cuenta&nbsp;<\/a><\/strong><strong><a href=\"https:\/\/oem.com.mx\/elsoldemexico\/gossip\/taylor-swift-aviva-sospechas-de-nueva-musica-por-cuenta-regresiva-en-su-pagina-25180372\" target=\"_blank\" rel=\"noreferrer noopener\">regresiva en su p\u00e1gina<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mercado dice que el fen\u00f3meno de Taylor Swift ofrece m\u00faltiples lecturas acad\u00e9micas,&nbsp;desde el an\u00e1lisis del amor rom\u00e1ntico hasta el&nbsp;<strong>empoderamiento econ\u00f3mico&nbsp;<\/strong><strong>femenino.<\/strong>&nbsp;\u201cElla tiene una visi\u00f3n empresarial muy clara. Desde la separaci\u00f3n de sus bienes&nbsp;hasta la recuperaci\u00f3n de los derechos de sus canciones, ha demostrado&nbsp;<strong>autonom\u00eda y&nbsp;<\/strong><strong>estrategia.&nbsp;<\/strong>Eso tambi\u00e9n es aprendizaje para los estudiantes\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Vincular los contenidos acad\u00e9micos con los intereses&nbsp;<\/em><\/strong><strong><em>de los estudiantes es una estrategia poderosa para&nbsp;<\/em><\/strong><strong><em>fomentar el aprendizaje<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Juana Mercado, acad\u00e9mica de la FES Acatl\u00e1n<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La profesora destaca que algunas alumnas ya han retomado el tema en trabajos de clase.&nbsp;\u201cHe recibido ensayos en los que analizan la forma en que&nbsp;Taylor&nbsp;<strong>resignifica&nbsp;<\/strong>sus&nbsp;<strong>experiencias amorosas<\/strong>&nbsp;y las convierte en&nbsp;<strong>obras creativas.<\/strong>&nbsp;Es un&nbsp;ejemplo de c\u00f3mo los intereses personales pueden vincularse con los&nbsp;<strong>contenidos&nbsp;<\/strong><strong>acad\u00e9micos\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este \u00edmpetu traspas\u00f3 las aulas. La UNAM tiene registro de&nbsp;<strong>dos tesis de licenciatura<\/strong>&nbsp;que&nbsp;tienen como tema a&nbsp;<strong>Taylor Swift.&nbsp;<\/strong>El primero de estos trabajos, de 2023, es una tesis para&nbsp;la&nbsp;<strong>licenciatura en Lengua y Literatura Modernas Inglesas,&nbsp;<\/strong>de la<strong>&nbsp;Facultad de Filosof\u00eda&nbsp;<\/strong><strong>y Letras,&nbsp;<\/strong>que hace un estudio sobre el uso de las im\u00e1genes de muerte y resurrecci\u00f3n en&nbsp;la escritura de la&nbsp;<strong>poeta Sylvia Plath y Taylor Swift.&nbsp;<\/strong>El segundo es un&nbsp;<strong>an\u00e1lisis de las&nbsp;<\/strong><strong>estrategias de marketing&nbsp;<\/strong>de la cantante en la industria musical estadounidense, para&nbsp;obtener la&nbsp;<strong>licenciatura en Administraci\u00f3n&nbsp;<\/strong>en la<strong>&nbsp;Facultad de Contadur\u00eda y&nbsp;<\/strong><strong>Administraci\u00f3n&nbsp;<\/strong>de la m\u00e1xima casa de estudios del pa\u00eds.<\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Taylor Swift con su discograf\u00eda \/ Foto: Instagram: @taylorswift<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando la educaci\u00f3n atraviesa por las emociones, por el gusto o por la identificaci\u00f3n con&nbsp;un fen\u00f3meno cultural, se vuelve m\u00e1s significativa. Vincular los contenidos acad\u00e9micos con&nbsp;los intereses de los estudiantes es una estrategia poderosa para fomentar el aprendizaje\u201d,&nbsp;dice Mercado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 355 a\u00f1os distancian a Lisbeth Nypan, acusada de brujer\u00eda y llevada a la hoguera&nbsp;en 1670, de Taylor Swift. Pero ambas encarnan la misma herej\u00eda: la de una mujer que&nbsp;cobra por su arte. &nbsp; En Swiftynomics: C\u00f3mo las mujeres dirigen y redefinen nuestra econom\u00eda, Misty&nbsp;Heggeness explora el hilo invisible que une a las mujeres [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":100288,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[748,694],"tags":[],"class_list":["post-100277","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura-feminista","category-destacadas"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/100277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=100277"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/100277\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/100288"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=100277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=100277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=100277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}