{"id":100100,"date":"2025-10-31T23:00:00","date_gmt":"2025-11-01T05:00:00","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=100100"},"modified":"2025-11-01T01:58:50","modified_gmt":"2025-11-01T07:58:50","slug":"escritoras-chiapanecas-protestan-durante-visita-de-paco-ignacio-taibo-ii-en-tuxtla","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/escritoras-chiapanecas-protestan-durante-visita-de-paco-ignacio-taibo-ii-en-tuxtla\/","title":{"rendered":"Escritoras chiapanecas protestan durante visita de Paco Ignacio Taibo II en Tuxtla"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201cNo somos cuota, somos presencia\u201d: escritoras y colectivas feministas responden a comentarios mis\u00f3ginos del escritor.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gabriela Couti\u00f1o&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tuxtla Guti\u00e9rrez, Chis. 31 Oct.- Escritoras, acad\u00e9micas, poetas, promotoras culturales, cuentistas y colectivas feministas chiapanecas, protestaron la tarde de&nbsp;este viernes&nbsp;frente a la librer\u00eda Jos\u00e9 Emilio Pacheco del Fondo de Cultura Econ\u00f3mica (FCE), ubicada en la Benem\u00e9rita Universidad Aut\u00f3noma de Chiapas (BUACH), donde se present\u00f3 el escritor y director del FCE, Paco Ignacio Taibo II.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las manifestantes llevaron a cabo una lectura en voz alta de textos de autoras mexicanas, como una forma simb\u00f3lica de protesta y de visibilizaci\u00f3n de la voz de las mujeres escritoras. La acci\u00f3n se enmarc\u00f3 en la visita del funcionario, quien se encuentra en Chiapas como parte de una jornada de actividades para promover la lectura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoras exigieron respeto y denunciaron la persistente exclusi\u00f3n de las mujeres, disidencias sexuales y comunidades racializadas del canon literario mexicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLas mujeres no somos cuota, somos presencia viva\u201d, dijo Gabriela Rodr\u00edguez de la Alianza de lectoras y escritoras feministas al dar lectura aun pronunciamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoras cuestionaron la idea de que la literatura femenina o ind\u00edgena sea un nicho separado del resto de la producci\u00f3n cultural. \u201cDurante siglos afirman-, fuimos borradas del relato para mantener una cuota totalitaria de voz masculina a la que se le ha adjudicado una falsa universalidad: blanca, masculina y heteronormada\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las escritoras criticaron lo que consideran un doble discurso dentro de los espacios progresistas y de izquierda, donde, aseguran, \u201cse sigue hablando desde el privilegio masculino con la soberbia que presume revoluci\u00f3n, pero repite las mismas l\u00f3gicas patriarcales de toda la vida\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1alaron la falta de autocr\u00edtica en funcionarios culturales que, pese a su formaci\u00f3n, reproducen estructuras de exclusi\u00f3n. \u201c\u00bfDe qu\u00e9 nos sirve un funcionario culto si no se cuestiona sus propias pr\u00e1cticas? \u00bfDe qu\u00e9 sirve quejarse de que el pa\u00eds no lee si no se atiende la desigualdad que impide esa lectura?\u201d, manifestaron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Alianza de lectoras y escritoras feministas recordaron que las mujeres han estado presentes en la historia literaria y social, aun cuando fueron invisibilizadas. \u201cSomos las que quemaron por saber demasiado, las que borraron de los libros, las que firmaron como \u2018An\u00f3nimo\u2019, las que tradujeron el dolor en palabra, las que sostienen la lucha en las calles y en las letras\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el pronunciamiento retomaron palabras de Rosario Castellanos: \u201cY no, hermanos, no somos las mujeres que temen la noche; somos las que hacen&nbsp;de la noche&nbsp;un d\u00eda\u201d, para subrayar que la transformaci\u00f3n cultural y pol\u00edtica del pa\u00eds no puede darse sin mujeres libres y respetadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLo gritamos hoy: el machismo no se justifica con ideolog\u00eda ni el patriarcado se disuelve con discursos progresistas. No habr\u00e1 revoluci\u00f3n sin nosotras\u201d, subraya el pronunciamiento, que exige al Estado y a sus representantes reconocer la diversidad y pluralidad de voces que conforman la cultura mexicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras tanto, en el interior de la librer\u00eda, Taibo II sosten\u00eda una charla con lectores y acad\u00e9micos, en un evento que registr\u00f3 una presencia inusual de guardias universitarios en los alrededores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Horas antes, el director del FCE hab\u00eda participado junto con el gobernador del estado Eduardo Ram\u00edrez Aguilar en la presentaci\u00f3n del programa \u201cLeyendo por la paz\u201d, una iniciativa estatal que busca impulsar la lectura como herramienta de convivencia y cultura de paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La lectura colectiva de las autoras chiapanecas marc\u00f3 un contraste con el acto institucional, al poner sobre la mesa la falta de espacios y reconocimiento para las mujeres en la literatura y en las pol\u00edticas culturales actuales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/11\/3b701597-8f01-4c88-ac21-f79198b0427e.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"569\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/11\/3b701597-8f01-4c88-ac21-f79198b0427e.jpg\" alt=\"\" class=\"wp-image-100102\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/11\/3b701597-8f01-4c88-ac21-f79198b0427e.jpg 853w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/11\/3b701597-8f01-4c88-ac21-f79198b0427e-300x200.jpg 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/11\/3b701597-8f01-4c88-ac21-f79198b0427e-768x512.jpg 768w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/11\/3b701597-8f01-4c88-ac21-f79198b0427e-150x100.jpg 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/11\/3b701597-8f01-4c88-ac21-f79198b0427e-696x464.jpg 696w\" sizes=\"auto, (max-width: 853px) 100vw, 853px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"768\" style=\"aspect-ratio: 432 \/ 768;\" width=\"432\" controls src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/11\/ca970664-3ec0-40c0-86e5-6f137e528f11.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u201cNo somos cuota, somos presencia\u201d: escritoras y colectivas feministas responden a comentarios mis\u00f3ginos del escritor.&nbsp; Gabriela Couti\u00f1o&nbsp; Tuxtla Guti\u00e9rrez, Chis. 31 Oct.- Escritoras, acad\u00e9micas, poetas, promotoras culturales, cuentistas y colectivas feministas chiapanecas, protestaron la tarde de&nbsp;este viernes&nbsp;frente a la librer\u00eda Jos\u00e9 Emilio Pacheco del Fondo de Cultura Econ\u00f3mica (FCE), ubicada en la Benem\u00e9rita Universidad Aut\u00f3noma [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":100101,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[54],"tags":[],"class_list":["post-100100","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mujeres"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/100100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=100100"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/100100\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/100101"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=100100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=100100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=100100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}